{"id":249394,"date":"2016-07-07T10:18:03","date_gmt":"2016-07-07T10:18:03","guid":{"rendered":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=249394"},"modified":"2016-07-09T15:52:04","modified_gmt":"2016-07-09T14:52:04","slug":"neue-studie-ueber-die-berliner-wohn-gewohnheiten","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/neue-studie-ueber-die-berliner-wohn-gewohnheiten-10249394\/","title":{"rendered":"Neue Studie \u00fcber die Berliner Wohn-Gewohnheiten"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-249654 size-full\" title=\"Energiekosten stellen keinen bedeutenden Grund f\u00fcr einen Wohnungswechsel dar\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2016\/07\/Screenshot_1-e1468075789316.jpg\" alt=\"Bild\" width=\"350\" height=\"162\" \/>Es kommt doch auf die Gr\u00f6\u00dfe an: Berliner streben beim Wohnungswechsel nach mehr Raum<br \/> YouGov-Studie im Auftrag von E WIE EINFACH zeigt:<br \/> &#8211; 45 Prozent der Berliner ziehen f\u00fcr eine gr\u00f6\u00dfere Wohnung um<br \/> &#8211; Knapp jeder Vierte nutzt die Hilfe eines Umzugsunternehmens<br \/> &#8211; Hohe Nebenkosten sind f\u00fcr Berliner kein Grund<\/p> <p><!--more--><\/p> <p>Der Berliner braucht Platz und wird dieser zu eng, packt er die Kisten &#8211; zu diesem Ergebnis kommt eine repr\u00e4sentative YouGov-Studie im Auftrag des Strom- und Gasanbieters E WIE EINFACH. Demnach hat knapp die H\u00e4lfte der Hauptstadtbewohner gro\u00dfe Wohntr\u00e4ume und f\u00fcr mehr Platz schon einmal die eigenen vier W\u00e4nde gewechselt. Damit sind sie &#8211; neben Nordrhein-Westfalen &#8211; deutsche Spitzenreiter. In anderen Bundesl\u00e4ndern ist es hingegen meist der Wunsch des Zusammenlebens mit dem Partner, der zu einem Wohnungswechsel f\u00fchrt. Doch auch mit der neuen Heimat sind die Berliner schnell wieder unzufrieden. Im Schnitt sind die Stadtstaatler auf der Suche nach der perfekten Bleibe bereits drei- bis vier-mal umgezogen. Nur ein Prozent ist noch nie umgezogen, im Bundesschnitt sind das viermal so viele. Ganze acht Prozent haben ihren Wohnort sogar schon mehr als zehnmal gewechselt. Auch damit liegt Berlin \u00fcber dem Deutschlandschnitt.<\/p> <p>Die Berliner vertrauen beim Umzug \u00fcberdurchschnittlich oft auf professionelle Hilfe: So \u00fcberl\u00e4sst ihn knapp jeder Vierte lieber einem Spezialisten (22 Prozent) &#8211; so viele wie in keinem anderen Bundesland. Zwar bekommen auch die Berliner Unterst\u00fctzung von Freunden und Familie (63 Prozent), doch sind andere Bundesl\u00e4nder wie etwa Baden-W\u00fcrttemberg mit 73 Prozent bei der Umzugshilfe aus dem privaten Umfeld deutlich besser aufgestellt.<\/p> <p>W\u00e4hrend in anderen Bundesl\u00e4ndern der Umzug auch ein Anlass ist, sich mit dem Thema Energiekosten zu besch\u00e4ftigen oder diese sogar einen Wohnungswechsel ausl\u00f6sen, haben die Berliner hierzu scheinbar keinen Bezug. Nicht einmal eine hohe Nebenkostennachzahlung ist bei dem Gro\u00dfteil der Hauptst\u00e4dter (94 Prozent) ein Grund, \u00fcber einen Wohnungswechsel nachzudenken. In der gesamtdeutschen Betrachtung sind sie damit am wenigsten kostensensibel. Auch wenn ein Umzug ins Haus steht, ist dies f\u00fcr die Berliner kein Anlass, sich Gedanken \u00fcber die Senkung ihrer Energiekosten zu machen. Denn mehr als die H\u00e4lfte zieht im Rahmen des Wohnungswechsels einen gleichzeitigen Wechsel des Strom- oder Gasversorgers nicht in Erw\u00e4gung. Im Gesamtschnitt ist die Mehrheit hier durchaus wechselbereiter. Dabei wei\u00df Oliver Bolay, Gesch\u00e4ftsf\u00fchrer von E WIE EINFACH: &#8222;Im Falle eines Umzugs kann der Vertrag mit dem bestehenden Energieanbieter meist im Rahmen des Sonderk\u00fcndigungsrechts fr\u00fchzeitig beendet werden. Damit ist der Wohnungswechsel die perfekte Gelegenheit, um nach einem neuen und g\u00fcnstigeren Anbieter Ausschau zu halten. So kann man schnell 200 Euro und mehr pro Jahr sparen.&#8220;<\/p> <p>Neben dem Verzicht auf einen Anbieterwechsel messen die Berliner auch der Drosselung ihrer Energiekosten keine Bedeutung bei. 28 Prozent und damit fast jeder dritte Berliner gibt an, sich noch nie mit dem Thema Energieeffizienz in den eigenen vier W\u00e4nden besch\u00e4ftigt zu haben. Auch ein Umzug ist f\u00fcr die Hauptst\u00e4dter kein Grund, diese Einstellung zu \u00fcberdenken. Oliver Bolay: &#8222;In einer neuen Wohnung m\u00fcssen es nicht immer gleich moderne, energiesparende Elektroger\u00e4te sein. Auch mit kleinen Ma\u00dfnahmen wie dem Wechsel auf Energiesparlampen kann die Energieeffizienz bereits gesteigert werden.&#8220;<\/p> <p>F\u00fcr die repr\u00e4sentative Studie wurden deutschlandweit 1.648 Personen in Deutschland ab 18 Jahren befragt.<\/p> <p>E WIE EINFACH ist ein bundesweiter Strom- und Gasanbieter mit Sitz in K\u00f6ln. Mit ma\u00dfgeschneiderten Tarifen sowohl f\u00fcr Privat- als auch f\u00fcr Gesch\u00e4ftskunden steht bei E WIE EINFACH der Kunde stets im Mittelpunkt. Das gilt f\u00fcr neue wie bestehende Kunden gleicherma\u00dfen. Unter dem Leitgedanken der Einfachheit entwickelt E WIE EINFACH dabei Produkte und Dienstleistungen nach den Bed\u00fcrfnissen seiner Kunden: leicht verst\u00e4ndlich, stets an schnellen L\u00f6sungen orientiert, immer transparent und mit der maximalen Vereinfachung im Blick.<\/p> <p>Strom-, Gas- und W\u00e4rmestrom-Tarife zu dauerhaft g\u00fcnstigen Preise bei einem gleichzeitig ausgezeichneten Service sind das Ergebnis. Dies best\u00e4tigen auch unabh\u00e4ngige Stellen: So erh\u00e4lt E WIE EINFACH regelm\u00e4\u00dfig Auszeichnungen f\u00fcr seinen Kundenservice, faire Vertragsbedingungen und das gute Preis-Leistungsverh\u00e4ltnis.<\/p> <p>Mehr zu E WIE EINFACH erfahren Sie unter www.e-wie-einfach.de, auf Twitter unter www.twitter.com\/E_WIE_EINFACH sowie auf Facebook unter www.facebook.com\/ewieeinfach.<\/p> <p>Firmenkontakt<br \/> E WIE EINFACH GmbH<br \/> Bettina Donges<br \/> Salierring 47-53<br \/> 50677 K\u00f6ln<br \/> 0800 \/ 44 11 800 71<br \/> SERVICE@E-WIE-EINFACH.DE<br \/> www.e-wie-einfach.de<\/p> <p>Pressekontakt<br \/> E WIE EINFACH GmbH<br \/> Bettina Donges<br \/> Salierring 47-53<br \/> 50677 K\u00f6ln<br \/> 0221-17737-308<br \/> presse@e-wie-einfach.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.e-wie-einfach.de\/\" title=\"STROM UND GAS VON E WIE EINFACH\" >www.e-wie-einfach.de<\/a><\/p> <p>&nbsp;<\/p> <p>&nbsp;<\/p> <\/div> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Es kommt doch auf die Gr\u00f6\u00dfe an: Berliner streben beim Wohnungswechsel nach mehr Raum YouGov-Studie im Auftrag von E WIE EINFACH zeigt: &#8211; 45 Prozent der Berliner ziehen f\u00fcr eine gr\u00f6\u00dfere Wohnung um &#8211; Knapp jeder Vierte nutzt die Hilfe eines Umzugsunternehmens &#8211; Hohe Nebenkosten sind f\u00fcr Berliner kein Grund<\/p>\n","protected":false},"author":1,"featured_media":249655,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[1734],"class_list":["post-249394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie-verbraucher","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/249394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=249394"}],"version-history":[{"count":3,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/249394\/revisions"}],"predecessor-version":[{"id":249708,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/249394\/revisions\/249708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/249655"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=249394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=249394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=249394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}