{"id":26773,"date":"2011-08-23T10:56:50","date_gmt":"2011-08-23T09:56:50","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=26773"},"modified":"2015-10-02T11:01:28","modified_gmt":"2015-10-02T10:01:28","slug":"medikamente-jetzt-revolutionaer-anders-entwickeln-wirksam-bei-den-meisten-bekannten-krankheiten","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/medikamente-jetzt-revolutionaer-anders-entwickeln-wirksam-bei-den-meisten-bekannten-krankheiten-1026773\/","title":{"rendered":"Medikamente jetzt revolution\u00e4r anders entwickeln: Wirksam bei den meisten bekannten Krankheiten"},"content":{"rendered":"<p><a href=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/medikamente-jetzt-revolutionaer-anders-entwickeln-wirksam-bei-den-meisten-bekannten-krankheiten-1026773\/www-ugichem-at_1314093234751\/\" rel=\"attachment wp-att-26835\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-26835\" title=\"Internetauftritt des Pharmaunternehmens\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/bbb65d3e44e460da993a521286717781.png\" alt=\"\" width=\"173\" height=\"121\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/8ca698a93fff35795cb0f3aac63a20ec.png\" \/><\/a>Die Beteiligung der V+ GmbH &amp; Co. Fonds 3 KG an der 2003 gegr\u00fcndeten UGICHEM GmbH umfa\u00dft 6,82 % Anteile. Das in Innsbruck ans\u00e4ssige Unternehmen mit zahlreichen chemischen und pharmazeutischen Alleinstellungsmerkmalen nutzt die zugeflossenen Finanzmittel zun\u00e4chst, um ihre neuartigen Gene-Silencing-Wirkstoffe, die sogenannten Ugimere, hinsichtlich relevanter pharmazeutischer und therapeutischer Parameter zu validieren. Die UGICHEM Gesellschaft f\u00fcr organische Chemie mbH ist ein spin-off aus der TU M\u00fcnchen, Institut f\u00fcr angewandte Chemie, Professor Ugi. Sie ist der erste und derzeit einzige Anbieter eines Gene-Silencing-Wirkstoff-Konzeptes mit dem Potential zur breiten Anwendbarkeit bei unterschiedlichsten Krankheiten.<\/p> <p><!--more-->Geplante Forschungsarbeiten<br \/> Dar\u00fcberhinaus werden erste pr\u00e4klinische Kandidaten zur Therapie immunologischer Erkrankungen entwickelt. Gerade hier bieten die Ugimere entscheidende Vorteile, da andere Wirkstoffe Immunzellen nur unzureichend penetrieren und so dort keine signifikante Modulation der Genexpression erlauben. Die bisherigen Forschungsergebnisse des UGICHEM-Managements aus drei Chemikern und zwei Biologen zeigen deutlich, dass die Ugimere derzeit der einzig klar differenzierte und substantiell neue Ansatz f\u00fcr die seit langem ungel\u00f6sten Herausforderungen im Gene-Silencing-Bereich sind.<\/p> <p>Innovatives Verfahren<br \/> Bisherige Medikamente blockieren sch\u00e4dliche Proteine. Der Bauplan von sch\u00e4dlichen Proteinen ist in der DNA innerhalb einer Zelle gespeichert. Die Ugimere verhindern bereits bei der Zellteilung, da\u00df sch\u00e4dliche Proteine sich vermehren k\u00f6nnen. Ugimere sind f\u00fcr die meisten aller bekannten Krankheiten anwendbar, auch f\u00fcr bisher als unheilbar geltende Krankheiten. Nur Ugimere k\u00f6nnen gut die Zellmembran penetrieren und in die Zellen eindringen. Das breit anwendbare Gene-Silencing-Wirkstoff-Konzept revolutioniert die Entwicklung von Medikamenten. Gene-Silencing ist theoretisch bei 80 % aller Krankheiten anwendbar, zum Beispiel bei Virus-Infektionen und verschiedenen Krebsarten, Entz\u00fcndungskrankheiten und Stoffwechselerkrankungen. Gene-Silencing er\u00f6ffnet dort auch neue Behandlungsm\u00f6glichkeiten.<\/p> <p>Alleinstellungsmerkmal der Ugimere<br \/> Ugimere penetrieren gut durch die Zellmembran in die Zellen hinein, w\u00e4hrend andere Gene-Silencing-Wirkstoffe hierzu Hilfsstoffe ben\u00f6tigen, die aber nur sehr beschr\u00e4nkt zur Verf\u00fcgung stehen. Deshalb ist eine Nutzung ganz eng begrenzt auf lokale Anwendungung wie in Gehirn, Leber oder Lunge. Es zeichnet sich nicht ab, da\u00df die Limitationen anderer Gene-Silencing-Wirkstoffe von deren Herstellern irgendwann \u00fcberwunden werden k\u00f6nnen. Ugimere hingegen werden bereits chemisch modifiziert und so an die Bed\u00fcrfnisse der einzelnen Krankheiten angepa\u00dft. Ugimere haben daher die gr\u00f6\u00dfte Erfolgswahrscheinlichkeit, das erste breit anwendbare Gene-Silencing-Wirkstoff-Konzept zu werden. Vorgesehen ist der Verkauf von Lizenzen f\u00fcr die einzelnen Ugimer-Wirkstoffe an Pharma-Unternehmen nach ugichem-interner Entwicklung bis zur Phase I.<\/p> <p>Fachbegriffe sind auf http:\/\/www.vplus-management.de\/presse\/pm_2011_34_01_ugichem.html erl\u00e4utert, um das Verst\u00e4ndnis f\u00fcr die auf http:\/\/www.ugichem.com vorgestellten Verfahren zu vertiefen.<\/p> <p>Unternehmensinformation<br \/> Die ugichem verf\u00fcgt mit den so genannten Ugimeren \u00fcber propriet\u00e4re und neue Gene-Silencing-Wirkstoffe, die es erlauben, die Limitierungen der bislang etablierten Technologien wie Antsense-Oligonucleotide oder siRNAs aufzul\u00f6sen. Im Gegensatz zu diesen ist die chemische Struktur der Ugimere nicht von nat\u00fcrlichen Nukleins\u00e4uren der notwendigen funktionellen Eigenschaften entworfen worden. Dadurch k\u00f6nnen auch bisher nicht zug\u00e4ngliche Zellen oder definierte Zellkompartimente ohne zus\u00e4tzliche Hilfsmittel effektiv erreicht werden. Die ugichem sieht ihre Aufgabe darin, die Ugimere als neuartige und erstklassige Medikamente zu etablieren. Den Fokus bilden dabei zun\u00e4chst Indikationen, bei den ein direkter Eingriff in Immunzellen erforderlich ist, was mit bisherigen Technologien nicht m\u00f6glich ist. Dar\u00fcber hinaus werden die Ugimere zu einer therapeutischen Plattform entwickelt, die potenziell f\u00fcr alle Erkrankungen geeignet ist, bei denen eine ge\u00e4nderte Genexpression involviert ist.<\/p> <p>Firmenkontakt<br \/> V+ Management GmbH<br \/> Michael Vogel<br \/> Wupperplatz 7<\/p> <p>51061 K\u00f6ln<br \/> Deutschland<\/p> <p>E-Mail: vogel@vplus-management.de<br \/> Homepage: http:\/\/www.vplus-management.de<br \/> Telefon: 0221 9649 0217<\/p> <p>Pressekontakt<br \/> publicEffect<br \/> Hans Kolpak<br \/> Fabrikstr. 2<\/p> <p>66981 M\u00fcnchweiler an der Rodalb<br \/> Deutschland<\/p> <p>E-Mail: hans-kolpak@publicEffect.com<br \/> Homepage: http:\/\/www.publicEffect.com<br \/> Telefon: 06395 910 8010<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Beteiligung der V+ GmbH &amp; Co. Fonds 3 KG an der 2003 gegr\u00fcndeten UGICHEM GmbH umfa\u00dft 6,82 % Anteile. Das in Innsbruck ans\u00e4ssige Unternehmen mit zahlreichen chemischen und pharmazeutischen Alleinstellungsmerkmalen nutzt die zugeflossenen Finanzmittel zun\u00e4chst, um ihre neuartigen Gene-Silencing-Wirkstoffe, die sogenannten Ugimere, hinsichtlich relevanter pharmazeutischer und therapeutischer Parameter zu validieren. Die UGICHEM Gesellschaft f\u00fcr<\/p>\n","protected":false},"author":291,"featured_media":198067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8808],"tags":[],"class_list":["post-26773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenschaft"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/26773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=26773"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/26773\/revisions"}],"predecessor-version":[{"id":209631,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/26773\/revisions\/209631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198067"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=26773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=26773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=26773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}