{"id":278133,"date":"2025-11-14T11:36:44","date_gmt":"2025-11-14T10:36:44","guid":{"rendered":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=278133"},"modified":"2025-11-14T11:36:44","modified_gmt":"2025-11-14T10:36:44","slug":"sicher-im-dunkeln-nach-hause-kommen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/sicher-im-dunkeln-nach-hause-kommen-10278133\/","title":{"rendered":"Sicher im Dunkeln nach Hause kommen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-278134 size-full\" title=\"ab wann ist Selbstverteidigung K\u00f6rperverletzung?\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2025\/11\/468724-e1763116497187.jpg\" alt=\"ein Schatten fl\u00fcchtet \u00fcber eine Treppe\" width=\"300\" height=\"225\" \/>ARAG Experten mit Tipps f\u00fcr einen sicheren Heimweg in der dunklen Jahreszeit<br \/> Wenn die Tage k\u00fcrzer werden, liegt der Heimweg oft im Dunkeln. Viele Menschen, vor allem Frauen, f\u00fchlen sich abends unsicher und meiden daher bestimmte Orte oder Verkehrsmittel, sobald es dunkel wird. Und das nicht ohne Grund: Laut Bundeskriminalamt wurde fast jede dritte Frau bereits Opfer eines Sexualdelikts. Die ARAG Experten geben Tipps, wie der Heimweg auch in der dunklen Jahreszeit sicherer werden kann.<!--more--><\/p> <p>Sichtbar und sicher unterwegs<\/p> <p>Ein wichtiger Schritt beginnt laut ARAG Experten schon bei der Kleidung: Helle, reflektierende Stoffe oder Zubeh\u00f6r mit Leuchtstreifen machen Fu\u00dfg\u00e4nger und Radfahrer f\u00fcr Autofahrer sichtbar. Besonders bei dunkler Kleidung untersch\u00e4tzen viele, wie sp\u00e4t sie von Autofahrern im Scheinwerferlicht erkannt werden. Reflektierende Armb\u00e4nder, Schirme oder Taschen erh\u00f6hen die Sichtbarkeit deutlich.<\/p> <p>Mit offenen Augen durch die Nacht<\/p> <p>Vor allem nachts geht es darum, aufmerksam zu bleiben und seine Umgebung im Auge zu behalten. Daher raten die ARAG Experten beispielsweise davon ab, \u00fcber Kopfh\u00f6rer Musik zu h\u00f6ren. Zudem k\u00f6nnte es hilfreich sein, sich vorab \u00fcber die Route Gedanken zu machen: Gibt es Kioske, Restaurants, Bars oder Gesch\u00e4fte, die noch ge\u00f6ffnet und im Notfall gut erreichbar sind? Und wer es laut mag: Ein batteriebetriebener Taschenalarm, der auf Knopfdruck einen lauten Alarmton von sich gibt, passt in jede Tasche und kann m\u00f6gliche Angreifer abschrecken.<\/p> <p>Begleiter f\u00fcr den Heimweg<\/p> <p>Wenn Freundin, Kumpel oder Partner nicht anwesend sind, sobald der Heimweg angetreten wird, k\u00f6nnte ein Telefonat helfen, sich sicherer zu f\u00fchlen. Was aber, wenn bereits alle schlafen? Die ARAG Experten empfehlen in diesen F\u00e4llen das <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/heimwegtelefon.net\/\"  rel=\"nofollow\">Heimwegtelefon<\/a>. Hier sitzen Ehrenamtler am Telefon und unterhalten sich mit den Anrufenden, bis sie sicher zu Hause sind. Aufgenommen werden Name, Telefonnummer und Route, auf der der Anrufende unterwegs ist. W\u00e4hrend des Telefonats verfolgen die Mitarbeiter den Heimweg \u00fcber eine Karte und wissen so zu jeder Zeit, wo sich der Gespr\u00e4chspartner befindet. Im schlimmsten Fall k\u00f6nnte daher auch umgehend die Polizei mit konkreten Ortsangaben informiert werden.<\/p> <p>Die n\u00e4chtlichen Helfer erreicht man unter der 0 30 &#8211; 12 07 41 82 von Sonntag bis Donnerstag von 21 Uhr bis Mitternacht sowie am Freitag und am Samstag von 21 bis um 3 Uhr morgens. Der Service finanziert sich \u00fcber Spenden und ist daher kostenlos. Es fallen lediglich die Telefongeb\u00fchren des jeweiligen Mobilfunkanbieters an. Wer sich selbst engagieren m\u00f6chte, kann sich <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/heimwegtelefon.net\/unterstuetzen\/mitmachen\/\"  rel=\"nofollow\">online bewerben<\/a>. Telefonisten ben\u00f6tigen lediglich einen zuverl\u00e4ssigen Computer mit einem Mikrofon oder ein Headset. \u00dcbrigens: Nicht nur Frauen d\u00fcrfen das Heimwegtelefon nutzen.<\/p> <p>&#8222;Schlumpfspray&#8220; als Markierung?<\/p> <p>Das gro\u00dffl\u00e4chige Verspr\u00fchen von blauer Farbe auf Haut oder Kleidung mittels des sogenannten &#8222;Schlumpfsprays&#8220; mag auf Social Media harmlos wirken, rechtlich ist es jedoch heikel. Wer einen anderen Menschen ohne dessen Zustimmung dauerhaft kennzeichnet, l\u00e4uft Gefahr, strafrechtlich belangt zu werden: Je nach Intensit\u00e4t kann das Verhalten den Tatbestand der K\u00f6rperverletzung erf\u00fcllen, an der Kleidung oder pers\u00f6nlichen Gegenst\u00e4nden Sachbesch\u00e4digung begr\u00fcnden oder als N\u00f6tigung bzw. Beleidigung gewertet werden. Dar\u00fcber hinaus ist das gezielte &#8222;Markieren&#8220; und anschlie\u00dfende \u00d6ffentlichmachen eines Tatverd\u00e4chtigen eine Form der Selbstjustiz. Die ARAG Experten raten daher dringend davon ab, derartige Sprays zu verwenden und stattdessen die Strafverfolgung den zust\u00e4ndigen Beh\u00f6rden zu \u00fcberlassen.<\/p> <p>Pfefferspray-Einsatz nur zur Notwehr<\/p> <p>Anders sieht es beim klassischen Pfefferspray aus. Dieses darf in Deutschland grunds\u00e4tzlich zwar nur zur Tierabwehr frei verkauft werden. Liegt aber ein Notwehrfall vor, ist der Einsatz unter Umst\u00e4nden erlaubt. Doch der Rahmen ist eng: Denn nach Paragraf 32 Strafgesetzbuch ist Notwehr die Abwehr eines gegenw\u00e4rtigen, rechtswidrigen Angriffs. Das bedeutet: Nur wenn tats\u00e4chlich eine unmittelbare Bedrohung besteht, darf man sich mit geeigneten Mitteln wehren, also auch mit Pfefferspray. Allerdings warnen die ARAG Experten vor dem Verh\u00e4ltnism\u00e4\u00dfigkeitsprinzip: Die Abwehrhandlung darf nicht \u00fcber das hinausgehen, was zur Verteidigung erforderlich ist. Wer Pfefferspray leichtfertig einsetzt, riskiert eine Anzeige wegen K\u00f6rperverletzung.<\/p> <p>Selbstverteidigung &#8211; was ist erlaubt?<\/p> <p>Neben Hilfsmitteln ist auch k\u00f6rperliche Selbstverteidigung erlaubt, solange sie der Abwehr eines aktuellen Angriffs dient. Kurse in Selbstverteidigung oder Deeskalation k\u00f6nnen helfen, in Stresssituationen handlungsf\u00e4hig zu bleiben. Erlaubt ist grunds\u00e4tzlich alles, was zur Verteidigung erforderlich und verh\u00e4ltnism\u00e4\u00dfig ist. Angefangen beim Wegsto\u00dfen bis hin zum Einsatz von Gegenst\u00e4nden zur Abwehr. Wichtig ist laut ARAG Experten, dass die Handlung nicht auf Vergeltung gerichtet ist. Wer etwa einen fliehenden Angreifer verfolgt und verletzt, handelt nicht mehr in Notwehr.<\/p> <p>Sie wollen mehr von den ARAG Experten lesen oder h\u00f6ren?<\/p> <p>Dann schauen Sie im <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.arag.com\/de\/newsroom\/\"  rel=\"nofollow\">ARAG newsroom<\/a> vorbei.<\/p> <p>Die ARAG ist das gr\u00f6\u00dfte Familienunternehmen in der deutschen Assekuranz und versteht sich als vielseitiger Qualit\u00e4tsversicherer. Sie ist der weltweit gr\u00f6\u00dfte Rechtsschutzversicherer. Aktiv in insgesamt 19 L\u00e4ndern &#8211; inklusive den USA und Kanada &#8211; nimmt die ARAG \u00fcber ihre internationalen Niederlassungen, Gesellschaften und Beteiligungen in vielen internationalen M\u00e4rkten mit ihren Rechtsschutzversicherungen und Rechtsdienstleistungen eine f\u00fchrende Position ein. Ihren Kunden in Deutschland bietet die ARAG neben ihrem Schwerpunkt im Rechtsschutzgesch\u00e4ft auch eigene einzigartige, bedarfsorientierte Produkte und Services in den Bereichen Komposit und Gesundheit. Mit mehr als 6.100 Mitarbeitenden erwirtschaftet der Konzern ein Umsatz- und Beitragsvolumen von \u00fcber 2,8 Milliarden Euro.<\/p> <p>ARAG SE ARAG Platz 1 40472 D\u00fcsseldorf<\/p> <p>Aufsichtsratsvorsitzender Dr. Dr. h. c. Paul-Otto Fa\u00dfbender<\/p> <p>Vorstand Dr. Renko Dirksen (Vorsitzender)<\/p> <p>Dr. Matthias Maslaton<\/p> <p>Wolfgang Mathmann<\/p> <p>Dr. Shiva Meyer<\/p> <p>Hanno Petersen<\/p> <p>Dr. Joerg Schwarze<\/p> <p>Sitz und Registergericht D\u00fcsseldorf HRB 66846 USt-ID-Nr.: DE 119 355 995<\/p> <p><b>Firmenkontakt<\/b><\/p> <p>ARAG SE<\/p> <p>Jennifer Kallweit<\/p> <p>ARAG Platz 1<\/p> <p>40472 D\u00fcsseldorf<\/p> <p>+49 211 963-3115<\/p> <p><img decoding=\"async\" src=\"https:\/\/pr-gateway.de\/media\/pr\/image\/9844\/email\/firma\/468724.png\" alt=\"073b10ae981cea04a30a067de0f7f800e660aa40\" \/><\/p> <p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.ARAG.de\"  target=\"_blank\" rel=\"nofollow noopener\">http:\/\/www.ARAG.de<\/a><\/p> <p><b>Pressekontakt<\/b><\/p> <p>Klaarkiming Kommunikation<\/p> <p>Claudia Wenski<\/p> <p>Steinberg 4<\/p> <p>24229 D\u00e4nischenhagen<\/p> <p>+49 4349 &#8211; 22 80 26<\/p> <p><img decoding=\"async\" src=\"https:\/\/pr-gateway.de\/media\/pr\/image\/9844\/email\/presse\/468724.png\" alt=\"073b10ae981cea04a30a067de0f7f800e660aa40\" \/><\/p> <p>http:\/\/www.ARAG.de<\/p> <p>Die Bildrechte liegen bei dem Verfasser der Mitteilung.<\/p>","protected":false},"excerpt":{"rendered":"<p>ARAG Experten mit Tipps f\u00fcr einen sicheren Heimweg in der dunklen Jahreszeit Wenn die Tage k\u00fcrzer werden, liegt der Heimweg oft im Dunkeln. Viele Menschen, vor allem Frauen, f\u00fchlen sich abends unsicher und meiden daher bestimmte Orte oder Verkehrsmittel, sobald es dunkel wird. Und das nicht ohne Grund: Laut Bundeskriminalamt wurde fast jede dritte Frau<\/p>\n","protected":false},"author":1,"featured_media":278134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-278133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recht-wirtschaft-steuerberatung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/278133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=278133"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/278133\/revisions"}],"predecessor-version":[{"id":278135,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/278133\/revisions\/278135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/278134"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=278133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=278133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=278133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}