{"id":2867,"date":"2009-12-14T20:00:24","date_gmt":"2009-12-14T19:00:24","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=2867"},"modified":"2010-07-26T14:19:42","modified_gmt":"2010-07-26T13:19:42","slug":"mit-8-000-euro-gewinnspiel-ins-neue-kite-friends-jahr","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/mit-8-000-euro-gewinnspiel-ins-neue-kite-friends-jahr-102867\/","title":{"rendered":"Mit 8.000-Euro-Gewinnspiel ins neue KITE &amp; friends-Jahr"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-2870\" title=\"KITE &amp; friends_0110.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2867\/KITE &amp; friends_0110-150x150.jpg\" alt=\"KITE &amp; friends_0110.jpg\" width=\"150\" height=\"150\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Herzlich Willkommen beim aktuellen Newsletter von KITE &amp; friends.<br \/> Mit 8.000-Euro-Gewinnspiel ins neue KITE &amp; friends-Jahr<\/p> <p>Zum Start ins Jahr 2010 bringt KITE &amp; friends richtig was an die Leinen. Bei unserem gro\u00dfen Gewinnspiel hast Du die Chance auf tolle Drachen und n\u00fctzliches Zubeh\u00f6r im Gesamtwert von mehr als 8.000 Euro. Um die Drachentasche mit neuem Equipment zu f\u00fcllen, musst Du nur zwei Dinge tun: Mitmachen und auf das n\u00f6tige Qu\u00e4ntchen Gl\u00fcck hoffen!<!--more--><br \/> Das ist der absolute Hammer: KITE &amp; friends pr\u00e4sentiert in Ausgabe 1\/2010 exklusiv die Bauanleitung f\u00fcr Bernhard Dingwerths Froggy. Der stablose Froschdrachen mit 3,50 Meter H\u00f6he ist nach Robbe und Papagei der aktuelle Geniestreich des sympathischen \u201eDrachenbernhard\u201c.<br \/> Folgende Themen-Highlights sind unter anderem im aktuellen Heft zu finden:<br \/> &#8211; Bericht &amp; Video: Kitebuggy-EM in St. Peter-Ording<br \/> &#8211; Exklusiver Bauplan: Der Frosch von Bernhard Dingwerth<br \/> &#8211; Mitmachen: 8.000-Euro-Gewinnspiel<br \/> &#8211; Bis ans Limit: Reactor II von Peter Lynn im Test<br \/> &#8211; Umdenken: Der Zodiac von Space Kites bietet ungeahntes Potenzial<br \/> &#8211; Ein Einleiner zum Verschenken: Die Rose von Wolkenst\u00fcrmer<br \/> &#8211; Mit der Hydra von HQ geht es zum Training auf\u00b4s Wasser<br \/> &#8211; Was Monsterb\u00f6en beim Speedkiting verursachen k\u00f6nnen<br \/> &#8230; und vieles mehr.<br \/> KITE &amp; friends erh\u00e4ltst Du im gut sortierten Fachhandel oder direkt beim Verlag. Abonnenten haben das Heft in der Regel einige Tage fr\u00fcher. Du hast noch kein Heft? Klicke jetzt hier und sichere Dir die aktuelle Ausgabe oder gleich alle Vorteile des Abos:<br \/> http:\/\/www.kite-and-friends.de<br \/> Die aktuelle Ausgabe liefern wir versandkostenfrei. Nat\u00fcrlich erh\u00e4ltst Du auch \u00e4ltere Ausgaben seit dem ersten Heft. Einen \u00dcberblick \u00fcber die lieferbaren Hefte findest Du hier:<br \/> https:\/\/www.alles-rund-ums-hobby.de\/openstore.htm?DS_FZ_KF<br \/> &#8212;<br \/> Wellhausen &amp; Marquardt<br \/> Mediengesellschaft bR<br \/> Hans-Henny-Jahnn-Weg 51<br \/> 22085 Hamburg<br \/> Telefon: 040\/42 91 77-100<br \/> Telefax: 040\/42 91 77-199<br \/> E-Mail: redaktion@kite-and-friends.de<br \/> Internet: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.kite-and-friends.de\"  >www.kite-and-friends.de<\/a><br \/> Vertretungsberechtigte Gesellschafter:<br \/> Tom Wellhausen &amp; Sebastian Marquardt<\/p> <p><a href=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/2867\/KITE &amp; friends_0110.jpg\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Herzlich Willkommen beim aktuellen Newsletter von KITE &amp; friends. Mit 8.000-Euro-Gewinnspiel ins neue KITE &amp; friends-Jahr Zum Start ins Jahr 2010 bringt KITE &amp; friends richtig was an die Leinen. Bei unserem gro\u00dfen Gewinnspiel hast Du die Chance auf tolle Drachen und n\u00fctzliches Zubeh\u00f6r im Gesamtwert von mehr als 8.000 Euro. Um die Drachentasche mit<\/p>\n","protected":false},"author":291,"featured_media":2870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport-und-freizeit"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/2867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=2867"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/2867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/2870"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=2867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=2867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=2867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}