{"id":28779,"date":"2011-09-14T09:54:23","date_gmt":"2011-09-14T08:54:23","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=28779"},"modified":"2013-09-13T11:33:09","modified_gmt":"2013-09-13T10:33:09","slug":"rekord-anteil-der-internationalen-studenten-an-der-handelshochschule-leipzig-hhl-auf-gut-60-prozent-gestiegen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/rekord-anteil-der-internationalen-studenten-an-der-handelshochschule-leipzig-hhl-auf-gut-60-prozent-gestiegen-1028779\/","title":{"rendered":"Welcome Days mit Fokus auf verantwortliches Handeln in der Wirtschaft"},"content":{"rendered":"<p>An der Handelshochschule Leipzig (HHL) haben sich zum Wintersemester 2011\/12 insgesamt 117 Studierende aus 29 L\u00e4ndern immatrikuliert. Darunter sind 43 Austauschstudenten aus dem mittlerweile auf 107 Partnerhochschulen angewachsenen internationalen Netzwerk der HHL. Der Anteil internationaler Studierender hat zu Beginn des neuen Studienjahrs die Rekordmarke von gut 60 Prozent erreicht.<\/p> <p>Bei der Wahl ihrer Hochschule spielten f\u00fcr die Studierenden verschiedene Faktoren eine Rolle. <!--more-->So \u00fcberzeugte die HHL beispielsweise die 22-j\u00e4hrige in Bangkok geborene Piraya Suthimai. Nach ihrem Bachelor-Studium an der Universit\u00e4t von Melbourne (Australien) und einem l\u00e4ngeren Praktikum bei BMW in M\u00fcnchen wird sie nun den Master-Studiengang in Management (M.Sc.) in Leipzig absolvieren. Piraya Suthima sagt: &#8222;Ich habe mich f\u00fcr die HHL aufgrund ihres flexiblen MSc-Programms entschieden. Die M\u00f6glichkeit, w\u00e4hrend des Studiums zwei Praktika absolvieren zu k\u00f6nnen, ist mir wichtig. Ich denke, dass gerade die Verbindung zwischen Theorie und Praxis mich bestens f\u00fcr den sp\u00e4teren Berufseinstieg vorbereitet. Nach meiner Zeit an der HHL m\u00f6chte ich gerne erst einmal in Europa arbeiten.&#8220;<br \/> Der 30-j\u00e4hrige geb\u00fcrtige Hallenser Sascha Meissner, der vor dem MBA-Studium bei IBM als Senior Consultant t\u00e4tig war, sagt: &#8222;Meine Wahl fiel auf die HHL aufgrund ihrer weltweiten Reputation, ihres umfassenden Curriculums sowie ihrer Internationalit\u00e4t. Hinzu kommt die geographische Lage der Business School. Mein Ziel ist es, nach dem Studienabschluss an der HHL in der Region Halle-Leipzig t\u00e4tig zu sein.&#8220;<\/p> <p>Welcome Days mit Fokus auf verantwortliches Handeln in der Wirtschaft<\/p> <p>Die feierliche Immatrikulation aller neuen Studierenden fand am Dienstag (13. September 2011) statt. In der Einf\u00fchrungsvorlesung sagte Karl-Erivan W. Haub, Gesch\u00e4ftsf\u00fchrender und pers\u00f6nlich haftender Gesellschafter der Unternehmensgruppe Tengelmann: &#8222;Unsere Wirtschaftswelt braucht F\u00fchrungspers\u00f6nlichkeiten mit Charisma und Talent. Mein Rat an die HHL-Studenten lautet: Finden Sie heraus, worin Sie am besten sind, entwickeln Sie sich weiter und erz\u00e4hlen Sie in Ihren Kreisen von der HHL.&#8220; Rektor Prof. Dr. Andreas Pinkwart sagte: &#8222;Herzlich hei\u00dfen wir die neuen HHL-Studenten willkommen. Sie haben die richtige Wahl getroffen, studieren Sie doch an einer universit\u00e4ren Einrichtung, deren Mission auf exzellente Lehre und qualit\u00e4tsvoller Forschung gr\u00fcndet. Die internationale HHL-Gemeinschaft erm\u00f6glicht Ihnen, Ihr pers\u00f6nliches wie berufliches Netzwerk um eine globale Perspektive zu erweitern. An der HHL werden Sie einen wahrlich unternehmerischen Geist mit mehr als 120 Unternehmensgr\u00fcndungen durch HHL-Alumni erleben.&#8220;<\/p> <p>Auf spielerische Weise lernen heute Nachmittag die neuen HHLler ihre Hochschule und die Stadt Leipzig kennen. In Teams, bestehend aus Studenten aller Studienprogramme, gehen die Handelshochsch\u00fcler auf eine Schnitzeljagd. Auf dem HHL-Campus m\u00fcssen die B\u00fcros der Lehrst\u00fchle und Mitarbeiter angesteuert werden. Dort sind Fragen wie &#8222;Prof. Z\u00fclch ist ein gro\u00dfer Fan von welchem deutschen Fu\u00dfballverein?&#8220; oder &#8222;Welche Funktion hatte Leipzigs Alte Handelsb\u00f6rse zur Zeit ihrer Entstehung gehabt?&#8220; zu beantworten. Auf das Siegerteam wartet eine kleine \u00dcberraschung.<\/p> <p>Der morgige, zweite &#8222;Welcome Day&#8220; dreht sich um ein Thema mit hoher gesellschaftlicher sowie volkswirtschaftlicher Relevanz: verantwortungsbewusstes Handeln. Ziel ist es, den Studierenden bereits vom ersten Tag an die Bedeutung des Themenkomplexes Nachhaltigkeit und Verantwortung f\u00fcr den unternehmerischen Alltag und die universit\u00e4re Ausbildung zu vermitteln. Organisatorisch und inhaltlich wird dieser Teil des &#8222;Welcome Events&#8220; vom Dr. Werner Jackst\u00e4dt Lehrstuhl f\u00fcr Wirtschafts- und Unternehmensethik der HHL verantwortet.<\/p> <p>Durch Impulsreferate von Mitarbeitern der Sponsoren der Veranstaltung, d.h. Henkel, Deutsche Bank und Bosch, erhalten die Studierenden Einblicke in die Herausforderungen der Umsetzung der unterzeichneten Leitlinien f\u00fcr verantwortliches Handeln in der Wirtschaft. Es werden dann am Nachmittag Konzepte erarbeitet, wie bspw. die Umsetzung des Leitbildes effektiver intern und extern durch die Unternehmen kommuniziert werden k\u00f6nnte. Weitere Informationen zu dem Leitbild: http:\/\/www.wcge.org\/529.htm<\/p> <p>Die Handelshochschule Leipzig (HHL)<\/p> <p>Die HHL ist eine universit\u00e4re Einrichtung und z\u00e4hlt zu den f\u00fchrenden internationalen Business Schools. Ziel der \u00e4ltesten betriebswirtschaftlichen Hochschule im deutschsprachigen Raum ist die Ausbildung leistungsf\u00e4higer, verantwortungsbewusster und unternehmerisch denkender F\u00fchrungspers\u00f6nlichkeiten. Neben der internationalen Ausrichtung spielt die Verkn\u00fcpfung von Theorie und Praxis eine herausragende Rolle. Die HHL zeichnet sich aus durch exzellente Lehre, klare Forschungsorientierung und praxisnahen Transfer sowie hervorragenden Service f\u00fcr ihre Studierenden. Sie bietet den 18-monatigen (bzw. 24-monatigen berufsbegleitenden) Master-Studiengang in Management (M.Sc.) an. Dar\u00fcber hinaus kann an der HHL der 18-monatige (bzw. 24-monatige berufsbegleitende) Master-Studiengang in General Management (MBA) belegt werden. Ein dreij\u00e4hriges Promotionsprogramm, das auch berufsbegleitend absolviert werden kann, rundet das Studienangebot der Leipziger Business School ab. Mit der HHL-Tochtergesellschaft HHL Executive GmbH werden firmenspezifische und offene Weiterbildungsprogramme f\u00fcr F\u00fchrungskr\u00e4fte angeboten. Im April 2004 erhielt die Hochschule die Akkreditierung durch AACSB International und hat diese als erste deutsche private Hochschule im April 2009 durch eine Reakkreditierung best\u00e4tigen k\u00f6nnen. Weitere Informationen: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.hhl.de\" title=\"Die Handelshochschule Leibzig\" >http:\/\/www.hhl.de<\/a><\/p> <p>Firmenkontakt<br \/> Handelshochschule Leipzig gGmbH<br \/> Volker St\u00f6\u00dfel<br \/> Jahnallee 59<\/p> <p>04109 Leipzig<br \/> Deutschland<\/p> <p>E-Mail: volker.stoessel@hhl.de<br \/> Homepage: http:\/\/www.hhl.de<br \/> Telefon: 0341-9851-614<\/p> <p>Pressekontakt<br \/> Handelshochschule Leipzig gGmbH<br \/> Volker St\u00f6\u00dfel<br \/> Jahnallee 59<\/p> <p>04109 Leipzig<br \/> Deutschland<\/p> <p>E-Mail: volker.stoessel@hhl.de<br \/> Homepage: http:\/\/www.hhl.de<br \/> Telefon: 0341-9851-614<\/p>","protected":false},"excerpt":{"rendered":"<p>An der Handelshochschule Leipzig (HHL) haben sich zum Wintersemester 2011\/12 insgesamt 117 Studierende aus 29 L\u00e4ndern immatrikuliert. Darunter sind 43 Austauschstudenten aus dem mittlerweile auf 107 Partnerhochschulen angewachsenen internationalen Netzwerk der HHL. Der Anteil internationaler Studierender hat zu Beginn des neuen Studienjahrs die Rekordmarke von gut 60 Prozent erreicht. Bei der Wahl ihrer Hochschule spielten<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-28779","post","type-post","status-publish","format-standard","hentry","category-wirtschaft-management-versicherung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/28779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=28779"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/28779\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=28779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=28779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=28779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}