{"id":28782,"date":"2011-09-14T09:58:10","date_gmt":"2011-09-14T08:58:10","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=28782"},"modified":"2011-09-14T09:58:10","modified_gmt":"2011-09-14T08:58:10","slug":"schmerzen-erfolgreich-bekaempfen-durch-reizstromgeraete","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/schmerzen-erfolgreich-bekaempfen-durch-reizstromgeraete-1028782\/","title":{"rendered":"Gefahrlose, effektive und wirkungsvolle Behandlungsmethode gegen Schmerzen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"Schmerztherapie und Muskelstimulation mit dem digitalen Kombinationsger\u00e4t f\u00fcr den bequemen Einsatz Zuhause.\" src=\"http:\/\/www.tensshop.de\/images\/product_images\/info_images\/digi01.jpg\" alt=\"\" width=\"124\" height=\"110\" \/>R\u00fcckenschmerzen, Migr\u00e4ne und Rheuma k\u00f6nnen schon fast als Volkskrankheiten angesehen werden. So ist die Zahl derer, die an diesen Symptomen leiden, in den letzten Jahrzehnten f\u00f6rmlich &#8222;explodiert&#8220;. Die Folgen finden sich nicht nur im volkswirtschaftlichen Bereich durch Arbeitsausf\u00e4lle etc., sondern die Schmerzen beeintr\u00e4chtigen auch das pers\u00f6nliche Leben. Viele greifen daher zu schmerzlindernden Medikamenten, obwohl sie sich dessen bewusst sind, dass sie damit ihrem K\u00f6rper auf Dauer schaden.<\/p> <p><!--more-->Abhilfe schafft jedoch oft eine Behandlung mit Reizstrom in Form einer Transkutane-Elektrische-Nervenstimulation (TENS). Reizstromger\u00e4te sind eine wertvolle und nebenwirkungsfreie Hilfe bei vielen Beschwerden und Schmerzen wie z. B. bei R\u00fcckenschmerzen, Kreuzschmerzen, Schulterschmerzen, Nackenschmerzen, Sportverletzungen, Migr\u00e4ne und Rheuma. Aber sie dienen auch der Muskelstimulation, der Nervenstimulation und der Massage, f\u00f6rdern die Durchblutung und unterst\u00fctzen die Gewebestraffung. TENS ist damit eine gefahrlose, sehr effektive und wirkungsvolle Behandlungsmethode gegen Schmerzen. Ihre Wirkung ist in klinischen Studien untersucht worden und wird in vielen L\u00e4ndern bereits seit 20 Jahren angewendet. Auch bei schon chronisch gewordenen Schmerzen werden hervorragende Ergebnisse erzielt. Durch Stimulationsimpulse kann sogar der Beckenboden trainiert werden und so wirksam die Inkontinenz bek\u00e4mpft werden. So ist das <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.tensshop.de\/index.php?cat=c44_Massage--und-Reizstromgeraete.html\" title=\"Die transkutane elektrische Nervenstimulation ist eine sehr wirkungsvolle, gefahrlose und alternative Behandlungsmethode gegen Schmerzen\" >Reizstromger\u00e4t<\/a> auch in Deutschland seit langem in Kliniken, Praxen und Therapeuten erfolgreich im Einsatz. Oft kombiniert wird die Behandlung mit TENS-Ger\u00e4ten mit EMS-Ger\u00e4ten (Elektromyostimulation), die der Muskelstimulation dienen.<\/p> <p>Aber auch im privaten Umfeld k\u00f6nnen Schmerzen mit Reizstromger\u00e4ten behandelt werden.<br \/> Als eines der f\u00fchrenden Unternehmen f\u00fcr den Online-Vertrieb von Reizstromger\u00e4ten hat es sich die Firma Ostimex Elektronik Vertrieb GmbH zur Aufgabe gemacht, ihren Kunden eine gefahrlose Behandlung im h\u00e4uslichen Umfeld zu erm\u00f6glichen und dieses zu g\u00fcnstigen Preisen. Neben einer gro\u00dfen Auswahl an TENS-Ger\u00e4ten und EMS-Ger\u00e4ten befindet sich auch reichhaltiges Zubeh\u00f6r im Sortiment der Firma. Dar\u00fcber hinaus ist das VITAtronic-Optima-Ger\u00e4t, das man gleichfalls in dem Onlineshop findet, eine nebenwirkungsfreie Alternative zur Behandlung von Erektionsst\u00f6rungen und Impotenz. Aber auch weitere Gesundheitsprodukte wie z. B. das Hydro-Sana Entschlackungs Fu\u00dfbad, das der Entspannung und Vitalisierung dient, geh\u00f6ren genauso zu dem Lieferprogramm von Ostimex wie der Raumionisator SmokeEX, der bei Atemwegsallergien hilft und Geruchsbel\u00e4stigungen durch Tabakrauch beseitigt. Gleicherma\u00dfen f\u00fchrt der Raumionisator zur Steigerung des allgemeinen Wohlbefindens durch Normalisierung der K\u00f6rperfunktionen, f\u00f6rdert die Aufnahmef\u00e4higkeit von Sauerstoff durch die Lungen und lindert chronische Beschwerden wie Asthma und Bronchitis. Abgerundet wird das umfangreiche Sortiment durch ausgesuchte Naturprodukte und Nahrungserg\u00e4nzungsmittel zu attraktiven Sonderkonditionen.<\/p> <p>N\u00e4here Informationen \u00fcber das gesamte Lieferprogramm von Ostimex findet man auf der Seite www.tensshop.de. Der interessant aufgebauten Seite sind auch weitere Serviceleistungen zu entnehmen wie z. B. eine Hotline f\u00fcr die Kaufberatung und einer Hotline f\u00fcr die Ger\u00e4teeinweisung.<\/p> <p>Angaben zum Unternehmen:<\/p> <p>Ostimex Elektronik Vertrieb GmbH<br \/> Gesch\u00e4ftsf\u00fchrer: Friedrich Novotny<br \/> Talstr. 3<br \/> 72178 Waldachtal<br \/> Tel.: 07443 6111<br \/> Fax: 07443 7543<br \/> email: info@tensshop.de<br \/> Internet: www.tensshop.de<\/p> <p>Verantwortlich f\u00fcr Texteinstellung:<br \/> DieWebAG<br \/> Email: presse@diewebag.de<br \/> Internet: www.diewebag.de\/suchmaschinenmarketing.php<\/p> <p>Firmenkontakt<br \/> Ostimex GmbH<br \/> Friedrich Novotny<br \/> Talstr. 3<\/p> <p>72178 Waldachtal<br \/> Deutschland<\/p> <p>E-Mail: info@tensshop.de<br \/> Homepage: http:\/\/www.tensshop.de<br \/> Telefon: 07443\/6111<\/p> <p>Pressekontakt<br \/> Ostimex GmbH<br \/> Friedrich Novotny<br \/> Talstr. 3<\/p> <p>72178 Waldachtal<br \/> Deutschland<\/p> <p>E-Mail: info@tensshop.de<br \/> Homepage: http:\/\/www.tensshop.de<br \/> Telefon: 07443\/6111<\/p>","protected":false},"excerpt":{"rendered":"<p>R\u00fcckenschmerzen, Migr\u00e4ne und Rheuma k\u00f6nnen schon fast als Volkskrankheiten angesehen werden. So ist die Zahl derer, die an diesen Symptomen leiden, in den letzten Jahrzehnten f\u00f6rmlich &#8222;explodiert&#8220;. Die Folgen finden sich nicht nur im volkswirtschaftlichen Bereich durch Arbeitsausf\u00e4lle etc., sondern die Schmerzen beeintr\u00e4chtigen auch das pers\u00f6nliche Leben. Viele greifen daher zu schmerzlindernden Medikamenten, obwohl sie<\/p>\n","protected":false},"author":291,"featured_media":198021,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-28782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernahrung-umwelt-natur"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/28782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=28782"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/28782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198021"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=28782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=28782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=28782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}