{"id":2935,"date":"2009-12-18T15:53:58","date_gmt":"2009-12-18T14:53:58","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=2935"},"modified":"2015-08-28T11:38:38","modified_gmt":"2015-08-28T10:38:38","slug":"motiviertere-softwareanwender-durch-natuerliche-interaktion","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/motiviertere-softwareanwender-durch-natuerliche-interaktion-102935\/","title":{"rendered":"Motiviertere Softwareanwender durch nat\u00fcrliche Interaktion"},"content":{"rendered":"<p><strong>Bundesministerium f\u00fcr Bildung und Forschung f\u00f6rdert Projekt &#8222;Fun of Use with Natural Interactions&#8220;<\/strong><\/p> <p>Das Forschungsprojekt &#8222;Fun of Use with Natural Interactions&#8220; (FUN-NI) untersucht seit Mai 2009, wie durch nat\u00fcrliche Interaktionsformen in Software das Nutzungserlebnis der Anwender gesteigert werden kann. Das positive Nutzererleben wiederum soll zu einer h\u00f6heren Akzeptanz der Softwareprodukte und zu einer besseren Motivation der Anwender f\u00fchren.<!--more--><\/p> <p>Die heute g\u00e4ngigen grafischen Benutzerschnittstellen von Software adressieren den Sehsinn. Als Interaktionsmedien verwenden sie meist Tastaturen und PC-M\u00e4use. Ziel des Projektes FUN-NI ist es, Benutzerschnittstellen zu entwickeln, die den Anwender mehr Sinne als bisher einsetzen lassen. Durch nat\u00fcrliche Interaktionsformen wie Sprache, Gestik oder Multi-Touch wird die Interaktion so gestaltet, wie es der Benutzer von nicht-technischen Objekten gewohnt ist. Hierdurch wird die Freude am Bedienen der Software (Fun of Use, User Experience) gesteigert \u2013 mit dem Effekt, dass der Anwender seine Produkte motivierter, \u00f6fter und andauernder einsetzt.<\/p> <p>Das Projekt FUN-NI ist Teil der Forschungsoffensive &#8222;KMU-innovativ: IKT&#8220;, die vom Bundesministerium f\u00fcr Bildung und Forschung eingerichtet wurde. Die Projektleitung liegt bei der a3 systems GmbH (Saarbr\u00fccken). Weitere Projektpartner sind die CIBEK technology + trading GmbH (Limburgerhof), das Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering IESE (Kaiserslautern) und die Folkwang Hochschule (Essen).<\/p> <p>&#8222;Positives Nutzererleben sorgt f\u00fcr Leistungsverbesserungen beim Anwender. Dies haben wir bereits in einem Vorg\u00e4ngerprojekt nachgewiesen&#8220;, erl\u00e4utert Rudolf Klein, Mitglied der Gesch\u00e4ftsf\u00fchrung der a3 systems GmbH. &#8222;Softwareprodukte, die der Anwender nachgewiesenerma\u00dfen bereitwilliger nutzt, bieten zudem einen deutlichen Wettbewerbsvorteil gegen\u00fcber herk\u00f6mmlichen Produkten. Die Anwender sind konzentrierter, sie verwenden ihre Software effizienter und die Investitionskosten amortisieren sich schneller.&#8220;<\/p> <p>Der Arbeitsansatz des Projektes basiert auf der Identifikation und Evaluation erfolgreicher Interaktionsmuster, sogenannter Patterns. Neben diesen Patterns wird im Projekt eine neue Evaluationsmethode entwickelt. Hierdurch werden softwareproduzierende KMU in der Lage sein, selbst die gew\u00fcnschten User-Experience-Eigenschaften in ihren Produkten zu \u00fcberpr\u00fcfen. Dies soll das Risiko bei der Entwicklung innovativer Softwareprodukte senken.<\/p> <p>Mehr Informationen zum Projekt &#8222;Fun of Use with Natural Interactions&#8220; (BMBF-F\u00f6rderkennzeichen 01 IS 09007) finden Sie im Internet unter www.fun-ni.org.<\/p> <p>\u00dcber die a3 systems GmbH (www.a3systems.com)<br \/> a3 systems ist eine L\u00f6sungsanbieterin f\u00fcr anspruchsvolle Gesch\u00e4ftsanwendungen und Integrationsprojekte. a3 systems entwirft, entwickelt und testet Softwarel\u00f6sungen auf Basis anerkannter Industriestandards und \u201eBest Practice\u201c-Ans\u00e4tze. Projektspezifisch zusammengestellte Expertenteams begleiten die Projekte durch alle Projektphasen \u2013 von der Analyse und Spezifikation \u00fcber Design, Implementierung und Integration bis hin zu Einf\u00fchrung, Software-Wartung und Betrieb. Mit der dante\u00ae Produktfamilie bietet a3 systems Standardprodukte f\u00fcr die Bereiche Content Management, Newslettermarketing und Helpdesk.<\/p> <p>Ihr pers\u00f6nlicher Ansprechpartner f\u00fcr weitere Fragen:<\/p> <p>Hartmut Schmitt<br \/> a3 systems GmbH<br \/> Saarbr\u00fccker Stra\u00dfe 51<br \/> 66130 Saarbr\u00fccken<br \/> Telefon: +49 (681) 988 18-16<br \/> Telefax: +49 (681) 988 18-29<br \/> E-Mail: hartmut.schmitt@a3systems.com<br \/> Internet: www.a3systems.com<br \/> Newsletter: www.instant-mailing.com\/im\/a3<\/p>","protected":false},"excerpt":{"rendered":"<p>Bundesministerium f\u00fcr Bildung und Forschung f\u00f6rdert Projekt &#8222;Fun of Use with Natural Interactions&#8220; Das Forschungsprojekt &#8222;Fun of Use with Natural Interactions&#8220; (FUN-NI) untersucht seit Mai 2009, wie durch nat\u00fcrliche Interaktionsformen in Software das Nutzungserlebnis der Anwender gesteigert werden kann. Das positive Nutzererleben wiederum soll zu einer h\u00f6heren Akzeptanz der Softwareprodukte und zu einer besseren Motivation<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8808],"tags":[],"class_list":["post-2935","post","type-post","status-publish","format-standard","hentry","category-wissenschaft"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/2935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=2935"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/2935\/revisions"}],"predecessor-version":[{"id":203597,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/2935\/revisions\/203597"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=2935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=2935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=2935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}