{"id":32387,"date":"2011-10-14T11:21:44","date_gmt":"2011-10-14T10:21:44","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=32387"},"modified":"2011-10-14T11:21:44","modified_gmt":"2011-10-14T10:21:44","slug":"frankfurter-buchmesse-2011-ravensburger-ist-marktfuehrer-bei-kinder-und-jugendbuechern","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/frankfurter-buchmesse-2011-ravensburger-ist-marktfuehrer-bei-kinder-und-jugendbuechern-1032387\/","title":{"rendered":"Frankfurter Buchmesse 2011:  Ravensburger ist Marktf\u00fchrer bei Kinder- und Jugendb\u00fcchern"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" title=\"Kinder- und Jugendb\u00fccher von Ravensburger \" src=\"http:\/\/static.images.ravensburger.de\/images\/produktseiten\/240\/54373.jpg\" alt=\"\" width=\"83\" height=\"123\" \/>(ddp direct)Ravensburg &#8211; Ein solides Umsatzwachstum erzielte der Ravensburger Buchverlag in den ersten drei Quartalen des Gesch\u00e4ftsjahres 2011, w\u00e4hrend der Kinder- und Jugendbuchmarkt nahezu auf Vorjahresniveau blieb. Wir gehen optimistisch ins Weihnachtsgesch\u00e4ft, \u00e4u\u00dferte sich Gesch\u00e4ftsf\u00fchrer Johannes Hauenstein auf der Frankfurter Buchmesse. Dar\u00fcber hinaus sei der Verlag f\u00fcr die k\u00fcnftigen medialen Ver\u00e4nderungen in der Buchbranche gut aufgestellt.<\/p> <p><!--more-->In einem Pressegespr\u00e4ch auf der Frankfurter Buchmesse erl\u00e4uterten die beiden Gesch\u00e4ftsf\u00fchrer des Ravensburger Buchverlages, Ulrike Metzger und Johannes Hauenstein, Tendenzen in der Branche und die Position von Ravensburger: Der klassische Kinder- und Jugendbuchmarkt ist ein Markt mit Zukunft und eine stabile S\u00e4ule der Buchbranche, sagte Metzger. Trotz der vielf\u00e4ltigen Mediennutzungsm\u00f6glichkeiten bleibt das gedruckte Buch das wichtigste Medium im Kinderzimmer. Gleichzeitig w\u00fcrden elektronische Kinderb\u00fccher an Bedeutung gewinnen, das klassische Buch jedoch nicht ersetzen, sondern erg\u00e4nzen.<\/p> <p>Eine weitere Tendenz sei die steigende Nachfrage des Buchhandels nach Non-Book Produkten, berichtete Hauenstein. Potential sehe er vor allem bei Spielen und Besch\u00e4ftigungsprodukten, die sich gut mit den vorhandenen Kinder- und Jugendbuchthemen erg\u00e4nzen w\u00fcrden.<\/p> <p>Ravensburger ist f\u00fcr diese Ver\u00e4nderungen im Buchmarkt gut aufgestellt, sagte Hauenstein. Unser Programm umfasst neben B\u00fcchern auch Spiele, Puzzles und Kreativprodukte. Deshalb ist Ravensburger auch im Non-Book Bereich ein idealer Partner des Handels. Neue Impulse setzen unsere Entwicklungen im digitalen Segment: So wurden vom audiodigitalen Lernsystem tiptoi\u00ae eine Million Produkte innerhalb eines Jahres verkauft.<\/p> <p>Weitere Informationen zu Ravensburger finden Sie unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.ravensburger.de\" title=\"Onlineshop des Ravensburger Buchverlags\" >www.ravensburger.de<\/a><\/p> <p>Firmenkontakt<br \/> Ravenburger AG<br \/> Heinrich H\u00fcntelmann<br \/> Robert-Bosch-Str. 1<\/p> <p>88214 Ravensburg<br \/> Deutschland<\/p> <p>E-Mail: heinrich.huentelmann@ravensburger.de<br \/> Homepage: http:\/\/www.ravensburger.de<br \/> Telefon: +49(0)751.86 19 42<\/p> <p>Pressekontakt<br \/> Ravenburger AG<br \/> Heinrich H\u00fcntelmann<br \/> Robert-Bosch-Str. 1<\/p> <p>88214 Ravensburg<br \/> Deutschland<\/p> <p>E-Mail: heinrich.huentelmann@ravensburger.de<br \/> Homepage:<br \/> Telefon: +49(0)751.86 19 42<\/p>","protected":false},"excerpt":{"rendered":"<p>(ddp direct)Ravensburg &#8211; Ein solides Umsatzwachstum erzielte der Ravensburger Buchverlag in den ersten drei Quartalen des Gesch\u00e4ftsjahres 2011, w\u00e4hrend der Kinder- und Jugendbuchmarkt nahezu auf Vorjahresniveau blieb. Wir gehen optimistisch ins Weihnachtsgesch\u00e4ft, \u00e4u\u00dferte sich Gesch\u00e4ftsf\u00fchrer Johannes Hauenstein auf der Frankfurter Buchmesse. Dar\u00fcber hinaus sei der Verlag f\u00fcr die k\u00fcnftigen medialen Ver\u00e4nderungen in der Buchbranche gut<\/p>\n","protected":false},"author":291,"featured_media":197909,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[361],"tags":[],"class_list":["post-32387","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verlagsnachrichten"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/32387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=32387"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/32387\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197909"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=32387"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=32387"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=32387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}