{"id":32503,"date":"2011-10-17T15:41:04","date_gmt":"2011-10-17T14:41:04","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=32503"},"modified":"2014-11-26T16:59:24","modified_gmt":"2014-11-26T15:59:24","slug":"bildungsdoc-kompass-fuer-den-persoenlichen-bildungserfolg","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/bildungsdoc-kompass-fuer-den-persoenlichen-bildungserfolg-1032503\/","title":{"rendered":"Viele F\u00f6rdert\u00f6pfe f\u00fcr Bildungsaufenthalte im Ausland"},"content":{"rendered":"<p>Erfolg im Beruf ist planbar &#8211; Bildung auch? Bei einem Bewerbungsgespr\u00e4ch \u00fcberzeugen nicht nur gute Noten und ein seri\u00f6ses und sympathisches Auftreten. Wichtig sind auch nachweisbare Auslandsaufenthalte parallel zur Schule und zum Studium. Doch welche Auslandsangebote gibt es, welche taugen etwas und wie sieht es mit F\u00f6rdergeldern aus? bildungsdoc bahnt einen Weg durch das Dickicht und zeigt, dass auch Bildungserfolg planbar ist \u2013 ab Schulbeginn!<\/p> <p>bildungsdoc versteht sich u.a. auch als Wegweiser f\u00fcr erfolgreiche Bildungsaufenthalte im Ausland. Das Infoportal sammelt kontinuierlich sachkundig und kompakt alle wichtigen Informationen und gibt viele hilfreiche Tipps.<\/p> <p><!--more-->Das Portal stellt denn auch Sch\u00fclersprachreisen f\u00fcr Kinder ab 7 Jahren vor, informiert \u00fcber das High School Year, berichtet von Sprachreisen ab 16 Jahren und weist auf die M\u00f6glichkeit hin, im Ausland auch als Au Pair zu arbeiten. Work and Travel wird sowieso immer beliebter und wer im Ausland an der Freiwilligenarbeit teilnimmt, kann sogar noch soziales Engagement nachweisen. Auch \u00fcber einen Bildungsurlaub und \u00fcber ein Auslandsstudium oder Auslandspraktikum informiert bildungsdoc. Passend zu jedem Auslandsprogramm pr\u00e4sentiert das Portal eine handverlesene Auswahl von Veranstaltern, Agenturen und Organisationen &#8211; mit Adresse und Kontaktdaten.<\/p> <p>Ein Auslandsaufenthalt kostet Geld. Verm\u00f6gende Familien k\u00f6nnen sich das leisten. Wo die Einnahmen bei den Eltern nicht so \u00fcppig sprudeln, sind 10.000 Euro etwa f\u00fcr ein 10-monatiges High School Year schwer aufzubringen &#8211; auch wenn es den Horizont erweitert und die Fremdsprachenkenntnisse perfektioniert.<\/p> <p>Was viele Eltern nicht wissen: Es gibt viele F\u00f6rdert\u00f6pfe f\u00fcr Bildungsaufenthalte im Ausland und zwar sowohl staatliche als auch solche der EU. Diese F\u00f6rdert\u00f6pfe sind zurzeit so gut gef\u00fcllt wie noch nie. bildungsdoc informiert dar\u00fcber, welche F\u00f6rdermittel es f\u00fcr Auslandsprogramme gibt und wie sich die F\u00f6rderma\u00dfnahmen effektiv aussch\u00f6pfen lassen. Hinzu kommt: Die Fl\u00fcge, Wechselkurse und Lebenshaltungskosten im Ausland waren schon lange nicht mehr so g\u00fcnstig wie jetzt.<\/p> <p>Ganz wichtig: Alle empfohlenen Veranstalter f\u00fcr Bildungsaufenthalte im Ausland sind Mitglieder in Fachverb\u00e4nden bzw. die Weiterbildungsfernschulen sind staatlich anerkannt. Somit wird den Eltern und dem reisenden Nachwuchs auch die n\u00f6tige Fachkompetenz vermittelt. Nur so ist garantiert, dass das Geld gut investiert ist und nicht verloren geht.<\/p> <p>\u00dcbrigens entl\u00e4sst bildungsdoc \u201eseine\u201c Sch\u00fcler, Studenten und Erwachsene auch nach dem Auslandsaufenthalt nicht, sondern bietet ihnen ein umfangreiches Kompendium, u.a. zu den Themen &#8222;Bewerbung&#8220; und &#8222;Vorstellungsgespr\u00e4ch&#8220; an. Hier lassen sich viele Tipps einsehen, die aufzeigen, wie sich die eigenen Auslandsaufenthalte besonders gewinnbringend in eigener Sache vermarkten lassen.<\/p> <p>Weitere zahlreiche Informationen zu Bildungsprogrammen und Angeboten: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.bildungsdoc.de\" title=\"    bildungsdoc vereinigt Bildungssuchende, Bildungsanbieter und Bildungsberater \u2013 deutschlandweit!\" >http:\/\/www.bildungsdoc.de<\/a><\/p> <p>bildungsdoc f\u00fchrt u.a. auch Seminare und Workshops zur Aus- und Weiterbildung von unabh\u00e4ngigen Bildungsberatern in ganz Deutschland durch, um den Aufbau des Bildungspools f\u00fcr unabh\u00e4ngige Bildungsberatung weiter zu forcieren. Auf der Website von bildungsdoc sind au\u00dferdem vier unterschiedliche Datenbanken integriert, in denen sich Bildungsanbieter, Bildungsberater und Netzwerk-Partner mit ihrem Profil eintragen k\u00f6nnen. Die Datenbanken erm\u00f6glichen Usern, Bildungssuchenden und Bildungsberatern eine schnelle und einfache Suche nach Bildungsprogrammen und gew\u00fcnschten Dienstleistungsangeboten \u2013 kategorisiert nach Bundesland, PLZ oder bundesweit!<\/p> <p>bildungsdoc<br \/> AP: Horst Rindfleisch<br \/> Theodor-Friedrich-Weg 4<br \/> 01279 Dresden<br \/> Fon: 0351-2543405<br \/> Mobil: 01577 &#8211; 1720859<br \/> E-Mail: info@bildungsdoc.de<br \/> Internet: http:\/\/www.bildungsdoc.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Erfolg im Beruf ist planbar &#8211; Bildung auch? Bei einem Bewerbungsgespr\u00e4ch \u00fcberzeugen nicht nur gute Noten und ein seri\u00f6ses und sympathisches Auftreten. Wichtig sind auch nachweisbare Auslandsaufenthalte parallel zur Schule und zum Studium. Doch welche Auslandsangebote gibt es, welche taugen etwas und wie sieht es mit F\u00f6rdergeldern aus? bildungsdoc bahnt einen Weg durch das Dickicht<\/p>\n","protected":false},"author":291,"featured_media":32506,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-32503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familie-jugend-familie"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/32503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=32503"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/32503\/revisions"}],"predecessor-version":[{"id":173111,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/32503\/revisions\/173111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/32506"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=32503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=32503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=32503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}