{"id":33135,"date":"2011-10-21T12:02:50","date_gmt":"2011-10-21T11:02:50","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=33135"},"modified":"2017-12-08T12:32:24","modified_gmt":"2017-12-08T11:32:24","slug":"energiebau-erhaelt-deutschen-solarpreis-2011","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/energiebau-erhaelt-deutschen-solarpreis-2011-1033135\/","title":{"rendered":"Reine Energie f\u00fcr Industrie- und Entwicklungsl\u00e4nder"},"content":{"rendered":"<p>(ddp direct)Die Energiebau Solarstromsysteme GmbH aus K\u00f6ln erh\u00e4lt als Pionier der Photovoltaik-Branche in diesem Jahr den renommierten Deutschen Solarpreis 2011 in der Kategorie Industrielle, kommerzielle oder landwirtschaftliche Betriebe\/Unternehmen. Verliehen wird der Preis seit 1994 durch die Europ\u00e4ische Vereinigung f\u00fcr erneuerbare Energien e.V. (Eurosolar) an Kommunen, Unternehmen, Medien und engagierte Initiativen, die sich um die Nutzung Erneuerbarer Energien besonders verdient gemacht haben.<\/p> <p>Gew\u00fcrdigt wird Energiebau f\u00fcr das unternehmerische Gesamtkonzept, so Eurosolar: Die Entwicklung vom Solarstrompionier zu einem der f\u00fchrenden Anbieter f\u00fcr Solarstromsysteme zeigt, dass Werteorientierung und wirtschaftlicher Erfolg vereint werden k\u00f6nnen. Energiebau steht damit repr\u00e4sentativ f\u00fcr die Unternehmen, die die Energiewende m\u00f6glich machen.<\/p> <p><!--more-->Solarstrom geh\u00f6rt die Zukunft<br \/> Das Photovoltaik-Systemhaus Energiebau vertreibt Solarstromsysteme und -komponenten an ein bundesweites Netzwerk von Fachpartnern aus dem Elektrohandwerk. 1983 gestartet als Ingenieursb\u00fcro f\u00fcr Energieeffizienz, geh\u00f6rt das inhabergef\u00fchrte Unternehmen mittlerweile zu den f\u00fchrenden Photovoltaik-Systemh\u00e4usern in Europa. Rund 350 Mitarbeiter am Stammsitz in K\u00f6ln sowie in den L\u00e4ndergesellschaften in den Benelux-Staaten, Frankreich, Italien, Ghana und den USA arbeiten erfolgreich am Ausbau der Photovoltaik in den jeweiligen M\u00e4rkten. Unsere Vision ist einfach: wir wollen eine lebenswerte Welt schaffen mit nachhaltiger Energieversorgung, skizziert der Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer Michael Sch\u00e4fer.<br \/> \u00dcber viele Jahre haben wir es gegen immense Gegenwehr der konventionellen Energieversorger mit unseren Mitstreitern geschafft, dass die Photovoltaik aus der Energieversorgung der Gegenwart und Zukunft nicht mehr wegzudenken ist, so Sch\u00e4fer weiter. Der Solarpionier rechnet, dass schon gegen Ende dieses Jahrzehnts Solarstrom mindestens 10% des Strombedarfs in Deutschland decken wird.<\/p> <p>Ausgezeichnete Vielfalt<br \/> In den ersten 20 Jahren des Firmenbestehens lag der Schwerpunkt in der Installation von Solaranlagen auf Haus- und Gewerbed\u00e4chern. Die so gewonnene Erfahrung in der t\u00e4glichen Praxis des Solarhandwerks flie\u00dft sowohl in die umfangreichen Kundenschulungen als auch in die Projektierung von Solarkraftwerken. Das wachsende Projektgesch\u00e4ft hat Energiebau konsequent zu einem internationalen Gesch\u00e4ftsbereich ausgebaut.<br \/> Branchenweite Bekanntheit genie\u00dft Energiebau als Entwickler und Hersteller von Modulbefestigungssystemen f\u00fcr alle Dachtypen, die unter dem Produktnamen LORENZ vertrieben werden. Das Flaggschiff des Montagesystems, LORENZ plus, wurde dieses Jahr bereits mit dem Produktdesignpreis iF Design Award ausgezeichnet.<\/p> <p>Reine Energie f\u00fcr Industrie- und Entwicklungsl\u00e4nder<br \/> Neben Anlagen zur Netzeinspeisung hat Energiebau fr\u00fcher als andere damit begonnen, den Markt f\u00fcr autarke Anlagen in Regionen ohne Netzanschluss zu erschlie\u00dfen. Seit 1994 engagiert sich das Unternehmen in Afrika und hat dort zahlreiche Dorfkliniken, Schulen und soziale Einrichtungen mit Solarstrom versorgt.<br \/> Mittlerweile werden auch gr\u00f6\u00dfere Anlagen in Afrika installiert. Aufsehen erregendes Beispiel ist die von UN-Generalsekret\u00e4r Ban Ki-Moon eingeweihte Photovoltaik-Anlage auf Afrikas erstem klimaneutralem B\u00fcrogeb\u00e4ude, dem Neubau des Umweltprogramms der Vereinten Nationen UNEP in der kenianischen Hauptstadt Nairobi. Die gro\u00dfen Erfolge der gesamten Photovoltaikbranche in Bezug auf Kostensenkungen und der Steigerung von Wirkungsgraden hat dazu gef\u00fchrt, dass Solarstrom schon heute in sonnenreichen L\u00e4ndern wettbewerbsf\u00e4hig ist. Dieser Status wird in Deutschland schon in wenigen Jahren erreicht sein. Damit sind wir unserem Unternehmensziel, m\u00f6glichst vielen Menschen auf der Welt Zugang zu sauberer Energie zu schaffen, ein St\u00fcck n\u00e4her gekommen, res\u00fcmiert Sch\u00e4fer.<\/p> <p>Die drei Gesch\u00e4ftsf\u00fchrer der Energiebau Solarstromsysteme, Herr Klaus Leyendecker, Herr Ren\u00e9 M\u00e9dawar und Herr Michael Sch\u00e4fer nehmen am 5.November 2011 im Historischen Rathaus der Stadt Saarbr\u00fccken den Deutschen Solarpreis 2011 entgegen.<\/p> <p>Firmenkontakt<br \/> Energiebau Solarstromsysteme GmbH<br \/> Timo Glatz<br \/> Heinrich-Rohlmann-Str. 17<\/p> <p>50829 K\u00f6ln<br \/> &#8211;<\/p> <p>E-Mail: presse@energiebau.de<br \/> Homepage: www.energiebau.de\/presse<br \/> Telefon: +49 221 98966 1530<\/p> <p>Pressekontakt<br \/> Energiebau Solarstromsysteme GmbH<br \/> Timo Glatz<br \/> Heinrich-Rohlmann-Str. 17<\/p> <p>50829 K\u00f6ln<br \/> &#8211;<\/p> <p>E-Mail: presse@energiebau.de<br \/> Homepage:<br \/> Telefon: +49 221 98966 1530<\/p>","protected":false},"excerpt":{"rendered":"<p>(ddp direct)Die Energiebau Solarstromsysteme GmbH aus K\u00f6ln erh\u00e4lt als Pionier der Photovoltaik-Branche in diesem Jahr den renommierten Deutschen Solarpreis 2011 in der Kategorie Industrielle, kommerzielle oder landwirtschaftliche Betriebe\/Unternehmen. Verliehen wird der Preis seit 1994 durch die Europ\u00e4ische Vereinigung f\u00fcr erneuerbare Energien e.V. (Eurosolar) an Kommunen, Unternehmen, Medien und engagierte Initiativen, die sich um die Nutzung<\/p>\n","protected":false},"author":291,"featured_media":197886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-33135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernahrung-umwelt-natur"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=33135"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33135\/revisions"}],"predecessor-version":[{"id":269392,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33135\/revisions\/269392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197886"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=33135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=33135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=33135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}