{"id":33645,"date":"2011-10-26T14:34:57","date_gmt":"2011-10-26T13:34:57","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=33645"},"modified":"2012-05-18T10:19:58","modified_gmt":"2012-05-18T09:19:58","slug":"presseinformation-zu-weihnachten-im-schuhkarton-kindern-in-not-mit-weihnachten-im-schuhkarton-freude-und-hoffnung-schenken","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/presseinformation-zu-weihnachten-im-schuhkarton-kindern-in-not-mit-weihnachten-im-schuhkarton-freude-und-hoffnung-schenken-1033645\/","title":{"rendered":"Ein kleiner Schuh kann kann unendlich viel bewegen"},"content":{"rendered":"<p>(ddp direct)Mitmachen ist simpel: Einfach einen Schuhkarton mit Geschenkpapier bekleben, ihn mit Geschenken f\u00fcr einen Jungen oder ein M\u00e4dchen der Altersklasse 2-4, 5-9 oder 10-14 f\u00fcllen und zusammen mit einer kleinen Spende zu einer der bundesweit 4.400 Abgabestellen bringen. Diese sind unter www.geschenke-der-hoffnung.org ver\u00f6ffentlicht.<\/p> <p>Die Freude der beschenkten Kinder \u00fcber diese P\u00e4ckchen hallt lange nach, sowohl emotional als auch ganz praktisch: <!--more-->Sie finden darin Schulhefte, warme Kleidung, ein Kuscheltier und vieles mehr. Was f\u00fcr uns ganz normale Alltagsgegenst\u00e4nde sind, ist f\u00fcr viele Familien in den Empf\u00e4ngerl\u00e4ndern in \u00fcberwiegend Osteuropa von unsch\u00e4tzbarem Wert. Deshalb wird die Geschenk-Aktion auch oft mit den Care- oder Westpaketen verglichen, an deren positive Auswirkung viele Empf\u00e4nger sich noch Jahre und Jahrzehnte sp\u00e4ter erinnern.<\/p> <p>Zusammenarbeit mit Kirchengemeinden<\/p> <p>Neben zahlreichen Privatpersonen, Schulen und Unternehmen unterst\u00fctzen in Deutschland viele evangelische, katholische und freikirchliche Kirchengemeinden als ehrenamtliche Sammelstellen die Aktion. Auch in den Empf\u00e4ngerl\u00e4ndern sind christliche Gemeinden verschiedener Konfessionen Partner von Geschenke der Hoffnung e.V. Ihr Anliegen und ihre Aufgabe ist es, die Schuhkartons dort zu verteilen, wo die Not am gr\u00f6\u00dften ist. Das geschieht immer wieder in Zusammenarbeit mit \u00f6rtlichen Schulen und Sozial\u00e4mtern. Oft betten sie die Weitergabe der P\u00e4ckchen in ein weihnachtliches Rahmenprogramm ein und bieten zus\u00e4tzlich zum Schuhkarton-Geschenk ein Heft mit Bibelgeschichten in der Landessprache an. Sollte eine Weihnachtsfeier und das Angebot des Heftchens nicht in den religi\u00f6sen oder kulturellen Kontext passen insbesondere in muslimischen L\u00e4ndern sehen die \u00f6rtlichen Verteiler davon ab. Die Geschenke gibt es in jedem Fall und ohne jede Bedingung.<\/p> <p>F\u00fcr Gemeinden sind die Verteilungen eine gute Gelegenheit, mit Kindern und ihren Eltern ins Gespr\u00e4ch zu kommen. Welche Kontakte daraus entstehen, liegt in der Eigenverantwortlichkeit der Gemeinden und der Entscheidungsfreiheit der Eltern und Kinder vor Ort. Somit beg\u00fcnstigt und unterst\u00fctzt Weihnachten im Schuhkarton die Arbeit vieler Kirchengemeinden und andere lokale oder regionale Initiativen.<\/p> <p>Prominente Stimmen zur Aktion<\/p> <p>Dr. Ursula von der Leyen, Bundesministerin f\u00fcr Arbeit und Soziales, unterst\u00fctzt Weihnachten im Schuhkarton: Ein kleiner Schuhkann kann unendlich viel bewegen. Denn wenn er reich gef\u00fcllt in den H\u00e4nden eines Kindes liegt, dann wird dieser Schuhkarton zur Schatzkiste. Mit Weihnachten im Schuhkarton gibt es eine einfache und praktische M\u00f6glichkeit, Hilfe zu leisten, die wirklich ankommt. Ein einfacher Karton kann diesen Kindern unermessliche Freude bereiten und ist zugleich ein Zeichen der Hoffnung. Denn oft sind es schon solch kleine Gesten, die Mut machen.<\/p> <p>Auch Dr. Roland Werner, Generalsekret\u00e4r des CVJM-Gesamtverbandes Deutschland, findet die Aktion gut, weil hier Kindern ganz praktisch die Liebe Gottes gezeigt wird und dass Menschen in anderen L\u00e4ndern an sie denken! Das ist in der heutigen Zeit von unsch\u00e4tzbarem Wert.<\/p> <p>Eine weltweite Aktion<\/p> <p>Weihnachten im Schuhkarton ist Teil der weltweiten Aktion Operation Christmas Child der internationalen Hilfsorganisation Samaritans Purse. 2010 packten Menschen in acht L\u00e4ndern \u00fcber acht Millionen Schuhkartons, die in 115 L\u00e4ndern verteilt wurden.<\/p> <p>Mit Samaritans Purse verbindet Geschenke der Hoffnung e.V. eine langj\u00e4hrige gute Partnerschaft. Die Grundpfeiler ihrer Arbeit decken sich: Hilfe ohne jede Bedingung. Die Hilfeleistungen geschehen immer unter gro\u00dfem Respekt der betroffenen Menschen und mit R\u00fccksichtnahme auf die kulturellen Gegebenheiten und religi\u00f6sen \u00dcberzeugungen vor Ort.<\/p> <p>F\u00fcr die Verteilungen der Geschenk-P\u00e4ckchen wurde zwischen Samaritans Purse und Geschenke der Hoffnung e.V. eine Vereinbarung unterzeichnet, die Abstimmungen in der Zusammenarbeit vorsieht und auch Grunds\u00e4tze zum Ablauf von Schuhkarton-Verteilungen definiert: Diese m\u00fcssen in Liebe, W\u00fcrde, Integrit\u00e4t und ohne Vorteilsnahme an den \u00c4rmsten der Armen erfolgen und die christliche Botschaft darf nicht manipulativ eingesetzt werden.<\/p> <p>Als christliches Hilfswerk bekennt sich Geschenke der Hoffnung e.V. dazu, vom Glauben zu reden. Dies geschieht jedoch vor dem Hintergrund einer Selbstverpflichtung, die jede Form von Zwang, Manipulation oder Ausn\u00fctzung einer Notlage ablehnt. Gleichzeitig bekennt sich das Werk zu dem am 29.06.2011 gemeinsam vom \u00d6kumenischen Rat der Kirchen, der Weltweiten Evangelischen Allianz und dem P\u00e4pstlichen Rat f\u00fcr Interreligi\u00f6sen Dialog ver\u00f6ffentlichten Verhaltenskodex f\u00fcr &#8222;Das christliche Zeugnis in einer multireligi\u00f6sen Welt&#8220;.<\/p> <p>Weitere, unabh\u00e4ngige Hintergrundinformation bietet Wikipedia:<br \/> http:\/\/de.wikipedia.org\/wiki\/Geschenke_der_Hoffnung<\/p> <p>Firmenkontakt<br \/> Geschenke der Hoffnung e.V.<br \/> Anja Wetzel<br \/> Haynauer Str. a 72<\/p> <p>12249 Berlin<br \/> Deutschland<\/p> <p>E-Mail: a.wetzel@geschenke-der-hoffnung.org<br \/> Homepage: www.geschenke-der-hoffnung.org<br \/> Telefon: 030-76883300<\/p> <p>Pressekontakt<br \/> Geschenke der Hoffnung e.V.<br \/> Anja Wetzel<br \/> Haynauer Str. a 72<\/p> <p>12249 Berlin<br \/> Deutschland<\/p> <p>E-Mail: a.wetzel@geschenke-der-hoffnung.org<br \/> Homepage:<br \/> Telefon: 030-76883300<\/p>","protected":false},"excerpt":{"rendered":"<p>(ddp direct)Mitmachen ist simpel: Einfach einen Schuhkarton mit Geschenkpapier bekleben, ihn mit Geschenken f\u00fcr einen Jungen oder ein M\u00e4dchen der Altersklasse 2-4, 5-9 oder 10-14 f\u00fcllen und zusammen mit einer kleinen Spende zu einer der bundesweit 4.400 Abgabestellen bringen. Diese sind unter www.geschenke-der-hoffnung.org ver\u00f6ffentlicht. Die Freude der beschenkten Kinder \u00fcber diese P\u00e4ckchen hallt lange nach,<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-33645","post","type-post","status-publish","format-standard","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=33645"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33645\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=33645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=33645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=33645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}