{"id":33911,"date":"2011-10-28T14:10:34","date_gmt":"2011-10-28T13:10:34","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=33911"},"modified":"2023-06-09T12:27:17","modified_gmt":"2023-06-09T11:27:17","slug":"liquidation-des-degi-international-anleger-sollten-jetzt-reagieren","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/liquidation-des-degi-international-anleger-sollten-jetzt-reagieren-1033911\/","title":{"rendered":"Liquidation des Degi International &#8211; Zeitnah eine Rechtsanwaltskanzlei aufsuchen"},"content":{"rendered":"<p>Der Degi International hat es nicht geschafft, w\u00e4hrend seiner Schlie\u00dfung seit November 2009 ausreichend Kapital zu beschaffen, um alle zu erwartenden R\u00fcckgabew\u00fcnsche seiner Anleger bei erneuter \u00d6ffnung erf\u00fcllen zu k\u00f6nnen. Folge der unzureichenden Liquidit\u00e4t ist die Abwicklung des Fonds. Die Liquidation des Degi International soll bis zum 15. Oktober 2014 andauern. Ab April 2012 sollen halbj\u00e4hrliche Auszahlungstranchen an die Anleger erfolgen.<\/p> <p>Trotz dieser geplanten Auszahlungen sind Verluste f\u00fcr die Anleger zu erwarten. Insbesondere die Anleger, die ihre Ersparnisse in den Fonds investiert und hiermit eine sinnvolle Altersvorsorge treffen wollten, k\u00f6nnen und wollen aber keine Verluste hinnehmen. Sie f\u00fchlen sich schlecht beraten.<\/p> <p><!--more-->GRP Rainer Rechtsanw\u00e4lte Steuerberater, K\u00f6ln, Berlin, Bonn, D\u00fcsseldorf, Hamburg, M\u00fcnchen www.grprainer.com r\u00e4t Betroffenen in dieser Situation: Gesch\u00e4digte Anleger sollten jetzt nicht tatenlos zusehen. Sinnvoll ist es, sich an einen Rechtsanwalt zu wenden, um etwaige Schadensersatzanspr\u00fcche gegen die Bank, die den Fonds vermittelt hat, pr\u00fcfen zu lassen.<\/p> <p>Aufgrund unserer Erfahrung mit einer Vielzahl von Mandaten zum Degi International k\u00f6nnen wir sagen, dass die Banken den Degi International oftmals als sehr sicher angepriesen, aber dabei den Anleger \u00fcber die Risiken des Fonds &#8211; wie das Schlie\u00dfungs- und Verlustrisiko &#8211; nicht aufgekl\u00e4rt haben. Hierin kann eine Falschberatung liegen, die zum Schadensersatzanspruch des Anlegers f\u00fchrt, denn die Bank ist gegen\u00fcber dem Anleger zur ordnungsgem\u00e4\u00dfen Aufkl\u00e4rung verpflichtet.<\/p> <p>Ein weiterer Ansatzpunkt f\u00fcr einen Schadensersatzanspruch des Anlegers kann darin liegen, dass die Bank R\u00fcckverg\u00fctungen, die sie f\u00fcr die Vermittlung des Fonds erhielt (sog. Kick-Backs), verschwiegen hat, obwohl eine diesbez\u00fcgliche Aufkl\u00e4rungspflicht gegen\u00fcber dem Anleger bestand. Auch hierdurch kann nach Rechtsprechung des Bundesgerichtshofs ein Schadensersatzanspruch ausgel\u00f6st werden.<\/p> <p>Besteht ein diesbez\u00fcglicher Anspruch des Anlegers, hat dieser die M\u00f6glichkeit, doch noch schadlos aus seiner Fondsbeteiligung herauszukommen. Es ist vor diesem Hintergrund ratsam, etwaige Anspr\u00fcche von einem mit dem Bank- und Kapitalmarktrecht vertrauten Anwalt pr\u00fcfen zu lassen.<\/p> <p>Da Schadensersatzanspr\u00fcche der Verj\u00e4hrung unterliegen, sollten Anleger nicht z\u00f6gern, sondern zeitnah eine Rechtsanwaltskanzlei aufsuchen. Denn tritt Verj\u00e4hrung ein, sind tats\u00e4chlich bestehende Anspr\u00fcche nicht mehr durchsetzbar, sobald sich der Gegner hierauf beruft.<\/p> <p>http:\/\/www.grprainer.com\/Degi-International.html<\/p> <p>FirmenkontaktGRP Rainer Rechtsanw\u00e4lte Steuerberater<br \/> G\u00fcrzenich-Quartier<br \/> Augustinerstra\u00dfe 10<br \/> 50667 K\u00f6ln<br \/> Tel.: +49 221-27 22 75-0<br \/> Fax: +49 221-27 22 75-24<br \/> <a class=\"moz-txt-link-abbreviated\" href=\"mailto:koeln@grprainer.com\">koeln@grprainer.com<\/a><\/p> <p>http:\/\/www.grprainer.com\/kanzlei\/standorte\/koeln.html<\/p> <p>&nbsp;<\/p> <p>Informieren Sie sich weiter \u00fcber Fachzeitschriften aus dem Bereich <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/www.fachzeitungen.de\/seite\/p\/kat\/katid\/43\" title=\"Fachzeitschriften zum Thema Recht\" >Recht-Wirtschaft-Steuerberatung<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Der Degi International hat es nicht geschafft, w\u00e4hrend seiner Schlie\u00dfung seit November 2009 ausreichend Kapital zu beschaffen, um alle zu erwartenden R\u00fcckgabew\u00fcnsche seiner Anleger bei erneuter \u00d6ffnung erf\u00fcllen zu k\u00f6nnen. Folge der unzureichenden Liquidit\u00e4t ist die Abwicklung des Fonds. Die Liquidation des Degi International soll bis zum 15. Oktober 2014 andauern. Ab April 2012 sollen<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-33911","post","type-post","status-publish","format-standard","hentry","category-recht-wirtschaft-steuerberatung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=33911"}],"version-history":[{"count":3,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33911\/revisions"}],"predecessor-version":[{"id":275357,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/33911\/revisions\/275357"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=33911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=33911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=33911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}