{"id":36773,"date":"2011-11-23T15:35:58","date_gmt":"2011-11-23T14:35:58","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=36773"},"modified":"2014-04-02T14:49:58","modified_gmt":"2014-04-02T13:49:58","slug":"saturn-ipad-app-kundenmagazin","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/saturn-ipad-app-kundenmagazin-1036773\/","title":{"rendered":"Verbindung von Print und Digital"},"content":{"rendered":"<p>Mit seinem crossmedial angelegten Kundenmagazin &#8222;TURN ON&#8220; will Saturn seine Technikkompetenz unterstreichen und sich als Ratgeber in Lifestylefragen positionieren. Entwicklung und Umsetzung von &#8222;TURN ON&#8220; haben die BTD Newmedia gemeinsam mit BurdaYukom Publishing \u00fcbernommen. Die Corporate-Publishing-Tochter des Burda-Konzerns verantwortet dabei die Printversion des Magazins, der Fullservice-Internetdienstleister der BTD Gruppe deren Verl\u00e4ngerung in die Online- und Mobile-Welt. <!--more-->Damit beweist die BTD, urspr\u00fcnglich aus dem Sport-Bereich kommend, einmal mehr ihr K\u00f6nnen im Aufbau von medien\u00fcbergreifenden L\u00f6sungen auch in anderen Segmenten.<\/p> <p>Der Anspruch an die iPad-App zu &#8222;TURN ON&#8220; ist, die Inhalte des Printmagazins nicht einfach mobil wiederzugeben, sondern eine exklusive Auswahl daraus channelgerecht und intelligent weiterzudrehen. &#8222;Wir bieten den Usern mit der iPad-App echten Mehrwert&#8220;, so Stefan Leibhard, gesch\u00e4ftsf\u00fchrender Gesellschafter der BTD Gruppe. &#8222;Diese k\u00f6nnen den zus\u00e4tzlichen multimedialen Content \u00fcber interaktive Elemente und Features f\u00fcr sich entdecken sowie haptisch und audiovisuell erleben.&#8220;<\/p> <p>Eine direkte Verbindung zwischen App und Online-Version stellen aktive Links her. Die Verkn\u00fcpfung zwischen Offline- und Online-Channel bieten die QR-Codes im Printmagazin. Eine Weiterentwicklung und ein Ausbau der Verbindung von Print und Digital sind f\u00fcr 2012 geplant.<\/p> <p>Firmenkontakt<br \/> BTD Newmedia GmbH<br \/> Alexandra Zebos<br \/> Goehtestr. 34<\/p> <p>80336 M\u00fcnchen<br \/> Deutschland<\/p> <p>E-Mail: Alexandra.Zebos@btd.de<br \/> Homepage: http:\/\/www.btd.de<br \/> Telefon: +49 (89)660291 0<\/p> <p>Pressekontakt<br \/> BTD Newmedia GmbH<br \/> Alexandra Zebos<br \/> Goehtestr. 34<\/p> <p>80336 M\u00fcnchen<br \/> Deutschland<\/p> <p>E-Mail: Alexandra.Zebos@btd.de<br \/> Homepage: http:\/\/www.btd.de<br \/> Telefon: +49 (89)660291 0<\/p>","protected":false},"excerpt":{"rendered":"<p>Mit seinem crossmedial angelegten Kundenmagazin &#8222;TURN ON&#8220; will Saturn seine Technikkompetenz unterstreichen und sich als Ratgeber in Lifestylefragen positionieren. Entwicklung und Umsetzung von &#8222;TURN ON&#8220; haben die BTD Newmedia gemeinsam mit BurdaYukom Publishing \u00fcbernommen. Die Corporate-Publishing-Tochter des Burda-Konzerns verantwortet dabei die Printversion des Magazins, der Fullservice-Internetdienstleister der BTD Gruppe deren Verl\u00e4ngerung in die Online- und<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-36773","post","type-post","status-publish","format-standard","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/36773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=36773"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/36773\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=36773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=36773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=36773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}