{"id":3693,"date":"2010-02-04T16:00:45","date_gmt":"2010-02-04T15:00:45","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=3693"},"modified":"2011-03-18T12:03:12","modified_gmt":"2011-03-18T11:03:12","slug":"der-gewerbe-und-hotelmakler-atrium-vermittelte-moebel-walther-ag-erwirbt-logistikhallemoebelhalle-bei-frankfurt-hahn","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/der-gewerbe-und-hotelmakler-atrium-vermittelte-moebel-walther-ag-erwirbt-logistikhallemoebelhalle-bei-frankfurt-hahn-103693\/","title":{"rendered":"Der Gewerbe- und Hotelmakler"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-3696\" title=\"3-3887Halle-weit.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/3693\/3-3887Halle-weit-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Nach erfolgreicher Vermittlung durch die ATRIUM  GmbH \u2013 Gewerbe- und Hotelmakler M&amp;A \u2013 mit Sitz in Rohr bei N\u00fcrnberg, \u00fcbernimmt die M\u00f6bel Walther AG f\u00fcr ihre SB Vertriebsschiene Sconto zu Jahresbeginn ein ehemaliges M\u00f6belzentrum bei Frankfurt-Hahn. <!--more-->Die Gewerbeanwesen wird nach einem vollst\u00e4ndigen Umbau neu er\u00f6ffnet.<br \/> Die ATRIUM GmbH entwickelte im Auftrag der Eigent\u00fcmer eine Verkaufsstrategie und \u00fcbernahm die Suche sowie die Verhandlungen mit neuen Investoren, die am Erwerb und der Neuprojektierung des Areals mit einer Gesamtfl\u00e4che von ca. 20.000 m\u00b2 interessiert waren. Das M\u00f6belzentrum kann nun von der bekannten M\u00f6bel-Einzelhandels Aktiengesellschaft als  Mitnahmem\u00f6belmarkt weitergef\u00fchrt werden.<br \/> Die ATRIUM GmbH ist seit \u00fcber 20 Jahren als Gewerbe- und Hotelmakler mit Sitz im Gro\u00dfraum N\u00fcrnberg \u00fcberregional t\u00e4tig. Der Schwerpunkt liegt in der Vermittlung von Hotel- und Gewerbeimmobilien, insbesondere auch aus der Verwertung von Banken und f\u00fcr Insolvenzverwalter. ATRIUM bietet das gesamte Spektrum an Immobiliendienstleistungen und bietet mit seinen Mitarbeitern professionelle Beratung in allen immobilienspezifischen Fragestellungen. Weitere Informationen finden Sie unter http:\/\/www.atrium2000.de<\/p> <p>Impressum\/Kontaktinformationen f\u00fcr die Presse:<\/p> <p>Rohr, 04.02.2010 \u2013<\/p> <p>Gesch\u00e4ftsleitung der<br \/> ATRIUM Projektbau GmbH<br \/> Gewerbe- und Hotelmakler M&amp;A<br \/> Business Real Estate Consultant<br \/> Waldstr. 22<br \/> D-91189 Rohr b. N\u00fcrnberg<br \/> Tel. +49 (0) 9122-79490<br \/> Fax +49 (0) 9122-794919<br \/> E-Mail: info@atrium2000.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.atrium2000.de\"  >www.atrium2000.de<\/a><\/p> <p>Gesch\u00e4ftsf\u00fchrung: Doris Hofbauer<br \/> HRB N\u00fcrnberg 12409<br \/> Wir fangen da an, wo andere aufh\u00f6ren!<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Nach erfolgreicher Vermittlung durch die ATRIUM GmbH \u2013 Gewerbe- und Hotelmakler M&amp;A \u2013 mit Sitz in Rohr bei N\u00fcrnberg, \u00fcbernimmt die M\u00f6bel Walther AG f\u00fcr ihre SB Vertriebsschiene Sconto zu Jahresbeginn ein ehemaliges M\u00f6belzentrum bei Frankfurt-Hahn.<\/p>\n","protected":false},"author":291,"featured_media":198958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bau-mieter-immobilien"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/3693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=3693"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/3693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198958"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=3693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=3693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=3693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}