{"id":38650,"date":"2011-12-08T15:48:16","date_gmt":"2011-12-08T14:48:16","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=38650"},"modified":"2025-03-28T11:59:36","modified_gmt":"2025-03-28T10:59:36","slug":"brandenburg-feiert-den-alten-fritz","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/brandenburg-feiert-den-alten-fritz-1038650\/","title":{"rendered":"Nicht nur Ausstellungen lenken den Blick auf den Preu\u00dfenk\u00f6nig"},"content":{"rendered":"<p>(ddp direct)Am 24. Januar 2012 j\u00e4hrt sich der Geburtstag Friedrichs des Gro\u00dfen zum 300. Mal. Anl\u00e4sslich dieses Jubil\u00e4ums gibt es in Brandenburg eine Vielzahl ganz unterschiedlicher Veranstaltungen, die Spurensuche und k\u00fcnstlerische Besch\u00e4ftigung zugleich sind.<\/p> <p>Den Anfang macht die Landeshauptstadt Potsdam vom 12. bis 24. Januar 2012 mit einem Fest f\u00fcr Friedrich. Der H\u00f6hepunkt wird ein \u00f6ffentliches Geburtstagsfest am 24. Januar sein, das gleichzeitig den Auftakt f\u00fcr das Themenjahr Kulturland Brandenburg 2012 &#8222;KOMMT ZUR VERNUNFT! Friedrich der Zweite von Preuszen&#8220; darstellt. <!--more-->Im Rahmen der Festwoche sind zahlreiche Veranstaltungen wie Ausstellungen, Theater- und Opernauff\u00fchrungen, Lesungen, Kabarett sowie Projekte bildender K\u00fcnstler geplant.<\/p> <p>Die zentrale Ausstellung zum Geburtstag pr\u00e4sentiert die Stiftung Preu\u00dfische Schl\u00f6sser und G\u00e4rten Berlin-Brandenburg (SPSG) vom 28. April bis zum 28. Oktober 2012 unter dem Motto Friederisiko im Neuen Palais im Park Sanssouci. Die gro\u00dfe Schau in 70 teilweise erstmals zug\u00e4nglichen und aufwendig restaurierten S\u00e4len auf insgesamt 6.000 Quadratmetern des Neuen Palais widmet sich der Person des K\u00f6nigs und stellt so viele Bez\u00fcge zur Zeit, Gesellschaft und Politik her (www.friederisiko.de). Weitere Ausstellungen mit ganz unterschiedlichen Schwerpunkten gibt es zum Beispiel in Potsdam im Filmmuseum, im neu er\u00f6ffneten Potsdam-Museum am Alten Markt, im Haus der Brandenburgisch-Preu\u00dfischen Geschichte sowie in Rheinsberg, in Neuruppin, in Heiligengrabe, in Bad Freienwalde und in Cottbus.<\/p> <p>Doch nicht nur Ausstellungen lenken den Blick auf den Preu\u00dfenk\u00f6nig. Die Genres im Friedrich-Jahr sind vielf\u00e4ltig: ein Musical und eine Filmshow in Potsdam, ein musikalisch-kom\u00f6diantisches Programm der Uckerm\u00e4rkischen B\u00fchnen in Schwedt, eine Oper in Rheinsberg, Schauspiele in Potsdam und Wustrau sowie eine barocke Reitinszenierung mit den Pferden der F\u00fcrstlichen Hofreitschule B\u00fcckeburg vor der Kulisse des Neuen Palais. Vieles davon wird als Urauff\u00fchrung erstmalig zu sehen sein.<\/p> <p>Als K\u00f6nig von Preu\u00dfen pr\u00e4gte Friedrich der Gro\u00dfe die Geschichte Europas im 18. Jahrhundert. Mit seinem Namen verbinden sich gravierende wirtschaftliche, politische und gesellschaftliche Transformationsprozesse in Brandenburg-Preu\u00dfen, die das zeitgen\u00f6ssische Umfeld im europ\u00e4ischen Ma\u00dfstab tief greifend gepr\u00e4gt haben. Dar\u00fcber hinaus hat sein Wirken als Staatsmann, Philosoph und K\u00fcnstler die europ\u00e4ische Geistesgeschichte nicht allein seines Jahrhunderts wesentlich mitbestimmt, sondern reicht bis in die Gegenwart.<\/p> <p>Informationen zu den Veranstaltungen gibt es bereits jetzt im Internet unter www.preussisches-arkadien.de sowie unter wwww.friedrich300.de.<\/p> <p>Eine Presseinformation mit der aktuellen \u00dcbersicht \u00fcber die Veranstaltungen senden wir Ihnen gerne zu (Mail an presse@reiseland-brandenburg.de).<\/p> <p>Das Neue Palais im Schlosspark Sanssouci in Potsdam ist vom 28. April bis zum 28. Oktober 2012 Ort der gro\u00dfen Jubil\u00e4umsausstellung &#8222;Friederisiko&#8220; zum 300. Geburtstag Friedrich des Gro\u00dfen. In ganz Brandenburg wird der Geburtstag ab Januar 2012 mit einem umfangreichen Veranstaltungsprogramm gefeiert (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.preussisches-arkadien.de\" title=\"2012 steht ganz im Zeichen des 300. Geburtstags Friedrichs des Gro\u00dfen\" >www.preussisches-arkadien.de<\/a>).<\/p> <p>Firmenkontakt<br \/> TMB Tourismus-Marketing Brandenburg GmbH<br \/> Birgit Kunkel<br \/> Am Neuen Markt 1<\/p> <p>D-14467 Potsdam<br \/> &#8211;<\/p> <p>E-Mail: kunkel@reiseland-brandenburg.de<br \/> Homepage: http:\/\/www.reiseland-brandenburg.de<br \/> Telefon: +49(0)331-29873-24<\/p> <p>Pressekontakt<br \/> TMB Tourismus-Marketing Brandenburg GmbH<br \/> Birgit Kunkel<br \/> Am Neuen Markt 1<\/p> <p>D-14467 Potsdam<br \/> &#8211;<\/p> <p>E-Mail: kunkel@reiseland-brandenburg.de<br \/> Homepage: http:\/\/<br \/> Telefon: +49(0)331-29873-24<\/p>","protected":false},"excerpt":{"rendered":"<p>(ddp direct)Am 24. Januar 2012 j\u00e4hrt sich der Geburtstag Friedrichs des Gro\u00dfen zum 300. Mal. Anl\u00e4sslich dieses Jubil\u00e4ums gibt es in Brandenburg eine Vielzahl ganz unterschiedlicher Veranstaltungen, die Spurensuche und k\u00fcnstlerische Besch\u00e4ftigung zugleich sind. Den Anfang macht die Landeshauptstadt Potsdam vom 12. bis 24. Januar 2012 mit einem Fest f\u00fcr Friedrich. Der H\u00f6hepunkt wird ein<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8804],"tags":[],"class_list":["post-38650","post","type-post","status-publish","format-standard","hentry","category-reisen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/38650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=38650"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/38650\/revisions"}],"predecessor-version":[{"id":277068,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/38650\/revisions\/277068"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=38650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=38650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=38650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}