{"id":388,"date":"2008-06-24T21:56:06","date_gmt":"2008-06-24T20:56:06","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/68-und-papierne-revolutionen-10388\/"},"modified":"2025-03-21T11:59:10","modified_gmt":"2025-03-21T10:59:10","slug":"68-und-papierne-revolutionen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/68-und-papierne-revolutionen-10388\/","title":{"rendered":"68 UND PAPIERNE REVOLUTIONEN"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.archplus.net\/\"  ><\/a><\/td> <\/tr> <\/tbody> <\/table> <p><strong>Steckt dahinter ein kluger Kopf? Screenshot der Aspekte-Sendung auf ZDF.de<\/strong><\/p> <p>ARCH+ und Pro qm laden ein zur Heftvorstellung und Autorenlesung<br \/> Datum: Freitag, 4. Juli 2008, 20:30 Uhr<\/p> <p>Ort: Buchandlung Pro qm, Almstadtstra\u00dfe 48-50, 10119<\/p> <p>Berlin<\/p> <p><strong><\/strong><br \/> Anl\u00e4\u00dflich des 40-j\u00e4hrigen Jubil\u00e4ums von ARCH+ findet in diesem Jahr eine Reihe von Veranstaltungen statt, die das Medium Zeitschrift begleitet und zur Diskussion einl\u00e4dt. Zum Auftakt wird Thilo Hilpert seine provokanten Thesen vom \u201eLand ohne Avantgarde\u201c, die in der aktuellen Ausgabe ARCH+ 186\/187 \u201eDie radikale Architektur der kleinen Zeitschriften\u201c erschienen sind, vorstellen:<!--more--><\/p> <p>\u201eZwei B\u00fccher, die in diesem Februar ausgiebig in der Presse besprochen worden sind, formulieren widerstreitende Positionen zur Rolle des Jahres 1968 f\u00fcr die Kultur des Nachkriegsdeutschlands, die auch bedeutsam sind f\u00fcr die Beurteilung der Nachkriegsarchitektur in ihrem Verh\u00e4ltnis zur Moderne. Dabei handelt es sich um \u201eRebellion und Wahn\u201c von Peter Schneider und \u201eUnser Kampf. 1968\u201c von G\u00f6tz Aly. Pauschalisiert l\u00e4sst sich sagen, dass Peter Schneider einer inzwischen verbreiteten, eher positiven Betrachtungsweise folgt, die diese Jahre als l\u00e4ngst \u00fcberf\u00e4lligen Bruch mit einem verschleppten Konservativismus sieht, der sich eine Kontinuit\u00e4t zur Nazizeit nicht mehr eingestehen wollte. Dagegen sieht G\u00f6tz Aly die Rolle dieses Kulturbruchs eher \u00fcberbewertet, weil Modernisierung schon zuvor begonnen habe unter dem Schutz eines \u201eHeilschlafs\u201c, in den eine \u00fcberdrehte Generation versetzt worden war. Aber Skepsis ist angebracht angesichts der Ungenauigkeiten seiner Aussagen. Denn die Art des radikalen Erwachens aus dem \u201eHeilschlaf\u201c der 50er und 60er Jahre traf vor allem die niedergehaltenen Z\u00f6glinge der Heilanstalten selbst, die ohne brauchbare Traditionen dastanden, die alles neu lernen mussten wie den aufrechten Gang in den K\u00fcnsten.\u201c<\/p> <p>Text von Thilo Hilpert als PDF-Download<br \/> Wir w\u00fcrden uns \u00fcber Ihr Kommen freuen.<\/p> <p>http:\/\/www.pro-qm.de<\/p> <p>Arch+ widmet sich seit vier Jahrzehnten dem Experiment in Architektur und St\u00e4dtebau. Angesiedelt zwischen Architektur, Stadt, Kultur und Medien lotet Arch+ viertelj\u00e4hrlich die Grenzen der sich wandelnden Disziplinen in Theorie und Praxis mit intellektueller Neugier aus. Als unabh\u00e4ngige, konzeptuelle Zeitschrift ist Arch+ einzigartig und dient als ein Forum der Auseinandersetzung.<\/p> <p>Arch+ is Germany\u2019s leading periodical for discourses in architecture, urbanism and related fields. Over the last four decades Arch+ is dedicated to the cultural and political setting of architecture and urbanism. Arch+ examines quarterly the fluid borders of the changing disciplines with an indepth, mono-thematic collection of contributions both in theory and practice. As an independent and conceptual magazine Arch+ serves as a forum for contemporary discourses.<\/p> <p>Arch+ was part of documenta 12 magazines \u2013 a collective editorial project linking over 90 periodicals engaged in contemporary cultural discourse worldwide.<\/p> <p>ARCH+<br \/> Zeitschrift f\u00fcr Architektur und St\u00e4dtebau<\/p> <p>Home\u00a0 Kontakt\u00a0 Bestellung\u00a0\u00a0 Newsletter<\/p> <p>Redaktion Berlin:<br \/> Bergengruenstr. 35<br \/> 14129 Berlin<\/p> <p>Redaktion Aachen:<br \/> Charlottenstr. 14<br \/> 60070 Aachen<\/p>","protected":false},"excerpt":{"rendered":"<p>Steckt dahinter ein kluger Kopf? Screenshot der Aspekte-Sendung auf ZDF.de ARCH+ und Pro qm laden ein zur Heftvorstellung und Autorenlesung Datum: Freitag, 4. Juli 2008, 20:30 Uhr Ort: Buchandlung Pro qm, Almstadtstra\u00dfe 48-50, 10119 Berlin Anl\u00e4\u00dflich des 40-j\u00e4hrigen Jubil\u00e4ums von ARCH+ findet in diesem Jahr eine Reihe von Veranstaltungen statt, die das Medium Zeitschrift begleitet<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-388","post","type-post","status-publish","format-standard","hentry","category-kunst-kultur-literatur-theater"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=388"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/388\/revisions"}],"predecessor-version":[{"id":276772,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/388\/revisions\/276772"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}