{"id":398,"date":"2008-06-26T09:16:23","date_gmt":"2008-06-26T08:16:23","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/prominente-geben-erntedank-anstose-%e2%80%9edamit-es-fur-alle-reicht%e2%80%9c-10398\/"},"modified":"2010-07-28T13:13:25","modified_gmt":"2010-07-28T12:13:25","slug":"prominente-geben-erntedank-anstoesse-damit-es-fuer-alle-reicht","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/prominente-geben-erntedank-anstoesse-damit-es-fuer-alle-reicht-10398\/","title":{"rendered":"Prominente geben Erntedank-Anst\u00f6\u00dfe, \u201edamit es f\u00fcr alle reicht\u201c"},"content":{"rendered":"<p><strong>Arbeitshilfe zum Erntedank 2008<\/strong>: Loben und mit-teilen<br \/> Prominente geben Erntedank-Anst\u00f6\u00dfe, \u201edamit es f\u00fcr alle reicht\u201c<\/p> <p>Altenkirchen. \u201eEin Erntedankfest, bei dem die Menschen sp\u00fcren: Die Kirchengemeinde kann gut feiern, sie ist informiert und setzt durch Mit-teilen Zeichen in den Lebensstil-Fragen der Gegenwart\u201c \u2013 das ist nach den Worten von Pfarrer Werner-Christian Jung, verantwortlicher Redakteur der Zeitschrift \u201eKirche im l\u00e4ndlichen Raum\u201c, das Ziel der speziellen Ausgabe zur Vorbereitung auf das Erntedankfest 2008. <!--more--><\/p> <p>Die Anfang Juli erscheinende 60-seitige Arbeitshilfe des \u201eAusschuss f\u00fcr den Dienst auf dem Land in der Evangelischen Kirche in Deutschland\u201c ist vor allem f\u00fcr die Hand von Landpfarrern und -pfarrerinnen konzipiert.<br \/> Unterst\u00fctzt durch einen bundesweiten Redaktionskreis werden in der neuesten Ausgabe der Quartalsschrift zwei Gottesdienstvorschl\u00e4ge unterbreitet, einer davon f\u00fcr einen Generationen \u00fcbergreifenden Gottesdienst, angereichert um zwei neuere Lieder.<\/p> <p>Ferner enth\u00e4lt die Arbeitshilfe Grunds\u00e4tzliches zum Thema \u201eLoben\u201c aus praktisch-theologischer Perspektive, lautet der Hefttitel doch \u201eLoben und mitteilen\u201c.<\/p> <p>Etliche Prominente kommen unter der Fragestellung \u201eErntedank \u2013 leben, damit es f\u00fcr alle reicht\u201c zu Wort. So sieht der Ministerpr\u00e4sident von Sachsen-Anhalt, Dieter Althaus, gerade die Christen in der Verantwortung: \u201eWir m\u00fcssen den Mut aufbringen, unser Sozialsystem grundlegend zu reformieren.\u201c Er pl\u00e4diert f\u00fcr ein Solidarisches B\u00fcrgergeld. Das er als \u201eein bedingungsloses Grundeinkommen von 800 Euro pro Monat f\u00fcr alle Erwachsenen\u201c ausgestattet wissen will.<br \/> Wetterforscher Gunther Tiersch verdeutlicht, dass wir uns \u201ein den n\u00e4chsten 20 bis 40 Jahren an h\u00e4ufige Wetterextreme gew\u00f6hnen und uns an sie anpassen m\u00fcssen.\u201c Allerdings werden die an den Klimawandel in Mitteleuropa angepassten neuen Getreidesorten \u201enicht mehr \u00fcber den gewohnten Anteil an notwendigen Aminos\u00e4uren verf\u00fcgen. Diese w\u00e4ren aber wichtig f\u00fcr das gesunde Aufwachsen unserer Kinder.\u201c Zuk\u00fcnftige Szenarien, aber auch die heutigen Naturkatastrophen \u201esollten wir uns ab und zu ins Ged\u00e4chtnis rufen, wenn wir n\u00e4chstes mal im Supermarkt einkaufen.\u201c \u00dcber das Staunen lernen werde auch wieder Dankbarkeit entstehen und die Erkenntnis, \u201ewie sensibel die Natur ist, wie bedrohlich der Klimawandel.\u201c<\/p> <p>Carl-Albrecht Bartmer, der Pr\u00e4sident der Deutschen Landwirtschaftsgesellschaft h\u00e4lt Z\u00fcchtungsfortschritte f\u00fcr den einzigen wirklich zukunftsweisenden Weg: \u201eKnappheit bei Nahrungsmitteln ist kein naturgegebenes Faktum, sondern Ausdruck davon, dass wir unsere Potentiale nicht in gebotenem Umfang nutzen, Potentiale unserer Acker- und Gr\u00fcnlandfl\u00e4chen &#8230; dieser Welt, auch die Potentiale unserer K\u00f6pfe.\u201c Er sieht in der \u201eFortschrittsorientierung ein Zeichen f\u00fcr das Verantwortungsbewusstsein des Menschen, das ihm mittels Verstand von Gott gegeben wurde. Daraus ergibt sich auch ein g\u00f6ttlicher Auftrag, diese Verantwortung durch sch\u00f6pferisches Denken wahrzunehmen.\u201c<\/p> <p>\u201eFortschritt als Ausdruck gottgegebener Vernunft\u201c werde allerdings nur dann helfen, wenn er den Nachhaltigkeitskriterien entspreche: \u201eWenn wir den Schutz der Sch\u00f6pfung, Verteilungsgerechtigkeit und effiziente Verfahren f\u00fcr bessere Ernten zugleich verwirklichen, dann werden wir in Zukunft leben k\u00f6nnen mit der Gewissheit, dass es f\u00fcr alle reicht und unsere Herzen sind voll des Erntedanks.\u201c<\/p> <p>Gerd Billen, Vorsitzender des Verbraucherinitiative Bundesverband, meint, dass das \u201ePreisschild, das den Tauschwert der Ware hier in Europa darstellt, in Wahrheit \u00fcber die globalen und nachhaltigen Produktions-, Verarbeitungs- und Vertriebskosten hinweg\u201c t\u00e4usche und folgert: \u201eW\u00fcrden aber die globalen Kosten auf den Preis der Ware umgem\u00fcnzt\u201c, dann w\u00fcrde auch die \u201eVerstrickung des Individuums in die komplexen gesellschaftlichen Widerspr\u00fcche\u201c deutlich. Deshalb fordert er die Kirchen theologisch heraus: \u201eDer evangelische Einspruch gegen diesen Teufelskreis der Schuld hei\u00dft: Rechtfertigung aus Gnade. Das Bewusstsein der eigenen Verstrickung wach zu halten, ohne zu verzweifeln, w\u00fcrde zumindest der subjektiven Verdoppelung jener Schuld\u201c Einhalt gebieten.\u201c Ob es dadurch freilich leichter w\u00fcrde, so zu leben, dass es f\u00fcr alle reicht, ist f\u00fcr den Verbrauchersch\u00fctzer schwer zu sagen. Immerhin erhofft er, dass die Bereitschaft steigt, \u201eden eingefahrenen Erwerbs- und Konsummustern der eigenen Kultur gegen\u00fcber kritischer zu werden.\u201c<\/p> <p>\u201eErnte- und Nahrungswissen erweitern\u201c \u2013 so lautet das Pl\u00e4doyer von Hannelore W\u00f6rz, Pr\u00e4sidentin des LandFrauenverband W\u00fcrttemberg-Baden. Dazu gingen die LandFrauen auch Kooperationen ein, bspw. mit \u201eBrot f\u00fcr die Welt\u201c bei der Kampagne f\u00fcr Ern\u00e4hrungssicherheit \u201eNiemand isst f\u00fcr sich allein\u201c. Dies erweitere und vertiefe den Blick f\u00fcr Zusammenh\u00e4nge zwischen Hunger und Armut, Konsumverhalten und Welthandel\u201c, erm\u00f6gliche<br \/> Verhaltens\u00e4nderungen und st\u00e4rke das Bem\u00fchen um ein gerechteres Wirtschafts- und Handelsmodell.<\/p> <p>Professor Werner Buchner von der Landwirtschaftskammer Nordrhein-Westfalen betrachtet \u201eErntedank im Licht der Sonne\u201c und sieht es als eine agronomische Herausforderung, sich in der Pflanzenz\u00fcchtung st\u00e4rker als bisher der Sonnenkraft als Wachstumsfaktor zuzuwenden.<br \/> Zwei weitere Beitr\u00e4ge beleuchten kritisch die Aussagekraft der gegenw\u00e4rtigen Lebensmittel-Kennzeichnung sowie die Frage darnach, wie viel gentechnisch ver\u00e4nderte Organismen heute auf unseren Tellern landen k\u00f6nnen.<\/p> <p>In \u201eZukunftsf\u00e4higes Deutschland in einer globalisierten Welt\u201c skizziert Kata Gei\u00dfler die im Oktober 2008 erscheinende gleichnamige Studie, die im Auftrag von Brot f\u00fcr die Welt, Evangelischem Entwicklungsdienst und BUND durch das Wuppertal Institut f\u00fcr Klima, Umwelt, Energie erstellt wird.<\/p> <p>Meditation, Meditationsbild, Lieder, Kommentar, Meldungen und Rezensionen runden die \u201eHandreichung zum Erntedank 2008\u201c ab.<\/p> <p>Das 60-seitige Heft kann zum Preis von 3,90 \u20ac zzgl. Versandkosten (Staffelpreise) unter folgender Anschrift bestellt werden:<\/p> <p>Kirche im l\u00e4ndlichen Raum<br \/> c\/o Evangelische Landjugendakademie<br \/> Dieperzbergweg 13-17<br \/> 57610 Altenkirchen<br \/> per E-Mail: kohl@lja.de<br \/> per Telefon: 02681\/9516-0<br \/> per Fax: 02681\/70206<\/p>","protected":false},"excerpt":{"rendered":"<p>Arbeitshilfe zum Erntedank 2008: Loben und mit-teilen Prominente geben Erntedank-Anst\u00f6\u00dfe, \u201edamit es f\u00fcr alle reicht\u201c Altenkirchen. \u201eEin Erntedankfest, bei dem die Menschen sp\u00fcren: Die Kirchengemeinde kann gut feiern, sie ist informiert und setzt durch Mit-teilen Zeichen in den Lebensstil-Fragen der Gegenwart\u201c \u2013 das ist nach den Worten von Pfarrer Werner-Christian Jung, verantwortlicher Redakteur der Zeitschrift<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-398","post","type-post","status-publish","format-standard","hentry","category-familie-jugend-familie"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=398"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/398\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}