{"id":40145,"date":"2011-12-21T14:22:13","date_gmt":"2011-12-21T13:22:13","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=40145"},"modified":"2014-01-15T12:37:02","modified_gmt":"2014-01-15T11:37:02","slug":"keine-eile-beim-bausparvertrag","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/keine-eile-beim-bausparvertrag-1040145\/","title":{"rendered":"Aktueller Marktvergleich der Bausparkassen"},"content":{"rendered":"<p>&#8222;Denn am 32. Dezember ist es zu sp\u00e4t&#8230;&#8220; &#8211; die legend\u00e4re Werbebotschaft von Joki Kirschner hat bleibende Wirkung hinterlassen. Das Jahresende ist die Zeit der Bausparvertr\u00e4ge. Jeder vierte Bausparer wird im Dezember abgeschlossen. Werbeargument war und ist die volle staatliche Jahrespr\u00e4mie f\u00fcr das Abschlussjahr. Tats\u00e4chlich gibt es jedoch keinen Grund zur Eile. Die Ertragsvorteile aufgrund eines Vertragsabschlusses am Ende des Jahres erweisen sich bei genauerer Betrachtung in der Regel als gering.<!--more--> Dennoch macht die Staats- und Banken-Krise Bausparen zu einer attraktiven Anlageform. Die Bausparkassen haben sich durch die Veranlagung in Bausparkredite solide aufgestellt, zeigt ein Blick des Verbraucherportals durchblicker.at, das u.a. auch einen Bauspar-Vergleichsrechner anbietet, in die Bilanzen der Institute.<\/p> <p>Bausparkassen solide aufgestellt<\/p> <p>Laut Bausparkassengesetz m\u00fcssen die Institute Bauspareinlagen Einlagen aus Bauspar-Vertr\u00e4gen zu allererst f\u00fcr Bausparkredite n\u00fctzen und auch etwaige \u00dcberh\u00e4nge in Zwischenkredite bzw. in konservative Wertpapiere veranlagen. Den Bilanzen zufolge haben die Bausparkassen 54 bis 79 Prozent ihrer Aktiva in Hypothekardarlehen veranlagt und so gut wie keine Veranlagungen in Staatsanleihen. &#8222;Damit stehen die Bausparkassen sehr solide da&#8220;, so Reinhold Baudisch von durchblicker.at. Au\u00dferdem sind Bauspareinlagen auch von der staatlichen Einlagensicherung mit derzeit 100.000 Euro erfasst.<\/p> <p>Bausparen nach Rekordjahr 2010 erstmals wieder r\u00fcckl\u00e4ufig<\/p> <p>Trotz einer guten Entwicklung im ersten Halbjahr 2011 &#8211; laut Arbeitsforum \u00d6sterreichischer Bausparkassen (A\u00d6B) stiegen in diesem Zeitraum die Bauspareinlagen nach dem Rekordjahr 2010 neuerlich um 2,6 Prozent auf 18,8 Mrd. Euro an &#8211; d\u00fcrfte sich Bausparen in diesem Jahr insgesamt r\u00fcckl\u00e4ufig entwickeln.<\/p> <p>Trotzdem bleibt Bausparen die in \u00d6sterreich beliebteste Anlageform. 5,5 Mio. \u00d6sterreicherinnen und \u00d6sterreicher besitzen einen Bausparer. &#8222;In Zeiten, in denen sich viele fragen, wie sicher ihre Spareinlagen sind, stehen Bausparer auf der sicheren Seite&#8220;, so Reinhold Baudisch von durchblicker.at. Auch die Verzinsung kann sich mit bis zu 2,25 Prozent bei fixverzinsten und bis zu 5,1 Prozent im ersten Jahr bei variabel verzinsten Angeboten sehen lassen. Dank der staatlichen F\u00f6rderung kommen derzeit noch 3 Prozent an Bausparpr\u00e4mie dazu.<\/p> <p>&#8222;Zuckerl&#8220; bis Jahresende vers\u00fc\u00dfen den Ertrag, Rendite-Auswirkung aber gering<\/p> <p>Dass man, wie \u00fcber Jahrzehnte beworben, die volle staatliche Bausparpr\u00e4mie f\u00fcr das laufende Jahr auch dann erh\u00e4lt, wenn man erst zu Jahresende seinen Bausparerabschlie\u00dft, wirkt sich jedoch nur bescheiden auf die Ertr\u00e4ge aus. Wer bis Ende des Jahres noch 1.200 Euro einzahlt, sichert sich die staatliche Pr\u00e4mie von 36 Euro lediglich ein Jahr fr\u00fcher.<\/p> <p>&#8222;Einige Bausparkassen bieten deshalb bis Jahresende noch h\u00f6here Startzinsen oder zus\u00e4tzliche Pr\u00e4mien in den ersten drei Jahren, damit ein Vorteil f\u00fcr Konsumenten darstellbar ist. Trotzdem macht der Unterschied im Auszahlungskapital zwischen einem Start noch im Dezember gegen\u00fcber einem Start im J\u00e4nner 2012 nur ca. 30 Euro aus. Das hei\u00dft, es gibt zwar einen Vorteil, dieser wird jedoch tendenziell \u00fcbertrieben&#8220;, so Baudisch.<\/p> <p>Deutlich gr\u00f6\u00dfer ist der Effekt einer Ver\u00e4nderung des Einzahlungsrhythmus. Wer statt monatlicher Zahlung einen Einmalerlag leistet, verbessert sein Auszahlungskapital gleich um 400 bis 600 Euro, da mehr Zinsen auf das einbezahlte Kapital anlaufen k\u00f6nnen. Bei einer j\u00e4hrlichen statt monatlichen Zahlung ist der Effekt immer noch zwischen 60 und 80 Euro.<\/p> <p>Online-Vergleich und -Abschluss bringt bis zu 145 Euro mehr Rendite beim Bausparen<\/p> <p>Obwohl Bausparen ein hoch standardisiertes Produkt ist, gibt es aber auch Unterschiede zwischen den Anbietern. Der von dem Fixkostenvergleichsportal durchblicker.at durchgef\u00fchrte aktuelle Marktvergleich zeigt, dass Konsumenten durch schlaue Wahl des Anbieters am Ende der Laufzeit bis zu 105 Euro mehr herausholen k\u00f6nnen. Daher sollten Konsumenten vor einem Abschluss die Angebote der Bausparkassen einem schnellen Online-Check unterziehen. Daf\u00fcr bietet durchblicker.at im Internet unter <a target=\"_blank\" rel=\"nofollow\" href=\"https:\/\/durchblicker.at\/bausparen\" title=\"Bausparen ist ungebrochen eine der beliebtesten Sparformen des Landes\" >https:\/\/durchblicker.at\/bausparen<\/a> einen kostenlosen Vergleichsrechner mit allen Angeboten an.<\/p> <p>Sinn macht au\u00dferdem oft auch der Abschluss eines Bauspar-Vertrags via Internet. Auf durchblicker.at erhalten Konsumenten bei Abschluss \u00fcber die Plattform einen Online-Bonus von bis zu 40 Euro, dar\u00fcber hinaus werden je nach Anbieter bis Jahresende von durchblicker.at noch zus\u00e4tzliche &#8222;Goodies&#8220; wie Tankgutscheine oder Marken-Kugelschreiber angeboten. In Summe lassen sich also durch Vergleich der Angebote und Online-Abschluss bis zu 145 Euro mehr beim Bausparen herausholen.<\/p> <p>\u00dcber durchblicker.at<\/p> <p>durchblicker.at erstellt seit 2010 aktuelle Tarif-Vergleiche f\u00fcr KonsumentInnen in \u00d6sterreich. Das Unternehmen ist auch Partner der AK Ober\u00f6sterreich und besch\u00e4ftigt 12 Mitarbeiter. Als erstes unabh\u00e4ngiges Internet-Portal f\u00fcr den Vergleich von Fixkosten sorgt durchblicker.at f\u00fcr Transparenz bei den Preisen, findet f\u00fcr die KonsumentInnen aus dem gesamten Angebot f\u00fcr den Bedarf den individuell g\u00fcnstigsten Anbieter und \u00fcbernimmt auch die Formalit\u00e4ten des Anbieterwechsels. Damit schafft durchblicker.at mehr Wettbewerb und bringt mit den neuen M\u00f6glichkeiten des Internets den \u00f6sterreichischen Markt in Schwung.<\/p> <p>Das Vergleichsportal umfasst derzeit Marktvergleiche f\u00fcr Kfz-, Motorrad-, Fahrrad-, Haushalts- und Rechtsschutzversicherungen, Bausparen, sowie Preisvergleiche f\u00fcr Strom und Gas. Eine Ausdehnung des Vergleichsportals auf weitere Versicherungsprodukte und andere Fixkosten des t\u00e4glichen Lebens ist in Arbeit. Weitere Informationen unter https:\/\/durchblicker.at.<\/p> <p>Firmenkontakt<br \/> durchblicker.at | YOUSURE Tarifvergleich GmbH<br \/> Reinhold Baudisch<br \/> Mooslackengasse 17<\/p> <p>1190 WIen<br \/> \u00d6sterreich<\/p> <p>E-Mail: online@durchblicker.at<br \/> Homepage: http:\/\/durchblicker.at<br \/> Telefon: 01 30 60 900<\/p> <p>Pressekontakt<br \/> durchblicker.at | YOUSURE Tarifvergleich GmbH<br \/> Reinhold Baudisch<br \/> Mooslackengasse 17<\/p> <p>1190 WIen<br \/> \u00d6sterreich<\/p> <p>E-Mail: online@durchblicker.at<br \/> Homepage: http:\/\/durchblicker.at<br \/> Telefon: 01 30 60 900<\/p>","protected":false},"excerpt":{"rendered":"<p>&#8222;Denn am 32. Dezember ist es zu sp\u00e4t&#8230;&#8220; &#8211; die legend\u00e4re Werbebotschaft von Joki Kirschner hat bleibende Wirkung hinterlassen. Das Jahresende ist die Zeit der Bausparvertr\u00e4ge. Jeder vierte Bausparer wird im Dezember abgeschlossen. Werbeargument war und ist die volle staatliche Jahrespr\u00e4mie f\u00fcr das Abschlussjahr. Tats\u00e4chlich gibt es jedoch keinen Grund zur Eile. Die Ertragsvorteile aufgrund<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-40145","post","type-post","status-publish","format-standard","hentry","category-wirtschaft-management-versicherung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/40145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=40145"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/40145\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=40145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=40145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=40145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}