{"id":40240,"date":"2011-12-21T14:38:45","date_gmt":"2011-12-21T13:38:45","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=40240"},"modified":"2016-02-26T16:12:57","modified_gmt":"2016-02-26T15:12:57","slug":"ereader-zu-weihnachten","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/ereader-zu-weihnachten-1040240\/","title":{"rendered":"eReader im Live-Shopping"},"content":{"rendered":"<p>B\u00fccher lesen ist wieder in Mode gekommen. Vor allem seit Amazon mit dem Hauseigenen eBook Reader Kindle, einen neuen Markt geschaffen hat. Mittlerweile gibt es weitere namhafte Konzerne, die sich in diesem Markt tummeln, Sony, Samsung, Noble, Barnes, um einige zu nennen.<\/p> <p>E-Reader haben eine kurvenreiche Geschichte. 1999 ist der erste E-Book-Reader &#8222;Rocket eBook&#8220; von der Firma NuvoMedia in Amerika erschienen. Leider blieb der kommerzielle Erfolg aus und das Projekt wurde wieder eingestampft. Ende 2007 ver\u00f6ffentlichte Amazon den Kindle und fand damit starken Zuspruch. <!--more-->Auch der Kampf gegen die neue Generation der Tablet-Computer konnte der eReader gewinnen. W\u00e4hrend der Besitz eines Tablet-Computers in Amerika von 5 % auf 8 % angestiegen ist, stieg er bei den eBook Readern in derselben Zeit von 6 % auf 12 % an.<\/p> <p>Im Vergleich zu einem Tablet sind die Texte gestochen scharf und \u00e4hneln einem Buch sehr stark. Selbst helles Sonnenlicht st\u00f6rt nicht und erzeugt keine st\u00f6renden Blendeffekte.<\/p> <p>Den gr\u00f6\u00dften Nutzen an diesen praktischen Ger\u00e4ten haben allerdings Sehbehinderte. Mit der M\u00f6glichkeit die Gr\u00f6\u00dfe und Schrift anzupassen, ist es auch Menschen die Probleme mit ihren Augen haben m\u00f6glich B\u00fccher zu lesen.<\/p> <p>Amazon bietet mittlerweile den Kindle f\u00fcr 99,- EUR an und punktet bei seinen Kunden vor allem im Weihnachtsgesch\u00e4ft.<br \/> Einige Unternehmen ziehen nach und so hat Comtech.de ein interessantes Weihnachtsangebot f\u00fcr alle Lesefreunde, die einfach nur lesen wollen. Das Einsteigermodell von Sony, PRS-300, gibt es 75% billiger, ab 39,- EUR, im Online-Shop zu kaufen.<\/p> <p>Das Ger\u00e4t f\u00fchlt sich durch seine gute Verarbeitung und dem schicken Alu-Look \u00e4u\u00dferst stabil und wertig an. Mit 5&#8243; ist das Ger\u00e4t zwar etwas kompakter als die breite Masse, aber daf\u00fcr liegt es ein bisschen besser in der Hand. Das geringe Gewicht, trotz Aluminium, macht sich auch positiv bemerkbar. Sony verzichtet bei diesem Ger\u00e4t auf Zusatzfunktionen wie MP3 oder Image Viewer f\u00fcr BMP- und JPEG-Dateien. Mit 512 MB Speicher passen ca. 350 B\u00fccher auf das PRS-300. F\u00fcr Vielleser, Reisende und Pendler sicherlich ein gutes Geschenk.<\/p> <p>Am ersten und zweiten Weihnachtstag, jeweils um 17 Uhr, wird in einer Live-Shopping Aktion bei Comtech.de eine Stunde lang das PRS-300 von Sony ab 39 EUR angeboten. Am 25.12 gibt es das Ger\u00e4t in Rot und am 26.12 in Silber. Der Preis steigert sich in dieser Stunde auf den urspr\u00fcnglichen Preis von 89 EUR. Das Angebot ist jeweils auf 300 St\u00fcck begrenzt. Wer sich auf der Comtech Fanseite bei Facebook anmeldet, bekommt \u00fcbrigens noch einen Gutschein \u00fcber 5 Euro.<\/p> <p>eBook Reader<\/p> <p>Firmenkontakt<br \/> Comtech GmbH<br \/> Klaus Arent<br \/> Talstra\u00dfe 13<\/p> <p>71546 Aspach<br \/> Deutschland<\/p> <p>E-Mail: k.arent@comtech.de<br \/> Homepage: http:\/\/www.comtech.de<br \/> Telefon: 071913440274<\/p> <p>Pressekontakt<br \/> Comtech GmbH<br \/> Klaus Arent<br \/> Talstra\u00dfe 13<\/p> <p>71546 Aspach<br \/> Deutschland<\/p> <p>E-Mail: k.arent@comtech.de<br \/> Homepage: http:\/\/www.comtech.de<br \/> Telefon: 071913440274<\/p>","protected":false},"excerpt":{"rendered":"<p>B\u00fccher lesen ist wieder in Mode gekommen. Vor allem seit Amazon mit dem Hauseigenen eBook Reader Kindle, einen neuen Markt geschaffen hat. Mittlerweile gibt es weitere namhafte Konzerne, die sich in diesem Markt tummeln, Sony, Samsung, Noble, Barnes, um einige zu nennen. E-Reader haben eine kurvenreiche Geschichte. 1999 ist der erste E-Book-Reader &#8222;Rocket eBook&#8220; von<\/p>\n","protected":false},"author":291,"featured_media":197700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8805],"tags":[],"class_list":["post-40240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shopping"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/40240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=40240"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/40240\/revisions"}],"predecessor-version":[{"id":230042,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/40240\/revisions\/230042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197700"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=40240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=40240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=40240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}