{"id":411,"date":"2008-07-01T15:30:35","date_gmt":"2008-07-01T14:30:35","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/journal-of-youth-and-adolescence-10411\/"},"modified":"2010-07-26T14:22:17","modified_gmt":"2010-07-26T13:22:17","slug":"journal-of-youth-and-adolescence","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/journal-of-youth-and-adolescence-10411\/","title":{"rendered":"Journal of Youth and Adolescence"},"content":{"rendered":"<p><strong>L\u00e4sst mich das dick aussehen?<\/strong><\/p> <p>Neue Studie belegt, dass Teenager ihr Verhalten bei der Gewichtskontrolle haupts\u00e4chlich von Gleichaltrigen abgucken<br \/> New York\/Heidelberg, 1. Juli 2008<\/p> <p>Wenn es um die Beurteilung ihrer eigenen Figur geht, werden Teenager vor allem von Gleichaltrigen beeinflusst, mit denen sie sich identifizieren. Dies best\u00e4tigt eine neue Studie1 von Dr. Eleanor Mackey vom Children&#8217;s National Medical Center in Washington DC und ihrer Kollegin Dr. Annette La Greca von der University of Miami. Ebenso wird das Gewichtskontrollverhalten und die Definition, was als normales Gewicht empfunden wird, vor allem davon beeinflusst, was andere als normales K\u00f6rpergewicht ansehen. Diese Ergebnisse wurden k\u00fcrzlich in einer Online-Version der Springer-Fachzeitschrift Journal of Youth and Adolescence ver\u00f6ffentlicht.<!--more--><\/p> <p>Gef\u00e4hrliche Gewichtskontrollpraktiken wie beispielsweise Di\u00e4ten und die Neigung zur Bulimie beginnen h\u00e4ufig im jugendlichen Alter und k\u00f6nnen ernsthafte langfristige Beeintr\u00e4chtigen der Gesundheit nach sich ziehen. Auch wenn offensichtlich ist, dass Gleichaltrige einen starken Einfluss auf die Gewichtskontrollstrategien von heranwachsenden M\u00e4dchen haben k\u00f6nnen, so besteht bis jetzt keine Klarheit dar\u00fcber, wie der Einfluss von Gleichaltrigen ausge\u00fcbt wird. Die Wissenschaftlerinnen wollten kl\u00e4ren, wie die Identifizierung mit einer bestimmten Gruppe von Gleichaltrigen dazu f\u00fchrt, ob sich die M\u00e4dchen \u00fcber ihr Gewicht sorgen und wie sie es kontrollieren m\u00f6chten.<\/p> <p>Die Autorinnen testeten 236 M\u00e4dchen im Alter zwischen 13 und 18 Jahren. Dabei wurde untersucht, mit welcher Gruppe von Gleichaltrigen sie sich identifizierten, welche eigenen Bedenken sie wegen ihres K\u00f6rpergewichts \u00e4u\u00dferten; ferner wurden sie \u00fcber ihre Wahrnehmung der Gewichtsprobleme anderer Gleichaltriger sowie \u00fcber ihr eigenes Gewichtskontrollverhalten befragt. Die Wissenschaftlerinnen fanden heraus, dass zwischen der Zugeh\u00f6rigkeit zu einer bestimmten Peergroup und dem Gewichtskontrollverhalten der M\u00e4dchen ein komplexer Zusammenhang besteht. Insbesondere bestand h\u00e4ufig ein Zusammenhang zwischen der Gruppe, mit der sich die M\u00e4dchen identifizierten und der Art der Gewichtskontrolle.<\/p> <p>Insbesondere waren M\u00e4dchen, die sich mit sportlichen Gleichaltrigen identifizierten, weniger um ihr eigenes Gewicht besorgt und schienen weniger geneigt, ihr Gewicht zu kontrollieren. M\u00e4dchen, die sich mit unangepassten Gleichaltrigen (sogenannten Alternativen) identifizierten, waren eher um ihr Gewicht und ihr Aussehen besorgt und versuchten aktiv Gewicht zu verlieren. M\u00e4dchen, die sich mit anderen identifizierten, welche die Schule abbrechen und h\u00e4ufig in Schwierigkeiten geraten (\u2018Burnouts\u2019), waren davon \u00fcberzeugt, dass Schlanksein und Di\u00e4ten bei ihren Gleichaltrigen eine hohen Stellenwert h\u00e4tten. M\u00e4dchen, die keiner bestimmten Peergroup angeh\u00f6rten, waren schlie\u00dflich am ehesten anf\u00e4llig f\u00fcr Schlankheitskuren.<\/p> <p>Den Autorinnen zufolge belegt diese Studie, dass die eigene Einstellung der M\u00e4dchen sowie ihre Wahrnehmung der Gewichts- und Aussehensideale bei anderen Gleichaltrigen eine entscheidende Rolle bei ihrem Gewichtskontrollverhalten spielt. Die Identifikation mit Gleichaltrigen k\u00f6nnte dabei ma\u00dfgeblich sein. Werden diese Zusammenh\u00e4nge begriffen, hat dies Auswirkungen auf die Vorbeuge- und Interventionsprogramme in Schulen und Vorschuleinrichtungen. Die Autorinnen schlagen vor, dass &#8222;Vertreter des Gesundheitswesens und der Schulen die heranwachsenden M\u00e4dchen \u00fcber ihre Zugeh\u00f6rigkeit zu bestimmten Gruppen Gleichaltriger befragen k\u00f6nnten, um die Jugendlichen ausfindig zu machen, die das st\u00e4rkste Gesundheit gef\u00e4hrdende Verhalten zeigen\u2026Die Unzufriedenheit der M\u00e4dchen mit ihrem K\u00f6rper und ihrem Gewicht ist m\u00f6glicherweise ebenfalls ein bedeutender Faktor f\u00fcr Gewichtskontrollma\u00dfnahmen.&#8220;<\/p> <p>Quelle<\/p> <p>1. Mackey ER &amp; La Greca AM (2008). Does this make me look fat? Peer crowd and peer contributions to adolescent girls\u2019 weight control behaviors. Journal of Youth and Adolescence; DOI 10.1007\/s10964-008-9299-2<\/p> <p>Journalisten k\u00f6nnen den vollst\u00e4ndigen Artikel als Pdf-Dokument abrufen.<br \/> Kontakt: Joan Robinson, joan.robinson@springer.com, Tel. +49-6221-4878130<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u00e4sst mich das dick aussehen? Neue Studie belegt, dass Teenager ihr Verhalten bei der Gewichtskontrolle haupts\u00e4chlich von Gleichaltrigen abgucken New York\/Heidelberg, 1. Juli 2008 Wenn es um die Beurteilung ihrer eigenen Figur geht, werden Teenager vor allem von Gleichaltrigen beeinflusst, mit denen sie sich identifizieren. Dies best\u00e4tigt eine neue Studie1 von Dr. Eleanor Mackey vom<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-411","post","type-post","status-publish","format-standard","hentry","category-ernahrung-umwelt-natur"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=411"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/411\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}