{"id":4146,"date":"2010-02-26T08:17:36","date_gmt":"2010-02-26T07:17:36","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=4146"},"modified":"2025-12-05T12:19:23","modified_gmt":"2025-12-05T11:19:23","slug":"smartphone-verschluesselung-ip-telefonie-mobilkommunikation","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/smartphone-verschluesselung-ip-telefonie-mobilkommunikation-104146\/","title":{"rendered":"Voice-Komplettierung f\u00fcr certgate Smartphone Protector: Erste Verschl\u00fcsselung f\u00fcr mobile IP-Telefonie auf handels\u00fcblicher und hochsicherer Plattform"},"content":{"rendered":"<p>N\u00fcrnberg, 25.02.2010, Die certgate GmbH, Anbieter von Sicherheitsl\u00f6sungen f\u00fcr mobile Endger\u00e4te, gibt die Entwicklung einer standardbasierten Sprachverschl\u00fcsselung bekannt. Die neue Voice-Crypto-App wird die Hochsicherheitsl\u00f6sung certgate Smartphone Protector des N\u00fcrnberger IT-Security-Spezialisten zu einer Gesamtl\u00f6sung f\u00fcr sichere Sprach- und Daten-Kommunikation vervollst\u00e4ndigen.<!--more--><\/p> <p>Die Technologie der bisher auf die hochsichere Verschl\u00fcsselung von Daten fokussierten certgate-L\u00f6sung wird unter anderem im Projekt SiMKo2 &#8211; auch bekannt als &#8222;Merkelphone&#8220; &#8211; f\u00fcr die sichere Mobilkommunikation der Bundesregierung und der \u00d6ffentlichen Verwaltung eingesetzt. Jetzt erfolgt die Erg\u00e4nzung um eine SIP- und SRTPkompatible Sprachverschl\u00fcsselungs-Komponente auf Basis von VoIP. F\u00fcr den Schl\u00fcsselaustausch kommen dabei wahlweise PKI oder das ZRTP-Verfahren zum Einsatz.<\/p> <p>&#8222;Mit unserer Neuentwicklung erm\u00f6glichen wir die verschl\u00fcsselte \u00dcbermittlung von Daten und Sprache auf h\u00f6chstem Sicherheitsniveau unter Nutzung handels\u00fcblicher Smartphones&#8220;, erl\u00e4utert Dr. Paschalis Papagrigoriou, Gesch\u00e4ftsf\u00fchrer der certgate GmbH. &#8222;Besonderen Wert haben wir darauf gelegt, dass Sprach- und Daten\u00fcbertragung durch sichere Verfahren abgeschirmt werden und die eingesetzten Endger\u00e4te durch unsere Smartcard mit einem hochwirksamen Schutz gegen Manipulationen und Spyware ausgestattet sind.&#8220;<\/p> <p>certgate schlie\u00dft Spionage-Angriffe gegen das Endger\u00e4t durch die BSIgepr\u00fcfte &#8222;Kernel-Protection&#8220; aus, die das Betriebssystem vor Manipulationen sch\u00fctzt und jede Installation von Schadsoftware auf dem Smartphone verl\u00e4sslich ausschlie\u00dft. Angreifbare Endger\u00e4te waren in die Diskussion geraten, nachdem bekannt wurde, dass Mikrophone und Lautsprecher der Mobiltelefone dem Angreifer mittels frei verf\u00fcgbarer Lausch-Software auch bei eingeschalteter Verschl\u00fcsselung den Zugang zum vertraulichen Gespr\u00e4chsinhalt er\u00f6ffnen k\u00f6nnen.<\/p> <p>Der &#8222;geh\u00e4rtete&#8220; certgate Smartphone Protector, der seit der CeBIT 2009 auf dem Markt eingef\u00fchrt ist, stellt eine einzigartig sichere L\u00f6sung dar, die mittels hardwaregesch\u00fctzter Zertifikate Smartphones und PDAs sowie die darauf befindlichen Daten vor jeder Art unberechtigter Zugriffe und Manipulationen abschirmt. Der Protector stellt au\u00dferdem Zertifikate und Schl\u00fcssel f\u00fcr die sichere Daten\u00fcbertragung (VPN, SSL) und die hardwaregest\u00fctzte Verschl\u00fcsselung von E-Mails (S\/MIME) zur Verf\u00fcgung.<\/p> <p>Besuchen Sie certgate:<br \/> 2. &#8211; 6. M\u00e4rz 2010 CeBIT 2010, Hannover<br \/> Halle 11, CeBIT SECURITY PLAZA, Stand D12, Pr\u00e4sentationsplatz 4<br \/> Halle 9, BAYERN INNOVATIV, Stand B20<\/p> <p>2. &#8211; 5. M\u00e4rz 2010, RSA Conference 2010, San Francisco<br \/> Moscone Convention Center, als Gast der certgate-Partner NCP und Kobil am Stand 1440<\/p> <p>\u00dcber certgate GmbH<\/p> <p>Das in N\u00fcrnberg ans\u00e4ssige High-Tech-Unternehmen certgate GmbH wurde 2004 von Dr. Paschalis Papagrigoriou gegr\u00fcndet. Gesch\u00e4ftsfeld der innovativen Firma ist die Entwicklung und Vermarktung von Produkten und L\u00f6sungen, die den Umgang mit mobilen Kommunikationsger\u00e4ten sicherer und benutzerfreundlicher machen. certgate hat die weltweit erste microSD-Card mit Smartcard-Funktionalit\u00e4t entwickelt und seinen technischen Vorsprung im Bereich der mobilen IT-Sicherheit mit Patentschutz versehen.<\/p> <p>Der Kern der L\u00f6sungen, die certgate SmartCard microSD, erm\u00f6glicht aufgrund ihrer starken kryptografischen Funktionen das Speichern und sichere Verwenden von Zertifikaten sowie das Generieren von Schl\u00fcsselpaaren. Damit unterst\u00fctzt die Smartcard auf Smartphones und Notebooks vollwertige Zwei-Faktor-Authentisierung, verschl\u00fcsselte Datenspeicherung, E-Mail-Verschl\u00fcsselung, sicheres Mobil-Banking nach HBCI- und EBICS-Standards und den Aufbau gesch\u00fctzter VPN-Verbindungen. In enger Zusammenarbeit mit Implementierungspartnern besch\u00e4ftigt sich certgate auch mit kundenindividuellen Sicherheitsl\u00f6sungen f\u00fcr Smartphones, PDAs und andere Mobilger\u00e4te auf Basis seiner certgate SmartCard microSD. www.certgate.com<\/p> <p>certgate GmbH<br \/> Merianstra\u00dfe 26<br \/> D-90409 N\u00fcrnberg<br \/> www.certgate.com<\/p> <p>Telefon +49 (911) 93523-32<\/p> <p>&#8212;&#8211;<\/p> <p>Sabine Faltmann, M.A.<br \/> Pressereferentin von certgate<\/p> <p>fon +49.241.57 07 357 | fax +49.321.21 20 53 63 | mobil +49.171.54 57 142<br \/> www.faltmann.com | mailto:certgate@faltmann-pr.de<\/p>","protected":false},"excerpt":{"rendered":"<p>N\u00fcrnberg, 25.02.2010, Die certgate GmbH, Anbieter von Sicherheitsl\u00f6sungen f\u00fcr mobile Endger\u00e4te, gibt die Entwicklung einer standardbasierten Sprachverschl\u00fcsselung bekannt. Die neue Voice-Crypto-App wird die Hochsicherheitsl\u00f6sung certgate Smartphone Protector des N\u00fcrnberger IT-Security-Spezialisten zu einer Gesamtl\u00f6sung f\u00fcr sichere Sprach- und Daten-Kommunikation vervollst\u00e4ndigen.<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[1363,1358,1359,1362,1364,1360,1361,1365],"class_list":["post-4146","post","type-post","status-publish","format-standard","hentry","category-handy-elektronik-telekommunikation","tag-cebit","tag-certgate","tag-ip-telefonie","tag-kryptografie","tag-microsd","tag-smartphone","tag-verschluesselung","tag-voice-crypto-app"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=4146"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4146\/revisions"}],"predecessor-version":[{"id":278163,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4146\/revisions\/278163"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=4146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=4146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=4146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}