{"id":4177,"date":"2010-02-27T07:35:19","date_gmt":"2010-02-27T06:35:19","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=4177"},"modified":"2014-11-09T08:41:43","modified_gmt":"2014-11-09T07:41:43","slug":"beckenbodenschmerzen-muskelentspannungstraining-spannungskopfschmerz-migraene-gesichtsschmerz","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/beckenbodenschmerzen-muskelentspannungstraining-spannungskopfschmerz-migraene-gesichtsschmerz-104177\/","title":{"rendered":"Inkontinenzhilfen &#8211; Elektronische Mess-Systeme  der Beckenboden-Muskelaktivitaet"},"content":{"rendered":"<p>Das NeuroTrac\u2122 Simplex ist ein bedienerfreundliches EMG Biofeedback-Geraet und eignet sich besonders fuer die ambulante Nach- sorge zu Hause. Eine moderne, ergometrische Geraeteform und einfacher Bedienungskomfort zeichnen das NeuroTrac\u2122 Simplex Geraet aus. Sowohl optische als auch akustische Signale melden dem Anwender die Kontraktionskraft der trainierten Muskulatur.<!--more--> Somit ist eine sichere Rueckmeldung (Bio-feedback) ueber den Istzustand der Muskulatur gewaehrleistet. Das NeuroTrac\u2122 Simplex kann mittels eines optischen Fiberkabels zur sicheren Datenuebertragung mit einem Computer verknuepft werden. Das NeuroTrac\u2122 Simplex ist ein bediener- freundliches EMG Biofeedback-Geraet und eignet sich besonders fuer die ambulante Nach- sorge zu Hause. Eine moderne, ergometrische Geraeteform und einfacher Bedienungskomfort zeichnen das NeuroTrac\u2122 Simplex Geraet aus. Sowohl opti- sche als auch akustische Signale melden dem Anwender die Kontraktionskraft der trainierten Muskulatur.  Somit ist eine sichere Rueckmeldung (Bio-feedback) ueber den Istzustand der Muskulatur gewaehrleistet. Das NeuroTrac\u2122 Simplex kann mittels eines optischen Fiberkabels zur sicheren Datenuebertragung mit einem Computer verknuepft werden.<br \/> Wann kann Biofeedback eingesetzt werden?<br \/> Stressinkontinenz, Dranginkontinenz,  Mischinkontinenz,  Stuhlinkontinenz \/ anale Inkontinenz,  Beckenbodenschmerzen, Muskelentspannungstraining,  Spannungskopfschmerz, Migraene,  Gesichtsschmerz,  chronischer Rueckenschmerz, Psychotherapie und Psychologie,  Angststoerungen,  Panikattacken,  Phobien,  Unterstuetzung von AT,  PMR, KB,  Hypnose,  Hyperaktivitaet,  Aufmerksamkeitsstoerungen,  Atemtraining,  Stressmanagement,  Mentales Training,  Psychosomatik und Verhaltensmedizin,  Morbus Raynaud,  essentielle Hypertonie,  Hyperventilationssyndrom,  Asthma,  chronische Muskelverspannungen  Weitere Informationen finden Sie auf unserer Website unter:<\/p> <p>http:\/\/www.heller-medizintechnik.de\/newsletter.html<\/p> <p>Gesch\u00e4ftsf\u00fchrer: \u00a0\u00a0 \u00a0Joachim Heller<\/p> <p>Europaplatz 2<br \/> D 35619 Braunfels<\/p>","protected":false},"excerpt":{"rendered":"<p>Das NeuroTrac\u2122 Simplex ist ein bedienerfreundliches EMG Biofeedback-Geraet und eignet sich besonders fuer die ambulante Nach- sorge zu Hause. Eine moderne, ergometrische Geraeteform und einfacher Bedienungskomfort zeichnen das NeuroTrac\u2122 Simplex Geraet aus. Sowohl optische als auch akustische Signale melden dem Anwender die Kontraktionskraft der trainierten Muskulatur.<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-4177","post","type-post","status-publish","format-standard","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=4177"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4177\/revisions"}],"predecessor-version":[{"id":172990,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4177\/revisions\/172990"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=4177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=4177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=4177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}