{"id":442,"date":"2008-07-11T09:03:25","date_gmt":"2008-07-11T08:03:25","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/schweizer-investieren-mehr-geld-in-medien-10442\/"},"modified":"2022-05-24T11:50:58","modified_gmt":"2022-05-24T10:50:58","slug":"schweizer-investieren-mehr-geld-in-medien","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/schweizer-investieren-mehr-geld-in-medien-10442\/","title":{"rendered":"Schweizer investieren mehr Geld in Medien"},"content":{"rendered":"<p> <font size=\"-1\"><strong>Werbung vermehrt an Zielgruppen, als an Reichweiten interessiert <\/strong><\/font><\/p> <table style=\"float: right; width: 168px\" border=\"0\" cellpadding=\"5\" cellspacing=\"0\"> <tr> <td align=\"center\" bgcolor=\"#ededed\"> <table border=\"0\" cellpadding=\"3\" cellspacing=\"0\" width=\"168\"> <tr> <td align=\"center\"><\/td> <\/tr> <tr> <td colspan=\"2\" class=\"txtklein\" align=\"center\"><!-- copyrighttext -->Schweizer geben 6,9 Mrd. Euro f\u00fcr Medien aus (Grafik: Verband Schweizer Presse)<!-- end copyrighttext --><\/td> <\/tr> <\/table> <\/td> <\/tr> <\/table> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"> <span class=\"txt\"> <!--PTE:ORT-->Z\u00fcrich (pte\/10.07.2008\/11:00) &#8211; Der Medienkonsum ist in der Schweiz weiterhin ein Wachstumsmarkt. Dies zeigen die Resultate der zum vierten Mal vom Verband Schweizer Presse http:\/\/www.schweizerpresse.ch durchgef\u00fchrten Studie zu den Medienbudgets. <\/span><\/font><!--more--><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\"><span class=\"txt\">Die Ausgaben stiegen 2007 um 6,6 Prozent auf 11,3 Mrd. Franken (6,9 Mrd. Euro), das sind 3.276 Franken (2.016 Euro) je Haushalt. 2006 waren es noch 1.930 Euro. &#8222;Das zeigt, dass die Schweizer bereit sind f\u00fcr gute Informationen auch viel Geld zu bezahlen&#8220;, meint Th\u00e9r\u00e8se Ruedin, die im Auftrag des Verbandes Schweizer Presse die Medienbudgetbefragung durchf\u00fchrte, im Gespr\u00e4ch mit pressetext.<\/span><\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">Den gr\u00f6\u00dften Teil, 6,2 Mrd. Franken (3,8 Mrd. Euro), gaben die Schweizer dabei f\u00fcr den Einkauf von Inhalten aus, was einem Plus von 3,5 Prozent entspricht. Einen Umsatzanstieg von 13,5 Prozent konnte die Medienbranche beim Verkauf von Ger\u00e4ten zur Mediennutzung verbuchen. &#8222;Die Leute wollen gute Fernseher, schnelle Internetverbindungen und rauschfreie Radios, daf\u00fcr geben sie gerne ein paar Franken mehr aus&#8220;, so Ruedin weiter. Mehr Geld ausgegeben wurde dabei f\u00fcr mobilen Content und f\u00fcr Downloads von Medienservices. Vor allem der Internethandel mit Tontr\u00e4gern, der um 86 Prozent zulegte, konnte davon profitieren. Der Buchmarkt schloss mit einem kleinen Plus von 2,5 Prozent das Jahr 2007 ab. Als Grund hierf\u00fcr wird die am 2. Mai 2007 aufgehobene Buchpreisbindung genannt, die zu einem starken Preiskampf f\u00fchrte.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">Ein hingegen schlechtes Jahr hat der Zeitungs- und Zeitschriftenmarkt durchlebt. Zwar habe jeder Haushalt im Durchschnitt noch 1,3 Abos, doch sank deren Gesamtzahl um 4,4 Prozent auf 2,7 Mio. &#8222;Der Schweizer Medienmarkt ist wie kaum ein zweiter in Europa durch die St\u00e4rke der Gratiszeitungen und durch die Kleinteiligkeit an Zeitungstiteln gepr\u00e4gt&#8220;, erkl\u00e4rt Ruedin. &#8222;Durch die Dreisprachigkeit der Schweiz gibt es viele kleine Titel, die regelm\u00e4\u00dfig ums \u00dcberleben k\u00e4mpfen m\u00fcssen.&#8220; In der Schweiz buhlen neben den k\u00e4uflich zu erwerbenden Zeitungen- und Zeitschriften sechs gro\u00dfe Gratiszeitungen um die Gunst der Leser.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">Neben den Abbozeitungen mussten auch die Stra\u00dfenverkaufstitel Absatzr\u00fcckg\u00e4nge hinnehmen. Das f\u00fchrt man beim Schweizer Presseverband darauf zur\u00fcck, dass weniger Kunden die L\u00e4den frequentierten. &#8222;Fr\u00fcher wurden Lottoscheine beim Kiosk abgegeben, heute wird im Internet gespielt. Dadurch ist der Mitnahmeeffekt von Printartikeln gesunken&#8220;, so der Verband. Im Gegensatz zu Deutschland und \u00d6sterreich sind drei von f\u00fcnf Titeln, die am Kiosk verkauft werden, ausl\u00e4ndische Publikationen. &#8222;Denn Schweizer Zeitungen werden schon aus Gewohnheit abboniert&#8220;, meint Ruedin.<\/font><\/p> <p><font face=\"Verdana, Arial, Helvetica, sans-serif\" size=\"-1\">Als zunehmenden Trend in der Schweizer Medienbranche macht Ruedin aus, dass sich Werbung immer weniger an Reichweiten orientiere, sondern vermehrt an den Zielgruppen, die damit erreicht werden k\u00f6nnen. &#8222;Werbetreibende interessiert immer st\u00e4rker, in welchem Umfeld sie ihre Werbung schalten und f\u00fcr Qualit\u00e4t ist man dort auch bereit, mehr Geld zu bezahlen.&#8220; Zudem sei Werbung aufgrund der Vielsprachlichkeit in der Schweiz ohnehin schon teuer. &#8222;Wenn Jugendliche in Deutschland erreicht werden sollen, dann muss man in zwei oder drei Titeln inserieren. Hier sind es je Sprache drei und das macht Werbung teuer&#8220;, so Ruedin. (Ende)<br \/> <br clear=\"all\" \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\"><\/a><br \/> Aussender: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pressetext.de\/\"  target=\"_new\" rel=\"noopener\">pressetext.austria<\/a><br \/> Redakteur:                        Erik Stasch\u00f6fsky<br \/> email: <a href=\"mailto:staschoefsky%40pressetext.com\">staschoefsky@pressetext.com<\/a><br \/> Tel. +43-1-81140-316   <\/font><\/p>","protected":false},"excerpt":{"rendered":"<p>Werbung vermehrt an Zielgruppen, als an Reichweiten interessiert Schweizer geben 6,9 Mrd. Euro f\u00fcr Medien aus (Grafik: Verband Schweizer Presse) Z\u00fcrich (pte\/10.07.2008\/11:00) &#8211; Der Medienkonsum ist in der Schweiz weiterhin ein Wachstumsmarkt. Dies zeigen die Resultate der zum vierten Mal vom Verband Schweizer Presse http:\/\/www.schweizerpresse.ch durchgef\u00fchrten Studie zu den Medienbudgets.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-442","post","type-post","status-publish","format-standard","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=442"}],"version-history":[{"count":3,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/442\/revisions"}],"predecessor-version":[{"id":274556,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/442\/revisions\/274556"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}