{"id":4610,"date":"2010-03-24T19:13:03","date_gmt":"2010-03-24T18:13:03","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=4610"},"modified":"2010-07-26T14:19:15","modified_gmt":"2010-07-26T13:19:15","slug":"siloadmaxx-als-weg-aus-der-exportkrise","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/siloadmaxx-als-weg-aus-der-exportkrise-104610\/","title":{"rendered":"Siloadmaxx als Weg aus der Exportkrise!"},"content":{"rendered":"<p>Hilgert, 23. M\u00e4rz 2010 \/\/ Die Firma Siloadmaxx GmbH &amp; Co. KG schickt sich an, der Fracht- und Container-Industrie belebend unter die Arme zu greifen. Das siloadmaxx\u00ae System, das schon auf der IAA 2008 ein umjubeltes Deb\u00fct feierte, wird seit diesem Jahr aktiv vermarktet.<br \/> \u201eWir haben im vergangenen Jahr das System perfektioniert und zahlreiche Performance Tests bei Kunden mit Bravur absolviert. 25t Sch\u00fcttgut in 25 Minuten zu verladen und dabei Standard-ISO-Container kapazit\u00e4tsf\u00fcllend auszunutzen, das macht uns keiner nach. <!--more-->Damit k\u00f6nnen wir Produktreichweite f\u00fcr zahlreiche Sch\u00fcttgut-Produkte enorm vergr\u00f6\u00dfern und so den Markt beleben\u201c, so Christian Hanses, Gesch\u00e4ftsf\u00fchrer der Siloadmaxx GmbH &amp; Co. KG.<br \/> siloadmaxx\u00ae ist ein patentiertes und mobiles System zur Bef\u00fcllung von Standard-ISO-Containern mit Sch\u00fcttg\u00fctern durch pneumatische F\u00f6rderung des Sch\u00fcttguts in die Container. Dadurch werden Container schneller und mit optimaler Raumausnutzung beladen. So verk\u00fcrzt sich die Beladungszeit bei einem Volumen von 25t auf bis zu 25 Minuten.<br \/> Erschlie\u00dfung neuer M\u00e4rkte wird wirtschaftlich sinnvoll<br \/> Der gro\u00dfe Vorteil besteht darin, dass f\u00fcr den Transport von Sch\u00fcttg\u00fctern keine speziellen Container oder Verpackungsmaterialien, wie BigBags ben\u00f6tigt werden. siloadmaxx\u00ae erm\u00f6glicht stattdessen die effiziente Nutzung von Standard-ISO-Containern. Das Optimierungspotenzial des Gesamtprozesses, das sich hieraus f\u00fcr die Kunden darstellt, ist enorm.<br \/> \u201eMit unserem System k\u00f6nnen wir dem Getreide-Bauern aus der Uckermark f\u00fcr sein Getreide den weltweiten Markt verf\u00fcgbar machen. Durch die stark reduzierten Frachtkosten ist er k\u00fcnftig in der Lage, konkurrenzf\u00e4hige Angebote abzugeben\u201c, so Hanses. \u201eDie Einsparungen, die wir mit siloadmaxx\u00ae erm\u00f6glichen, lesen sich bestens: 48% weniger Transportkosten, 75% Zeiteinsparung bei der Vorlogistik, 33% weniger Container ben\u00f6tigt und bis zu 500t Sch\u00fcttgut pro Tag und Maschine umschlagbar.\u201c<br \/> Container-Leerst\u00e4nde abbauen durch Wandlung von Sch\u00fcttgut in St\u00fcckgut<br \/> Viel st\u00e4rker wird die Wirkung des siloadmaxx\u00ae Systems f\u00fcr die Container Logistiker sein. Mehrere Millionen Leer-Container k\u00f6nnen auf diese Art und Weise wieder einer neuen Anwendung zugef\u00fchrt werden. F\u00fcr manchen Logistiker wird der Container durch die g\u00fcnstige und effiziente Beladung zur Verpackung von Sch\u00fcttg\u00fctern. \u201eSo wird Sch\u00fcttgut ja zu St\u00fcckgut!\u201c, wie der CEO eines weltweit operierenden Logistikriesen w\u00e4hrend einer Pr\u00e4sentation bemerkte.  Dieser wusste weiterhin zu berichten, dass sein Unternehmen j\u00e4hrlich fast 1,5 Millionen Leer-Container bewegen, was einen entgangenen Gewinn von 250 \u2013 300 Mio. \u20ac bedeutet.<br \/> Die neuen M\u00f6glichkeiten f\u00fcr den Umgang mit Sch\u00fcttg\u00fctern, er\u00f6ffnet der Industrie der Schenkers, Hapaq Lloyds, Maersk &amp; Co T\u00fcren zu neuen M\u00e4rkten. Kostenreduktion und bessere Raumnutzung sind hier die magischen Schlagworte.<br \/> Siloadmaxx GmbH &amp; Co. KG macht Ernst<br \/> Die Firma w\u00e4chst, um dem Markt gerecht zu werden. Das Gesch\u00e4ftsmodell, das sowohl weltweite Lizenzierungen als auch ein franchiseartiges Niederlassungsmodell vorsieht, ist auf schnelle und weltweite Verbreitung ausgerichtet. \u201eIch m\u00f6chte meine Maschinen in 10 Jahren weltweit fahren sehen k\u00f6nnen wie die braunen LKWs von UPS\u201c, versichert Hanses abschlie\u00dfend seinen Traum regelrecht. Und man muss ihm glauben. Erste Niederlassungen werden im Norden Deutschlands gegr\u00fcndet und Anfragen zur Lizenzierung sind aus den USA, Canada und Australien schon eingetroffen.<br \/> Kontakt:<br \/> Maurice Hofmann<br \/> Presse<br \/> Siloadmaxx GmbH &amp; Co. KG<br \/> In den Erlen 8<br \/> D-56206 Hilgert<br \/> Tel.: \t+49 2624 &#8211; 94 370 44<br \/> Mob. \t+49 172 &#8211; 21 535 84<br \/> Fax: \t+49 2624 &#8211; 94 370 48<br \/> E-Mail: marketing@siloadmaxx.com<br \/> Internet: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.siloadmaxx.com\"  >www.siloadmaxx.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Hilgert, 23. M\u00e4rz 2010 \/\/ Die Firma Siloadmaxx GmbH &amp; Co. KG schickt sich an, der Fracht- und Container-Industrie belebend unter die Arme zu greifen. Das siloadmaxx\u00ae System, das schon auf der IAA 2008 ein umjubeltes Deb\u00fct feierte, wird seit diesem Jahr aktiv vermarktet. \u201eWir haben im vergangenen Jahr das System perfektioniert und zahlreiche Performance<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-4610","post","type-post","status-publish","format-standard","hentry","category-transport-logistik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=4610"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/4610\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=4610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=4610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=4610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}