{"id":463,"date":"2008-07-22T15:26:42","date_gmt":"2008-07-22T14:26:42","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/sport-design-drachen-42008-alles-ubers-kitefliersmeeting-10463\/"},"modified":"2012-10-22T14:15:47","modified_gmt":"2012-10-22T13:15:47","slug":"sport-design-drachen-42008-alles-ubers-kitefliersmeeting","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/sport-design-drachen-42008-alles-ubers-kitefliersmeeting-10463\/","title":{"rendered":"Sport &#038; Design Drachen 4\/2008: Alles \u00fcbers Kitefliersmeeting"},"content":{"rendered":"<p>Das 24. Kitefliersmeeting auf Fan\u00f8 ist Geschichte, doch die Hochsaison der<br \/> nationalen und internationalen Drachenfeste ist weiter in vollem Gange. Wer<br \/> das Meeting in diesem Jahr verpasst hat oder seine Erinnerungen auffrischen<br \/> will, den versorgen wir in Sport &amp; Design Drachen 4\/2008 mit allen<br \/> Informationen rund um das Kite-Spektakel auf dem d\u00e4nischen Eiland.<\/p> <p>Und damit Ihr auf den weiteren Festivals immer up to date seid, haben wir im<br \/> aktuellen Heft eine F\u00fclle spektakul\u00e4rer News und angesagter Modelle<br \/> zusammengetragen. Beispielsweise den eindrucksvollen T-Delta von Colours in<br \/> Motion und die rasanten Matten der Symphony-Beach-Serie von Invento.<!--more--><\/p> <p>Unter anderem sind folgende Themen im aktuellen Heft zu finden:<\/p> <p>&#8211; Ph\u00e4nomenal: 24. Kitefliersmeeting Fan\u00f8<br \/> &#8211; Im Reich der Scheherazade: Luftbildgalerie \u2013 Indien<br \/> &#8211; Land Art: Windart-Installation Project RED<br \/> &#8211; Flink und elegant: Bat Cat von Wolkenst\u00fcrmer<br \/> &#8211; \u00a1Vamos a la playa! Symphony Beach von Invento<br \/> &#8211; Mathematiker: T-Delta von Colours in Motion<br \/> &#8211; Drachendealer: Michael Z\u00e4hler im Interview<br \/> &#8211; Gemeinsam stark: Bow-Kite-Workshop<br \/> &#8211; Im Portrait: Jochen M\u00fcller<\/p> <p>&#8230; und vieles andere mehr.<\/p> <p>Sport &amp; Design Drachen erh\u00e4ltst Du direkt im Verlag oder im gut sortierten<br \/> Fachhandel. Abonnenten haben das Heft in der Regel einige Tage fr\u00fcher. Du<br \/> hast noch kein Heft? Klicke jetzt hier und sichere Dir die aktuelle Ausgabe<br \/> oder gleich alle Vorteile des Abos:<\/p> <p>http:\/\/www.sport-und-design-drachen.de<\/p> <p>&#8212;<\/p> <p>Wellhausen &amp; Marquardt<br \/> Mediengesellschaft bR<br \/> Eppendorfer Weg 109<br \/> 20259 Hamburg<\/p> <p>Telefon: 040 \/ 40 18 07 10<br \/> Telefax: 040 \/ 40 18 07 11<\/p> <p>Internet: http:\/\/www.sport-und-design-drachen.de<br \/> E-Mail: redaktion@sport-und-design-drachen.de<\/p> <p>Vertretungsberechtigte Gesellschafter:<br \/> Tom Wellhausen &amp; Sebastian Marquardt<\/p>","protected":false},"excerpt":{"rendered":"<p>Das 24. Kitefliersmeeting auf Fan\u00f8 ist Geschichte, doch die Hochsaison der nationalen und internationalen Drachenfeste ist weiter in vollem Gange. Wer das Meeting in diesem Jahr verpasst hat oder seine Erinnerungen auffrischen will, den versorgen wir in Sport &amp; Design Drachen 4\/2008 mit allen Informationen rund um das Kite-Spektakel auf dem d\u00e4nischen Eiland. Und damit<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-463","post","type-post","status-publish","format-standard","hentry","category-event-entertainment-lifestyle"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=463"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}