{"id":46934,"date":"2012-08-07T11:29:56","date_gmt":"2012-08-07T10:29:56","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=46934"},"modified":"2012-11-12T14:42:19","modified_gmt":"2012-11-12T13:42:19","slug":"englisch-deutsche-fachwoerterbuecher-des-transport-und-logistikwesens","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/englisch-deutsche-fachwoerterbuecher-des-transport-und-logistikwesens-1046934\/","title":{"rendered":"Englisch-deutsche Fachw\u00f6rterb\u00fccher des Transport- und Logistikwesens"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-46939\" title=\"Dieses Fachw\u00f6rterbuch erm\u00f6glicht Ihnen einen leicht verst\u00e4ndlichen Einstieg in die Welt des Gefahrgutes. \" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/090025c30325d63a636c1c3f77ca40a7.jpg\" alt=\"\" width=\"85\" height=\"119\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/090025c30325d63a636c1c3f77ca40a7.jpg\" \/>Die Utrata &amp; Riedel Verlagsgesellschaft bR ist ein junger Verlag der Anfang des Jahres 2012, von J\u00fcrgen Utrata und Stefan Riedel, gegr\u00fcndet wurde. In Gelsenkirchen, mitten im Herzen des Ruhrgebiets angesiedelt, dem gr\u00f6\u00dften Ballungsgebiet und Logistikstandort Europas, sind die Firmengr\u00fcnder tief verwurzelt mit den vielf\u00e4ltigen \u00c4sten des Transport- und Logistikwesens in der Verkehrswirtschaft. Ziel ist es, die gerade hier, nicht immer leicht verst\u00e4ndliche und sehr umfangreiche Fachsprache f\u00fcr jedermann &#8211; ob Anf\u00e4nger oder erfahrener Praktiker &#8211; zug\u00e4nglich zu machen.<\/p> <p><!--more-->Die Utrata &amp; Riedel Verlagsgesellschaft hat sich auf englisch-deutsche Fachw\u00f6rterb\u00fccher f\u00fcr Beruf, Universit\u00e4ten, Fachhochschulen, Berufsschulen und die Erwachsenenbildung spezialisiert.<\/p> <p>Es wird ein besonderer Wert auf einen praxisnahen und leichten Zugang gelegt, um sowohl dem Berufsanf\u00e4nger, als auch dem erfahrenen Berufspraktiker in ausf\u00fchrender und leitender T\u00e4tigkeit bei seiner Kommunikation, ob \u00fcber E-Mail, Postverkehr, Telefon, Telefax oder beim pers\u00f6nlichen Gespr\u00e4ch wirkungsvoll und effektiv zu unterst\u00fctzen. Alle W\u00f6rterb\u00fccher sind zudem ideal f\u00fcr Ihre Fortbildung, Weiterbildung, Ausbildung, Studium oder Umschulung geeignet.<\/p> <p>Die sichere Kommunikation in der Weltsprache Englisch, gerade im Zeitalter der zunehmenden Globalisierung im Personen- und G\u00fcterverkehr, ist in der heutigen Gesch\u00e4fts- und Handelswelt allgegenw\u00e4rtig und unverzichtbar geworden. Die Fachw\u00f6rterb\u00fccher der Utrata &amp; Riedel Verlagsgesellschaft bieten Ihnen einen leicht verst\u00e4ndlichen Zugang zu Ihrer Fachsprache.<\/p> <p>Um Ihnen das Erlernen oder Vertiefen Ihres pers\u00f6nlichen Fachwortschatzes noch mehr zu erleichtern, hat sich die Utrata &amp; Riedel Verlagsgesellschaft mit dem seit vielen Jahren bew\u00e4hrten Lernprogrammanbieter, der phase6 AG in Riehen in der Schweiz zusammengetan.<\/p> <p>So ist es m\u00f6glich geworden, Ihnen ein besonders einfach strukturiertes Lernsystem zug\u00e4nglich zu machen, welches genau auf Ihre pers\u00f6nliche Art des Lernens zugeschnitten werden kann. Das Vokabellernprogramm phase6 zeichnet sich durch eine bewusst einfach gehaltene und \u00fcbersichtlich strukturierte Benutzeroberfl\u00e4che und den garantierten Langzeit-Lerneffekt aus. Es ist f\u00fcr alle Altersgruppen und nahezu alle Lerninhalte geeignet. Alleine in Deutschland wird es von \u00fcber 3000 Schulen und Universit\u00e4ten und bisher \u00fcber 300.000 zufriedenen Anwendern empfohlen. Seit \u00fcber 10 Jahren wird es aber auch \u00e4u\u00dferst erfolgreich in zahlreichen Bildungsinstituten, therapeutischen Praxen, an namenhaften Sprachschulen und zu firmeninternen Schulungen, sowie im Bereich der beruflichen Aus-, Weiter- und Fortbildung eingesetzt.<\/p> <p>Sie k\u00f6nnen &#8211; nach der Art des bew\u00e4hrten und auf einem wissenschaftlichen Prinzip beruhenden Karteikartenlernsystems &#8211; sowohl unter Apple Mac OS X, Microsoft Windows, Apple iPhone oder Apple iPad jederzeit, ob zu Hause, auf der Arbeit, in der Schule, Uni oder unterwegs, jederzeit auf alle Ihre Lerninhalte zugreifen.<\/p> <p>Ab dem 15.08.2012 bietet Ihnen der Kooperationspartner phase6 die phase6 cloud, zum Einf\u00fchrungspreis von 9,99 \u20ac pro Jahr. Damit k\u00f6nnen Sie alle Ihre Lerninhalte und Lernst\u00e4nde zwischen phase6 desktop f\u00fcr Ihren PC\/Mac und phase6 mobile f\u00fcr Ihr Apple iPad und Apple iPhone synchronisieren.<\/p> <p>Utrata &amp; Riedels Fachw\u00f6rterb\u00fccher im \u00dcberblick:<\/p> <p>&#8211; Binnenschifffahrt<br \/> &#8211; B\u00fcro<br \/> &#8211; Containerverkehr<br \/> &#8211; Eisenbahnverkehr<br \/> &#8211; Gefahrgut<br \/> &#8211; Logistik<br \/> &#8211; Luftverkehr<br \/> &#8211; Seeschifffahrt<br \/> &#8211; Stra\u00dfenverkehr<br \/> &#8211; Versicherung im Verkehrsgewerbe<br \/> &#8211; Werkzeuge<br \/> &#8211; Zollwesen und Au\u00dfenhandel<\/p> <p>F\u00fcr Firmen- und Bildungskunden werden attraktive Preismodelle angeboten:<\/p> <p>&#8211; 15 % Erm\u00e4\u00dfigung ab dem Kauf von zwei gleichen Lerninhalten<br \/> &#8211; 20 % Erm\u00e4\u00dfigung ab dem Kauf von 10 Produkten, egal ob phase6 desktop, phase6 cloud oder den Lerninhalten<\/p> <p>Ihre Vorteile noch einmal im \u00dcberblick:<\/p> <p>&#8211; 1x zahlen = 3x nutzen (Mac\/PC, iPhone und iPad)<br \/> &#8211; Kostenlose Updates Ihrer gekauften Lerninhalte<br \/> &#8211; Immer und \u00fcberall lernen<br \/> &#8211; Unterst\u00fctzt das hochaufl\u00f6sende Retina-Display Ihres iPad<br \/> &#8211; Nur 9,99 \u20ac f\u00fcr jeden Lerninhalt<br \/> &#8211; Kostenloses phase6 mobile f\u00fcr iPhone und iPad<\/p> <p>Worauf warten Sie noch?<\/p> <p>Schauen Sie noch heute vorbei und \u00fcberzeugen Sie sich selbst. Ob in der Uni, in der Fachhochschule, am Arbeitsplatz, in der Berufsausbildung, in der Erwachsenenbildung oder zu Hause und unterwegs, alle Lerninhalte der Utrata &amp; Riedel Verlagsgesellschaft unterst\u00fctzen sie jederzeit und effektiv in Ihrer pers\u00f6nlichen Art des Lernens.<\/p> <p>Durch die kostenlosen Testdateien, k\u00f6nnen Sie jeden der Lerninhalte zeitlich unbegrenzt in reduziertem Umfang testen.<\/p> <p>phase6 bietet Ihnen f\u00fcr phase6 desktop ebenfalls eine kostenlose 20-t\u00e4gige Testversion in vollem Funktionsumfang an.<\/p> <p>phase6 mobile f\u00fcr iPhone und iPad erhalten Sie komplett kostenlos im Apple App Store von iTunes.<\/p> <p>Microsoft, Windows are registered trademarks of Microsoft Corporation in the U.S.A. and\/or other regions\/countries.<br \/> Apple, Mac, Mac OS X, iPhone, iPad, Retina are trademarks of Apple Inc., registered in the U.S. and other countries.<\/p> <p>Utrata &amp; Riedel Verlagsgesellschaft bR<br \/> J\u00fcrgen Utrata und Stefan Riedel<br \/> Buschweg 10<br \/> 45896 Gelsenkirchen<\/p> <p>Tel: +49 (0)2 09 &#8211; 98 89 12 28<br \/> Fax: +49 (0)2 09 &#8211; 77 98 30 97<\/p> <p>E-Mail: info@utrata-und-riedel.de<br \/> Internet: http:\/\/www.utrata-und-riedel.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Utrata &amp; Riedel Verlagsgesellschaft bR ist ein junger Verlag der Anfang des Jahres 2012, von J\u00fcrgen Utrata und Stefan Riedel, gegr\u00fcndet wurde. In Gelsenkirchen, mitten im Herzen des Ruhrgebiets angesiedelt, dem gr\u00f6\u00dften Ballungsgebiet und Logistikstandort Europas, sind die Firmengr\u00fcnder tief verwurzelt mit den vielf\u00e4ltigen \u00c4sten des Transport- und Logistikwesens in der Verkehrswirtschaft. Ziel ist<\/p>\n","protected":false},"author":3,"featured_media":197645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-46934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transport-logistik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/46934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=46934"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/46934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197645"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=46934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=46934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=46934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}