{"id":48104,"date":"2012-09-20T13:55:20","date_gmt":"2012-09-20T12:55:20","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=48104"},"modified":"2025-10-31T13:35:05","modified_gmt":"2025-10-31T12:35:05","slug":"positive-resonanz-aber-auch-kritik","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/positive-resonanz-aber-auch-kritik-1048104\/","title":{"rendered":"Positive Resonanz, aber auch Kritik"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-48105\" title=\"Kein Anbieterwechsel, keine Mindestvertragslaufzeit, kein Verbindungsentgelt, kein Mindestumsatz und keine versteckten Kosten.\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/06b0bebf8d5745575129dd7037dda310.jpg\" alt=\"\" width=\"105\" height=\"112\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/73532871c6f06d1c0e179093f41c3296.jpg\" \/>Die in den letzten Wochen durchgef\u00fchrte Kundenzufriedenheitsumfrage ergab eine sehr positive Resonanz, aber auch einige Kritikpunkte.<\/p> <p>Bei der Nutzung der Dienste lag VoIP deutlich vorne, gefolgt von Callthrough und Callback. Die Bewertung in Bezug auf die Qualit\u00e4t und Benutzerfreundlichkeit der Dienste ergab, dass knapp 88% der VoIP Nutzer zufrieden waren. Diejenigen Kunden, die auch Callback und Callthrough genutzt haben, waren mit der Qualit\u00e4t zu durchschnittlich 85% zufrieden, w\u00e4hrend sie die Benutzerfreundlichkeit mit ca. 79% einstuften.<\/p> <p><!--more-->Es zeigte sich, dass bei den beiden Diensten scheinbar noch einiger Informationsbedarf hinsichtlich der Nutzungsm\u00f6glichkeiten und dem Endpreis herrscht. Hier arbeiten wir dran. In absehbarer Zeit werden wir eine \u00fcberarbeitete Tarifseite einstellen, wo auch Anwendungsbeispiele sowie deren Preiszusammensetzung erl\u00e4utert werden.<\/p> <p>In Bezug auf die Gestaltung der Webseite gab es durchweg positive Kritik. Die Zufriedenheit in den Bereichen Verst\u00e4ndlichkeit, \u00dcbersichtlichkeit und Vollst\u00e4ndigkeit lag zwischen 87 und 93%. Die Gestaltung der Webseite warf aber einige Fragen auf. Einige Kunden fanden die Seite zu voll, w\u00e4hrend andere wiederum zu sp\u00e4rliche Informationen bem\u00e4ngelten. Hier werden wir uns bem\u00fchen zuk\u00fcnftig Inhalte sowohl f\u00fcr Experten und Neulinge anzubieten.<\/p> <p>Zwei Hauptkritikpunkte werden wir kurzfristig beheben.<br \/> Damit Sie als Neukunde sofort von den Vorz\u00fcgen von Ventengo profitieren k\u00f6nnen, werden wir ihnen Anfang Oktober eine L\u00f6sung pr\u00e4sentieren. Schauen Sie einfach in der ersten Oktoberwoche noch einmal auf die Webseite von Ventengo und lassen sich \u00fcberraschen.<\/p> <p>Au\u00dferdem wurde gew\u00fcnscht, dass als abgehende Rufnummer die eigene Festnetznummer eingetragen werden kann. Hier arbeiten wir mit Hochdruck an einer L\u00f6sung und werden diese noch im vierten Quartal vorstellen.<\/p> <p>Als Fazit l\u00e4sst sich feststellen, das \u00fcber 86% der Kunden Ventengo weiterempfehlen w\u00fcrden. Wir arbeiten daran, dass auch die restlichen 14% zufriedene Kunden werden!<\/p> <p>Impressum:<br \/> Impressum<br \/> Ventelo GmbH<br \/> Mathias-Br\u00fcggen-Str. 55<br \/> 50829 K\u00f6ln<\/p> <p>Tel.: +49 (0)221 6698 010<br \/> Fax: +49 (0)221 6698 019<br \/> Mail: info@ventelo.de<\/p> <p>Vertretungsberechtigte Gesch\u00e4ftsf\u00fchrer:<br \/> Christof Sommerberg<br \/> Dietmar Becker<br \/> Tel.: +49 (0)221 6698 010<br \/> Fax: +49 (0)221 6698 019<br \/> Mail: info@ventelo.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Die in den letzten Wochen durchgef\u00fchrte Kundenzufriedenheitsumfrage ergab eine sehr positive Resonanz, aber auch einige Kritikpunkte. Bei der Nutzung der Dienste lag VoIP deutlich vorne, gefolgt von Callthrough und Callback. Die Bewertung in Bezug auf die Qualit\u00e4t und Benutzerfreundlichkeit der Dienste ergab, dass knapp 88% der VoIP Nutzer zufrieden waren. Diejenigen Kunden, die auch Callback<\/p>\n","protected":false},"author":3,"featured_media":48105,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-48104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handy-elektronik-telekommunikation"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/48104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=48104"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/48104\/revisions"}],"predecessor-version":[{"id":278056,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/48104\/revisions\/278056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/48105"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=48104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=48104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=48104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}