{"id":48970,"date":"2012-10-19T10:28:17","date_gmt":"2012-10-19T09:28:17","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=48970"},"modified":"2012-10-19T10:28:17","modified_gmt":"2012-10-19T09:28:17","slug":"unterstuetzung-bei-lernschwaechen-und-vorhandenen-wissensluecken","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/unterstuetzung-bei-lernschwaechen-und-vorhandenen-wissensluecken-1048970\/","title":{"rendered":"Unterst\u00fctzung bei Lernschw\u00e4chen und vorhandenen Wissensl\u00fccken"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-48971 alignleft\" title=\"qualifizierte Lehrkr\u00e4fte arbeiten nach den aktuellen Lehrpl\u00e4nen der einzelnen Schultypen und verwenden die Lehrb\u00fccher, die Ihr Kind auch aus der Schule kennt.\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/748cfc4857e0a1d430ca58625dbe11d8.jpg\" alt=\"\" width=\"119\" height=\"119\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/2f778e7659f4b4ed00c6a38e94ca9e95.jpg\" \/>(M\u00fcnchen). Zur Nachhilfe zu gehen, ist in Bayern ganz normal: Unser Bundesland liegt in den \u201eTop Drei\u201c der L\u00e4nder, in denen die Eltern Geld f\u00fcr Nachhilfe ausgeben. Noch lernfreudiger sind nur die Baden-W\u00fcrttemberger. Das zeigt eine Umfrage der Bertelsmann Stiftung aus diesem Jahr. Doch nicht nur Sch\u00fcler haben Bedarf an zus\u00e4tzlichen Unterrichtsstunden, sondern auch kaufm\u00e4nnische Auszubildende, die sich auf die IHK-Pr\u00fcfung vorbereiten oder Erwachsene, die sich im kaufm\u00e4nnischen Bereich weiterbilden m\u00f6chten. In M\u00fcnchen bietet die Bildungseinrichtung lern.de\u00ae (http:\/\/www.lern.de ) ab dem nun beginnenden Winterhalbjahr 2012 Nachhilfe in allen F\u00e4chern f\u00fcr jede Altersklasse und verschiedene Schultypen an; ebenso Weiterbildung f\u00fcr Erwachsene.<\/p> <p><!--more-->Lernf\u00f6rderung finanziert mit dem Bildungspaket<br \/> \u201eBei lern.de\u00ae bekommen die Sch\u00fcler eine optimale Unterst\u00fctzung bei Lernschw\u00e4chen und vorhandenen Wissensl\u00fccken, damit Schule und Lernen wieder Spa\u00df machen\u201c, erkl\u00e4rt Inhaber Sascha Jankovic. \u201eWir wollen die Kinder und junge Erwachsene individuell f\u00f6rdern. Die Nachhilfetermine k\u00f6nnen dabei auch am Wochenende oder abends stattfinden, so dass der Nachhilfeunterricht sich gut mit dem restlichen Tagesablauf vereinbaren l\u00e4sst\u201c. Wie oft die Sch\u00fcler w\u00f6chentlich eine professionelle Betreuung ben\u00f6tigen, k\u00f6nnen sie beziehungsweise ihre Eltern selbst festlegen. Der Nachhilfeunterricht erfolgt generell einzeln, auf Wunsch in Kleingruppen bis maximal drei Sch\u00fcler.<br \/> Tipp: Mit dem sogenannten Bildungspaket unterst\u00fctzt das Bundesministerium f\u00fcr Arbeit und Soziales Familien mit niedrigem Einkommen; auch Nachhilfe f\u00e4llt unter dieses Paket. F\u00fcr Antragssteller bedeutet dass, dass sie unter Umst\u00e4nden auch bei der M\u00fcnchner Bildungseinrichtung f\u00fcr nur f\u00fcnf Euro pro Stunde Unterricht nehmen k\u00f6nnen.<\/p> <p>Lehrer reden mit<br \/> Das Team von lern.de\u00ae ist seit 1999 erfolgreich in M\u00fcnchen im Bildungsbereich t\u00e4tig. Die Nachhilfekr\u00e4fte arbeiten nach den aktuellen Lehrpl\u00e4nen der einzelnen Schultypen und verwenden die Lehrb\u00fccher, die auch aus der Schule bekannt sind. Zudem baut die Einrichtung auf Wunsch engen Kontakt mit den Schulen und Lehrern auf, die Eltern erhalten auf Wunsch regelm\u00e4\u00dfig einen Zwischenstand des Lernerfolges ihres Kindes. Weitere Informationen zur M\u00fcnchner Bildungseinrichtung und einen Gutschein f\u00fcr eine kostenlose Probestunde gibt es bei lern.de\u00ae, Sascha Jankovic, Hoheneckstr. 70, 81243 M\u00fcnchen, zentrale Terminvereinbarungen unter 089 &#8211; 96 19 96 30 oder <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.lern.de\" title=\"lern.de bietet effektive, erfolgreiche und preiswerte Nachhilfe und Pr\u00fcfungsvorbereitung f\u00fcr alle F\u00e4cher, Klassenstufen und Schultypen an.\" >http:\/\/www.lern.de<\/a> .<\/p> <p>Impressum:<br \/> Fa. lern.de\u00ae e.K.<br \/> Zentrale Sitz: Hoheneckstr. 70, 81243 M\u00fcnchen<br \/> Telefon: +49 (0)89 &#8211; 96 19 96 30<br \/> Telefax: +49 (0)89 &#8211; 20 32 32 14<br \/> E-Mail: presse@lern.de<br \/> Gesch\u00e4ftsf\u00fchrer und Inhaber: Sascha Jankovic<br \/> Handelsregisternummer: Amtsgericht M\u00fcnchen HRA 96844<br \/> http:\/\/www.lern.de<br \/> http:\/\/twitter.com\/lernde<br \/> http:\/\/www.facebook.com\/lern.de<br \/> http:\/\/plus.google.com\/102388087999969728592<\/p>","protected":false},"excerpt":{"rendered":"<p>(M\u00fcnchen). Zur Nachhilfe zu gehen, ist in Bayern ganz normal: Unser Bundesland liegt in den \u201eTop Drei\u201c der L\u00e4nder, in denen die Eltern Geld f\u00fcr Nachhilfe ausgeben. Noch lernfreudiger sind nur die Baden-W\u00fcrttemberger. Das zeigt eine Umfrage der Bertelsmann Stiftung aus diesem Jahr. Doch nicht nur Sch\u00fcler haben Bedarf an zus\u00e4tzlichen Unterrichtsstunden, sondern auch kaufm\u00e4nnische<\/p>\n","protected":false},"author":3,"featured_media":48971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-48970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familie-jugend-familie"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/48970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=48970"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/48970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/48971"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=48970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=48970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=48970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}