{"id":50929,"date":"2012-12-28T11:26:09","date_gmt":"2012-12-28T10:26:09","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=50929"},"modified":"2021-01-15T12:22:26","modified_gmt":"2021-01-15T11:22:26","slug":"stiftung-medienopfer-die-neue-tv-diktatur-immer-mehr-kaempfen-gegen-die-neue-gez-zwangsabgabe","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/stiftung-medienopfer-die-neue-tv-diktatur-immer-mehr-kaempfen-gegen-die-neue-gez-zwangsabgabe-1050929\/","title":{"rendered":"Stiftung Medienopfer: Die neue ,,TV-Diktatur&#8220; &#8211; Immer mehr k\u00e4mpfen gegen die neue GEZ-Zwangsabgabe"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"margin: 0px 10px 10px 0px;\" title=\"GEZ, nein danke!\" alt=\"\" src=\"http:\/\/pm.connektar.de\/informationen-medien\/stiftung-medienopfer-die-neue-tv-diktatur-immer-mehr-kaempfen-gegen-die-neue-gez-zwangsabgabe-5851\/anhang\/gezneindanke.jpg?b=200&amp;h=200\" width=\"132\" height=\"92\" \/>Immer mehr B\u00fcrger, Institutionen, B\u00fcndnisse und Anw\u00e4lte k\u00e4mpfen gegen den ARD\/ZDF Rundfunkbeitrag, der ab 1. Januar 2013 alle Haushalte betrifft. wir sagen Ihnen, wie Sie sich wehren k\u00f6nnen<\/p> <p>Der ab 1. Januar 2013 verbindliche Rundfunkbeitrag, der f\u00fcr jeden Haushalt verpflichtend gilt, ist verfassungswidrig, sagen verschiedene Rechtsanw\u00e4lte aber auch zwei der renommiertesten deutschen Verfassungsrechtler: Professor Ingo von M\u00fcnch und Prof. Dr. Christoph Degenhart. <!--more-->Die Abgabe, die unabh\u00e4ngig vom Vorhandensein eines Fernseh- oder Radioempfangsger\u00e4tes geleistet werden muss, verst\u00f6\u00dft ihrer Ansicht nach sowohl gegen Artikel 3 als auch Artikel 2 des Grundgesetzes (Eingriff in das Grundrecht auf freie Entfaltung). Auch die Bild-Zeitung berichtet vom Aufschrei der Vereine, Verb\u00e4nde und B\u00fcrger. In Internetforen wird die GEZ als UnGEZiefer, Mafia und Abzockerbande beschimpft. Eine Klage vor dem Bayerischen Verfassungsgericht will nun die Frage kl\u00e4ren, ob es sich bei diesem Beitrag nicht um eine Zwangssteuer handelt.<\/p> <p>Einzugserm\u00e4chtigung widerrufen<\/p> <p>Doch was kann man tun, um diese ungerechte &#8222;Steuer&#8220;, die auch blinde, sehbehinderte, demenzkranke und taube Menschen &#8211; wenn auch mit einem reduzierten Beitrag &#8211; betrifft, zu bek\u00e4mpfen?<br \/> Die Stiftung Medienopfer hat dabei eine sehr effektiven Vorschlag: Widerrufen Sie noch in diesem Jahr die Einzugserm\u00e4chtigung der GEZ bei Ihrer Bank oder Ihrem Kreditinstitut. Dann muss die GEZ reagieren. Notfalls muss dann gerichtlich gepr\u00fcft werden, ob der neue Beitrag \u00fcberhaupt rechtm\u00e4\u00dfig ist.<br \/> Die Stiftung Medienopfer geh\u00f6rte zu den ersten, die nach Expertisen, die sie anfertigen lie\u00df, die Verfassungswidrigkeit des neuen Rundfunkbeitrages als gegeben sah. Schon jetzt bereite man f\u00fcr etliche B\u00fcrger, die sich dazu entschlossen haben, die kommenden neuen Beitragsbescheide anzugreifen, entsprechende Klagen vor. Juristen erwarten nun einen massiven Druck auf die Landesrundfunkanstalten.<\/p> <p>Die Datenproblematik &#8211; GEZ schafft bundesweites Datenregister<\/p> <p>Die Stiftung Medienopfer wird versuchen, die Rechte der B\u00fcrger vor den zust\u00e4ndigen Instanzen mit Hilfe spezialisierter Anw\u00e4lte durchzusetzen. N\u00f6tigenfalls auch vor dem Bundesverfassungsgericht.<br \/> Es stellt sich ja auch die Frage, ob die Daten\u00fcbermittlung, die alle Melde\u00e4mter in ganz Deutschland an die GEZ veranlassen werden, nicht einen Versto\u00df gegen das Grundrecht auf informationelle Selbstbestimmung darstellt. Schlie\u00dflich werden bundesweit Daten von der GEZ gesammelt, obwohl die GEZ keine staatliche Stelle ist.<\/p> <p>Der Rundfunkbeitrag ist die GEZ-Geb\u00fchr im Schafspelz<\/p> <p>Da hat man sich einen sch\u00f6nen Namen ausgedacht: &#8222;ARD\/ZDF Deutschlandradio Rundfunkbeitrag&#8220; oder &#8222;Haushaltsabgabe&#8220; hei\u00dft die alte unbeliebte GEZ-Geb\u00fchr ab Januar. Wer aber einen Beitrag bezahlt, muss einen Nutzen aus dieser Abgabe ziehen k\u00f6nnen. Das ist aber nicht wirklich ersichtlich. Was ist mit den Menschen, die keine Ger\u00e4te besitzen, was mit den blinden, sehbehinderten, den tauben Menschen? Wer also den Rundfunkbeitrag bezahlen muss, obwohl er keine Empfangsger\u00e4te besitzt, oder aufgrund k\u00f6rperlicher Begebenheiten nicht nutzen kann, hat keinen Nutzen und bekommt auch keine Gegenleistung. Und schon ist der Beitrag kein Beitrag mehr, sondern vielmehr eine Steuer. Doch darf denn ein Land so eine versteckte Steuer erheben? Gibt es daf\u00fcr Gesetzesgrundlagen?<br \/> Wir werden das pr\u00fcfen, und freuen uns, das der Widerstand von Tag zu Tag gr\u00f6\u00dfer wird.<\/p> <p>Mit freundlichen Gr\u00fc\u00dfen<\/p> <p>Sascha Giller<br \/> Vorstandsvorsitzender der www.stiftung-medienopfer.de<br \/> kontakt@stiftung-medienopfer.de<img decoding=\"async\" alt=\"\" src=\"http:\/\/connekt.connektar.de\/s\/?16db-ba-68a40\" \/><\/p> <p>\u00dcber:<\/p> <p>Stiftung Medienopfer<br \/> Herr Sascha Giller<br \/> Bergstra\u00dfe 21<br \/> 99192 Neu-Dietendorf<br \/> Deutschland<\/p> <p>fon ..: 0162-9809706<br \/> web ..: http:\/\/www.stiftung-medienopfer.de<br \/> email : kontakt@stiftung-medienopfer.de<\/p> <p><span style=\"font-style: italic;\">Die Stiftung Medienopfer setzt sich f\u00fcr die Interessen und Rechte von Fernsehzuschauern und Zeitungslesern ein.<br \/> Bei rechtlichen Auseinandersetzungen werden spezialisierte Fachanw\u00e4lte eingeschaltet.<\/span><\/p> <p>Pressekontakt:<\/p> <p>Journalistenwatch.com<br \/> Herr Thomas B\u00f6hm<br \/> L\u00f6bdergraben 11a<br \/> 07743 Jena<\/p> <p>fon ..: 0170-9290030<br \/> web ..: http:\/\/www.journalistenwatch.com<br \/> email : chefredaktion@journalistenwatch.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Immer mehr B\u00fcrger, Institutionen, B\u00fcndnisse und Anw\u00e4lte k\u00e4mpfen gegen den ARD\/ZDF Rundfunkbeitrag, der ab 1. Januar 2013 alle Haushalte betrifft. wir sagen Ihnen, wie Sie sich wehren k\u00f6nnen<\/p>\n","protected":false},"author":3,"featured_media":197543,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[473],"tags":[1799,2335,2334,2333,2336],"class_list":["post-50929","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medien-journalismus","tag-fernsehen","tag-gez","tag-oeffentlich-rechtliches-fernsehen","tag-tv","tag-zwangsgebuehr"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/50929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=50929"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/50929\/revisions"}],"predecessor-version":[{"id":273130,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/50929\/revisions\/273130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197543"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=50929"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=50929"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=50929"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}