{"id":51966,"date":"2013-02-01T13:38:00","date_gmt":"2013-02-01T12:38:00","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=51966"},"modified":"2021-07-12T08:51:45","modified_gmt":"2021-07-12T07:51:45","slug":"mit-einigen-geschickt-geplanten-brueckentagen-laesst-sich-somit-die-ferienzeit-verdoppeln","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/mit-einigen-geschickt-geplanten-brueckentagen-laesst-sich-somit-die-ferienzeit-verdoppeln-1051966\/","title":{"rendered":"Mit einigen geschickt geplanten Br\u00fcckentagen l\u00e4sst sich somit die Ferienzeit verdoppeln"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-52009\" title=\"Cavalaire sur mer\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/a42822255421002924b078470f3aef22.jpg\" width=\"125\" height=\"113\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/9d70e07f889dccf8be607acd88d582b5.jpg\" \/>Hier in Deutschland scheint es, als habe der Winter jetzt erst richtig angefangen. Minusgrade und Schneetreiben lassen uns vertr\u00e4umt an Sonne, Strand und Meer denken. W\u00e4hrend die Hoteliers noch die Zimmer herrichten und alles f\u00fcr die kommende Urla ubssaison vorbereiten, sollten Urlauber schon mal genau in ihren Kalender schauen. Jutta Hubracht, Inhaberin des \u201eHotel Villa Provencale\u201c in S\u00fcdfrankreich, hat sich \u00fcber die Br\u00fcckentage 2013 schon mal Gedanken gemacht. Denn selten war ein Jahr so \u201earbeitnehmerfreundlich\u201c wie das Jahr 2013 es sein wird. <!--more-->Alle bundesweiten Feiertage fallen auf einen Wochentag. Mit einigen geschickt geplanten Br\u00fcckentagen l\u00e4sst sich somit die Ferienzeit verdoppeln! Warum also nicht jetzt schon ein verl\u00e4ngertes Wochenende an der C\u00f4te d&#8217;Azur planen?<\/p> <p>Ostereier am Strand suchen<br \/> So k\u00f6nnte man sich die Zeit um Ostern f\u00fcr einen sch\u00f6nen Familienurlaub freinehmen. Mit dem Einsatz von gerade einmal 8 Urlaubstagen kann man dann glatt 16 Tage in die Ferien fahren, und zwar von 25. M\u00e4rz bis zum 8. April. W\u00e4hrend man um diese Jahreszeit in Deutschland noch auf eine warme Jacke angewiesen ist, herrschen in Frankreich an der C\u00f4te d&#8217;Azur bereits Temperaturen um die 20 Grad.<\/p> <p>Goldene Herbsttage an derC\u00f4te d&#8217;Azur<br \/> Der Tag der Deutschen Einheit ist 2013 ein Donnerstag. Also lohnt es sich auch hier, einen Br\u00fcckentag zu nehmen und das verl\u00e4ngerte Wochenende vielleicht sogar f\u00fcr einen sch\u00f6nen Herbsttrip zu nutzen. Ein paar entspannte Tage in S\u00fcdfrankreich am Meer sind da doch dem regnerischen Wetter in Deutschland vorzuziehen!<\/p> <p>Wer jetzt in Urlaubsstimmung gekommen ist, sollte nicht all zu lange mit der Planung warten. Schon fr\u00fch werden die verl\u00e4ngerten Wochenenden ausgebucht sein. Weitere Informationen unter www.hotelvillaprovencale.com und planen Sie den Urlaub 2013.<\/p> <p>Weitere Informationen und Angaben finden Sie unter http:\/\/www.hotelvillaprovencale.com\/.<\/p> <p>\u00dcber :<br \/> Das im provenzalischen Stil renovierte Hotel Villa Provencale ist ein sympathisches und charmantes Hotel und steht unter der Leitung der beiden deutschen \u201eAuswanderer\u201c Jutta und Rudolf Hubracht. Es liegt im S\u00fcden Frankreichs direkt an der C\u00f4te d&#8217;Azur in der Stadt Cavalaire sur mer. Der feine Sandstrand ist bequem zu Fu\u00df erreichbar (600 Meter). Das inhabergef\u00fchrte Hotel punktet mit 22 stil- und geschmackvoll eingerichteten Zimmern, die teilweise mit einem Balkon oder einer Terrasse ausgestattet sind. Ein Restaurant mit provenzalischer K\u00fcche sowie der hoteleigene mediterrane Garten laden zum Entspannen und Genie\u00dfen ein. Im Hotel wird flie\u00dfend deutsch, franz\u00f6sisch, englisch und italienisch gesprochen. Weitere Informationen unter: www.hotelvillaprovencale.com<\/p> <p>Pressekontakt:<br \/> Hotel Villa Provencale<br \/> Edda R\u00f6ssler<br \/> Rue des Maures<br \/> 83240 Cavalaire sur mer<br \/> Frankreich<br \/> 069-514461<br \/> er@roesslerpr.de<br \/> http:\/\/www.hotelvillaprovencale.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Hier in Deutschland scheint es, als habe der Winter jetzt erst richtig angefangen. Minusgrade und Schneetreiben lassen uns vertr\u00e4umt an Sonne, Strand und Meer denken. W\u00e4hrend die Hoteliers noch die Zimmer herrichten und alles f\u00fcr die kommende Urla ubssaison vorbereiten, sollten Urlauber schon mal genau in ihren Kalender schauen. Jutta Hubracht, Inhaberin des \u201eHotel Villa<\/p>\n","protected":false},"author":3,"featured_media":197451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8804],"tags":[],"class_list":["post-51966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reisen"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/51966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=51966"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/51966\/revisions"}],"predecessor-version":[{"id":273758,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/51966\/revisions\/273758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197451"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=51966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=51966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=51966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}