{"id":5215,"date":"2010-04-23T17:47:57","date_gmt":"2010-04-23T16:47:57","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=5215"},"modified":"2024-09-20T10:59:58","modified_gmt":"2024-09-20T09:59:58","slug":"pollen-radar-auf-das-iphone","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/pollen-radar-auf-das-iphone-105215\/","title":{"rendered":"OMD D\u00fcsseldorf und CLANMO lassen Allergiker aufatmen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5218\" title=\"Pollenradar_ Home.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/5215\/Pollenradar_ Home-200x300.jpg\" alt=\"\" width=\"120\" height=\"181\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/5215\/Pollenradar_%20Home-200x300.jpg 200w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/5215\/Pollenradar_%20Home.jpg 320w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Der ratiopharm \u201ePollen-Radar\u201c kommt mittels Gratis-App auf das iPhone<br \/> F\u00fcr Heuschnupfen-Allergiker ist Erleichterung in Sicht: per kostenloser iPhone App k\u00f6nnen sich Betroffene jetzt mobil \u00fcber die Pollenbelastung in ihrer Umgebung informieren und wer-den so vor der n\u00e4chsten Nies-Attacke gewarnt.<br \/> Die von OMD D\u00fcsseldorf konzipierte und den Mobile-Experten CLANMO in Zusammenarbeit mit OMG 4CE umgesetzte App \u201ePollen-Radar\u201c enth\u00e4lt neben ortsbasierten Informationen \u00fcber die aktuelle Belastung von 14 Pollen auch eine Drei-Tages-Vorhersage.<!--more-->Damit sind zum ersten Mal die von wetter.online erhobenen Informationen \u00fcber die regionale Pollenbelas-tung per Handy verf\u00fcgbar.<br \/> Der \u201ePollen-Radar\u201c bietet zudem viele n\u00fctzliche Tipps rund um das Thema, so wie eine GPS-basierte Apothekensuche und ist der aktuell umfangreichste \u201eHeuschnupfen\u201c-Service, der kostenlos mobil erh\u00e4ltlich ist.<\/p> <p>\u201eDer ratiopharm \u201ePollen-Radar\u201c ist ein gutes Beispiel f\u00fcr die konsequente Ausdehnung einer funktionierenden Produkt- und Markenwelt auf den Kanal Mobile. Die App \u00fcberzeugt mit ei-nem extrem hohen Nutzwert f\u00fcr den User und ist damit ein ideales Instrument zur Kunden-bindung\u201c, so Joachim Bader, Gesch\u00e4ftsf\u00fchrer von CLANMO.<br \/> \u00dcber OMD:<br \/> OMD Germany ist die am schnellsten wachsende Mediaagentur Deutschlands und geh\u00f6rt zur OMD Worldwide (www.omd.com), der weltweit gr\u00f6\u00dften Mediaagenturgruppe mit 140 B\u00fcros in 80 L\u00e4ndern und \u00fcber 8.000 Angestellten. OMD Germany betreibt f\u00fcnf Niederlassungen in vier St\u00e4dten (D\u00fcssel-dorf, Hamburg, M\u00fcnchen, Berlin) und besch\u00e4ftigt \u00fcber 500 Mitarbeiter.<br \/> Im aktuellen RECMA-Ranking der gr\u00f6\u00dften deutschen Agenturen belegt OMD Germany erneut den zweiten Platz. Zum wiederholten Male wurde der Agentur vom renommierten Fachmagazin \u201eAdweek\u201c der Titel \u201eMedia Agency of the Year\u201c zugesprochen. Dar\u00fcber hinaus f\u00fchrt OMD im f\u00fcnften Jahr in Fol-ge das Kreativ-Ranking des \u201eGunn Report for Media\u201c an.<br \/> \u00dcber OMG 4CE:<br \/> Die OMG 4CE GmbH ist die Spezialagentur f\u00fcr Digital Media, Branded Content und Dialog Marketing der Omnicom Media Group Germany. Die Omnicom Media Group (OMG) ist der internationale Media-<br \/> Arm der weltweit gr\u00f6\u00dften Kommunikations- und Marketingdienstleistungsgruppe Omnicom und um-fasst zwei der f\u00fchrenden Media-Agenturnetworks OMD und PHD.<br \/> \u00dcber CLANMO:<br \/> Die CLANMO GmbH (http:\/\/www.clanmo.com) ist eine hochdekorierte Agentur f\u00fcr Mobile Interaction. Sie betreut Kunden sowohl strategisch als auch konzeptionell bei der mobilen Markenf\u00fchrung und der Entwicklung des mobilen Service-Portfolios. Schwerpunktbranchen sind Travel, Automotive, Fashion, Lifestyle und Telekommunikation. Die Arbeit von CLANMO zeichnet sich nachhaltig durch hohe Quali-t\u00e4t und Innovationskraft aus. F\u00fcr Kunden wie zum Beispiel IKEA, Lufthansa und Konami erarbeitete CLANMO mehrfach Projekte, die sich zu Industry-Benchmarks entwickelten und mit zahlreichen A-wards ausgezeichnet wurden. Unter anderem gewann CLANMO den Global Mobile Award 2010 f\u00fcr die IKEA PS Einrichtungskamera. Von den Standorten M\u00fcnchen und K\u00f6ln aus unterst\u00fctzt CLANMO Kunden mit einem Full-Serviceangebot aus strategischer Beratung, Kreation und hauseigener Mobile Technologie. Dabei liefert CLANMO das gesamte Mobile Portfolio aus einer Hand: Kampagnenkreati-on, Applikationsentwicklung, Mobile Internet und Mobile Mediaplanung. Kunden sind u.a. Lufthansa, Konami, Europcar, Vodafone, T-Mobile, Hugo Boss und Porsche.<\/p> <p>Pressekontakt ClanMo:<br \/> Anke Piontek<br \/> forvision<br \/> Beratung f\u00fcr Marketing, PR und TV<br \/> Spichernstra\u00dfe 32<br \/> 50672 K\u00f6ln<br \/> tel: 0221\/51 09 16 90<br \/> fax: 0221\/51 09 16 9- 29<br \/> mail: info@forvision.de<br \/> http:\/\/www.forvision.de<\/p> <p><a href=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/5215\/Pollenradar_ Home.jpg\">Pollenradar_ Home.jpg (85 KB)<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Der ratiopharm \u201ePollen-Radar\u201c kommt mittels Gratis-App auf das iPhone F\u00fcr Heuschnupfen-Allergiker ist Erleichterung in Sicht: per kostenloser iPhone App k\u00f6nnen sich Betroffene jetzt mobil \u00fcber die Pollenbelastung in ihrer Umgebung informieren und wer-den so vor der n\u00e4chsten Nies-Attacke gewarnt. Die von OMD D\u00fcsseldorf konzipierte und den Mobile-Experten CLANMO in Zusammenarbeit mit OMG 4CE umgesetzte App<\/p>\n","protected":false},"author":291,"featured_media":5218,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-5215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=5215"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5215\/revisions"}],"predecessor-version":[{"id":276401,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5215\/revisions\/276401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/5218"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=5215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=5215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=5215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}