{"id":5232,"date":"2010-04-26T10:38:08","date_gmt":"2010-04-26T09:38:08","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=5232"},"modified":"2010-07-26T14:19:09","modified_gmt":"2010-07-26T13:19:09","slug":"fahrpersonal-zielgenau-koordinieren-und-steuern","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/fahrpersonal-zielgenau-koordinieren-und-steuern-105232\/","title":{"rendered":"Fahrpersonal zielgenau koordinieren und steuern"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5235\" title=\"LOGO-sms-ware-160x38.gif\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/5232\/LOGO-sms-ware-160x38.gif\" alt=\"\" width=\"160\" height=\"38\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Mit sms-ware Transport und Logistik wird das Fahrpersonal unkompliziert und schnell informiert und koordiniert. Speziell f\u00fcr die Transportbranche entwickelt, \u00fcberzeugt sms-ware Transport und Logistik mit umfangreichen Features. Das Produktportfolio von sms-ware, sms for business wurde aktuell um die L\u00f6sung sms-ware Transport und Logistik erweitert. Bereits seit 1994 entwickelt und integriert die BSC Computer Systeme GmbH  Kommunikationsl\u00f6sungen f\u00fcr Unternehmen verschiedenster Branchen.<br \/> SMS f\u00fcr Transport und Logistik<!--more--><br \/> Schnelle und gezielte Informations\u00fcbertragung spielt in mobil agierenden Branchen wie G\u00fcterbef\u00f6rderungen eine erhebliche Rolle. Hier setzt sms-ware Transport und Logistik an.<br \/> Speditionen und Transportunternehmen nutzen den kosteng\u00fcnstigen Kurznachrichten-Versand, um die interne Kommunikation mit ihrem Fahrpersonal sicher und unkompliziert abzuwickeln.<br \/> Tourenplanung, Touren\u00e4nderungen und Auftragsdaten k\u00f6nnen zeitnah oder terminiert \u00fcbermittelt werden. Dies birgt viele Vorteile gegen\u00fcber der klassischen Kommunikation per Telefon oder Funkverkehr.<br \/> Bequem vom PC aus sendet die Disposition schnell und eindeutige Anweisungen und Auftr\u00e4ge an das Fahrpersonal. Unn\u00f6tige Telefonate entfallen ebenso wie \u00dcbertragungsfehler bei der m\u00fcndlichen \u00dcbergabe von Daten.<br \/> Daneben bietet dies zus\u00e4tzlichen Komfort f\u00fcr den Fahrer, da zeitaufwendiges Notieren von Informationen w\u00e4hrend der Fahrt entfallen.<br \/> Auch der Kommunikation beim internationalen G\u00fcterverkehr steht hier nichts im Wege, da die Tarifstruktur keinen Unterschied zwischen nationalen und internationalen SMS macht.<br \/> sms-ware TL 2.0 ist eine einfach installierbare Desktop-Anwendung f\u00fcr den Versand an einzelne oder mehrere Empf\u00e4nger. Die komfortable Empf\u00e4ngerverwaltung erm\u00f6glicht auch unterschiedliche Sende-Listen (Verteiler) zur gleichzeitigen Ansprache von Benutzergruppen. Der Import von Empf\u00e4ngerdaten erspart das wiederholte Schreiben der Empf\u00e4ngerdaten. Nachrichten mit einer L\u00e4nge von \u00fcber 600 Zeichen sind kein Problem.<br \/> Die Software ist wahlweise als Einzelplatz oder im Netzwerk einsetzbar.<br \/> Optional kann die Integration in Applikationen oder Datenbanken (Speditionssoftware, CRM, ERP)  erreicht werden. Jede gew\u00fcnschte Statusmeldung, wie z.B. Auftragsbet\u00e4tigung und Versandinformation damit auch automatisiert versendet werden.<br \/> F\u00fcr die Nutzung der sms-ware Produkte wird keine zus\u00e4tzliche Hardware ben\u00f6tigt. Die Bereitstellung erfolgt \u00fcber Verbrauchslizenzen ohne Vertragsbindung und ohne monatliche Kosten. Der verschl\u00fcsselte Versand ist von jedem Internetf\u00e4higen PC bei minimalem Einrichtungsaufwand m\u00f6glich.<br \/> Interessenten erhalten eine kostenfreie Demolizenz inklusive  kostenfreiem SMS-Kontigent zum Testen.<br \/> Die BSC Computer Systeme GmbH ist seit 1991 erfolgreich als IT-Dienstleister im Bereich Kommunikation, Mobilit\u00e4t und IT-Systeml\u00f6sungen f\u00fcr das gesch\u00e4ftliche Umfeld t\u00e4tig.<br \/> Langj\u00e4hrige Erfahrung, hohes Produkt-KnowHow sowie ein dichtes Netzwerk von kompetenten Partnerunternehmen gew\u00e4hrleisten Unternehmenskunden branchen- und bedarfsgerechte L\u00f6sungen und eine optimale Betreuung.<br \/> Weitere Informationen zu den Produkten unter www.sms-ware.de oder per Mail anfordern unter info@sms-ware.de<br \/> Herstellerinformationen unter www.bsc-computer.de.<br \/> Kontakt:<br \/> BSC Computer Systeme GmbH<br \/> Gesch\u00e4ftsf\u00fchrer Reinhard M\u00fcller<br \/> Gewerbestr. 75<br \/> 79194 Gundelfingen<br \/> Tel: 0761 50459 0<br \/> Fax: 0761 50459 40<br \/> info@bsc-computer.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.bsc-computer.de\"  >http:\/\/www.bsc-computer.de<\/a><br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.sms-ware.de\"  >http:\/\/www.sms-ware.de<\/a><\/p> <p><a href=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/5232\/LOGO-sms-ware-160x38.gif\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Mit sms-ware Transport und Logistik wird das Fahrpersonal unkompliziert und schnell informiert und koordiniert. Speziell f\u00fcr die Transportbranche entwickelt, \u00fcberzeugt sms-ware Transport und Logistik mit umfangreichen Features. Das Produktportfolio von sms-ware, sms for business wurde aktuell um die L\u00f6sung sms-ware Transport und Logistik erweitert. Bereits seit 1994 entwickelt und integriert die BSC Computer Systeme GmbH<\/p>\n","protected":false},"author":291,"featured_media":5235,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-5232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transport-logistik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=5232"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/5235"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=5232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=5232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=5232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}