{"id":52534,"date":"2013-02-21T12:36:27","date_gmt":"2013-02-21T11:36:27","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=52534"},"modified":"2013-02-21T12:53:11","modified_gmt":"2013-02-21T11:53:11","slug":"schadensanalyse-und-zerstoerungsfreie-pruefung","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/schadensanalyse-und-zerstoerungsfreie-pruefung-1052534\/","title":{"rendered":"Schadensanalyse und zerst\u00f6rungsfreie Pr\u00fcfung"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-52535\" title=\"Die Ermittlung der Versagensursache ist Voraussetzung f\u00fcr die Schadensabhilfe\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/70a0c30e631e3c142c6930c4d1cf3cee.jpg\" width=\"104\" height=\"139\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/280155e59c7397a220134f8bb405d506.jpg\" \/>Ein Weiterbildungsangebot von Haus der Technik in Zusammenarbeit mit DGfZP e.V.<br \/> In dem Seminar am 26.-27. M\u00e4rz 2013 in Berlin wird die systematische Herangehensweise an die Schadensursachenermittlung vermittelt und diskutiert. Die Teilnehmer erfahren, wie man eine fundierte Schadensanalyse aufbaut und erhalten einen \u00dcberblick \u00fcber Schadensarten und -mechanismen sowie Untersuchungsmethoden anhand von Praxisbeispielen. In Gruppenarbeit werden die erworbenen Kenntnisse an Fallbeispielen gefestigt.<br \/> <!--more-->Sicherheit und Zuverl\u00e4ssigkeit sind heute unabdingbar f\u00fcr den Einsatz technischer Produkte. Trotz sorgf\u00e4ltiger Konstruktion und Herstellung aber auch auf Grund von Fehlern im Produktzyklus versagen Bauteile oft mit der Folge hoher wirtschaftlicher Verluste und \/ oder der Gef\u00e4hrdung von Menschenleben. Die Ermittlung der Versagensursache ist damit Voraussetzung f\u00fcr die Schadensabhilfe bzw. -verh\u00fctung und an vielen Stellen Initiator f\u00fcr technische Innovationen.<br \/> Ingenieure, Techniker und Fachkr\u00e4fte aus der Industrie k\u00f6nnen am 15.-16. April 2013 in Berlin die M\u00f6glichkeiten und Grenzen von physikalischen Verfahren der zerst\u00f6rungsfreien Pr\u00fcfung kennen lernen.<\/p> <p>1927 in Essen gegr\u00fcndet, ist das Haus der Technik (HDT) heute nicht nur das \u00e4lteste, sondern auch eines der f\u00fchrenden unabh\u00e4ngigen Weiterbildungsinstitute f\u00fcr Fach- und F\u00fchrungskr\u00e4fte Deutschlands. Rund 15.000 Teilnehmer nutzen j\u00e4hrlich die Einrichtungen in Essen und in den Zweigstellen in Berlin und M\u00fcnchen. Mit einem breiten Bildungsangebot in Technik, Wirtschaft, Elektrotechnik, Fahrzeugtechnik, Medizin, Chemie, Bauwesen, Qualit\u00e4tsmanagement und Umweltschutz konzentriert sich das HDT auf zukunftsweisende Kernbranchen. Mehr als 5.000 Referenten, ausgew\u00e4hlte Experten aus Wissenschaft und Wirtschaft, vermitteln jeweils Erkenntnisse aus ihren Fachgebieten \u2013 aktuell, praxisnah und wissenschaftlich fundiert. Ein eigenes Qualit\u00e4tsmanagementsystem sorgt f\u00fcr die Einhaltung der hohen Standards wie sie der Wuppertaler Kreis als Bundesverband f\u00fcr betriebliche Weiterbildung von seinen Mitgliedern fordert. Das HDT ist Au\u00dfeninstitut der Rheinisch-Westf\u00e4lischen Technischen Hochschule Aachen sowie Kooperationspartner der Universit\u00e4ten Bonn, Braunschweig, Duisburg-Essen und M\u00fcnster. Es unterh\u00e4lt zudem enge Kontakte zu Unternehmen und Forschungseinrichtungen und versteht sich als Forum f\u00fcr den Austausch von Wissen und Erfahrungen.<\/p> <p>N\u00e4here Informationen finden Interessierte beim Haus der Technik e.V. unter Tel. 030\/39493411 (Frau Dipl.- Ing.- p\u00e4d. Heike Cramer-Jekosch), Fax 030\/39493437 oder direkt unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.hdt-essen.de\" title=\"Berufsbegleitendes Studium, Seminare, Lehrg\u00e4nge und Tagungen im Haus der Technik \" >www.hdt-essen.de<\/a><br \/> Suchwort: DGFZP<\/p> <p>Haus der Technik<br \/> Karl-Liebknecht-Str. 29<br \/> 10178 Berlin<\/p> <p>Zweigstellenleiterin<br \/> Dipl.-Ing.-P\u00e4d.<br \/> Heike Cramer-Jekosch<br \/> h.cramer-jekosch@hdt-essen.de<br \/> Tel.: 030 39493411<br \/> Fax: 030 39493437<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein Weiterbildungsangebot von Haus der Technik in Zusammenarbeit mit DGfZP e.V. In dem Seminar am 26.-27. M\u00e4rz 2013 in Berlin wird die systematische Herangehensweise an die Schadensursachenermittlung vermittelt und diskutiert. Die Teilnehmer erfahren, wie man eine fundierte Schadensanalyse aufbaut und erhalten einen \u00dcberblick \u00fcber Schadensarten und -mechanismen sowie Untersuchungsmethoden anhand von Praxisbeispielen. In Gruppenarbeit werden<\/p>\n","protected":false},"author":3,"featured_media":52535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8806],"tags":[],"class_list":["post-52534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technik"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/52534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=52534"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/52534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/52535"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=52534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=52534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=52534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}