{"id":5590,"date":"2010-05-10T14:09:20","date_gmt":"2010-05-10T13:09:20","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=5590"},"modified":"2021-11-05T13:01:52","modified_gmt":"2021-11-05T12:01:52","slug":"kinder-fuer-elektronik-begeistern-2","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/kinder-fuer-elektronik-begeistern-2-105590\/","title":{"rendered":"Kinder f\u00fcr Elektronik begeistern"},"content":{"rendered":"<p><strong><em>Warum erzeugt eine Solarzelle Strom? Was ist der Unterschied zwischen Strom und Spannung? Wie bringe ich eine Gl\u00fchbirne zum Leuchten? <\/em><\/strong><\/p> <p>Seit drei Monaten ist die Website \u201eKleiner Ingenieur\u201c (www.kleiner-ingenieur.com) online und erfreut sich wachsender Beliebtheit.<\/p> <p>Das Internet-Angebot will Kinder im Alter von f\u00fcnf bis zehn Jahren f\u00fcr Elektronik begeistern, spricht aber auch Eltern, Erzieher und Lehrer an, die einen verst\u00e4ndlichen Einstieg in die Welt der Elektronik suchen.<!--more--><\/p> <p>Anleitungen f\u00fcr erste Experimente und Schaltungen, kindgerechte und anschauliche Erkl\u00e4rungen der wichtigsten Fachbegriffe und Komponenten regen zum Mitmachen und -denken an.<\/p> <p>Die Grundlagen der Elektronik beschr\u00e4nken sich bewusst auf Wissensgebiete, die f\u00fcr Kinder zwischen f\u00fcnf und zehn Jahren begreifbar sind. \u201eEin Sechsj\u00e4hriger muss nicht wissen, wie ein Transistor funktioniert oder wie und warum man ein Relais einsetzt\u00a0\u2013 er w\u00e4re damit schnell \u00fcberfordert und gelangweilt\u201c, begr\u00fcndet Betreiberin Carmen Skupin.<\/p> <p>Gro\u00dfen Wert legt die Website dagegen auf das Basteln mit elektronischen Bauelementen: \u201eAus elektronischen Bauteilen eigenh\u00e4ndig eine Schaltung aufzubauen, spielt f\u00fcr Kinder eine entscheidende Rolle um technische Prinzipien und Funktionsweisen zu begreifen\u201c, sagt Carmen Skupin.<\/p> <p>Nachwuchsprobleme in technischen Berufen und der Ingenieurmangel sind nicht zuletzt auf eine fehlende fr\u00fchkindliche F\u00f6rderung technischer Interessen zur\u00fcckzuf\u00fchren. W\u00e4hrend Technik alle Bereiche unseres Lebens durchdringt, vollzieht sich in der heranwachsenden Generation ein Wandel vom Konstruktiven zum Konsumtiven. Kinder setzen sich immer seltener mit der Funktionsweise von Technik auseinander \u2013 sie wird schlichtweg vorausgesetzt.<\/p> <p>Dabei ben\u00f6tigt gerade die junge Generation technische Kompetenzen, um Technik nutzen und herstellen zu k\u00f6nnen. Die wissenschaftliche Forschung spricht von \u201eTechniksozialisation\u201c, die Menschen von fr\u00fchester Kindheit an mit Technik vertraut macht, motiviert und Interesse weckt.<\/p> <p>Weitere Informationen:<\/p> <p>Website \u201eKleiner Ingenieur\u201c<\/p> <p>Verantwortliche Redakteurin:<\/p> <p>Carmen Skupin<\/p> <p>Wendelsteinstr. 11a<\/p> <p>D-85540 Haar<\/p> <p>Tel.: 089 43777141<\/p> <p>Fax: 089 43766621<\/p> <p>Email: cs@kleiner-ingenieur.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Warum erzeugt eine Solarzelle Strom? Was ist der Unterschied zwischen Strom und Spannung? Wie bringe ich eine Gl\u00fchbirne zum Leuchten? Seit drei Monaten ist die Website \u201eKleiner Ingenieur\u201c (www.kleiner-ingenieur.com) online und erfreut sich wachsender Beliebtheit. Das Internet-Angebot will Kinder im Alter von f\u00fcnf bis zehn Jahren f\u00fcr Elektronik begeistern, spricht aber auch Eltern, Erzieher und<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-5590","post","type-post","status-publish","format-standard","hentry","category-familie-jugend-familie"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=5590"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5590\/revisions"}],"predecessor-version":[{"id":273975,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5590\/revisions\/273975"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=5590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=5590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=5590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}