{"id":56310,"date":"2013-03-20T08:13:48","date_gmt":"2013-03-20T08:13:48","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=56310"},"modified":"2022-10-28T12:32:58","modified_gmt":"2022-10-28T11:32:58","slug":"online-marketing-auf-den-punkt-gebracht","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/online-marketing-auf-den-punkt-gebracht-1056310\/","title":{"rendered":"Online-Marketing auf den Punkt gebracht"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Der Marketing-Day Rheinland in M\u00f6nchengladbach\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/e6445e879a31f43453259046bade8325.jpg\" width=\"150\" height=\"150\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/e6445e879a31f43453259046bade8325.jpg\" \/>e-Marketingday Rheinland am 18. April 2013: Informationen rund um Online-Marketing f\u00fcr Unternehmen aus dem Mittelstand<\/p> <p>&#8211; Fach- und Anwenderforen sowie Begleitausstellung bieten Know-how und Austausch<br \/> &#8211; Studieninstitut f\u00fcr Kommunikation informiert \u00fcber Weiterbildungen f\u00fcr Online-Marketing<\/p> <p>Bereits zum dritten Mal pr\u00e4sentieren die Industrie- und Handelskammern im Rheinland den<br \/> e-Marketingday. Kleine und mittlere Unternehmen sind eingeladen, sich im Rahmen der Fach- und Anwenderforen sowie der Begleitausstellung ein vertieftes Bild zu Online-Marketing zu verschaffen. <!--more-->Den Impulsvortrag h\u00e4lt Ibrahim Evsan, Social Media-Vorreiter und Mitglied der Medienkommission der Landesanstalt NRW. Er berichtet \u00fcber die Zukunft und die Trends der digitalen Welt. Weitere Top-Referenten vermitteln in den Fachforen Wissen etwa zu Cross-Media-Marketing, Mobile-Marketing oder Werbung in Online-Games. Neu sind die Anwenderforen. Hier erl\u00e4utern Unternehmer ihre Erfahrungen hinsichtlich Ma\u00dfnahmen und erzielter Wirkung.<\/p> <p>Fachausstellung: weitere Inhalte zu Online-Marketing und Weiterbildung<br \/> Den ganzen Veranstaltungstag \u00fcber bietet die begleitende Fachausstellung allen Besuchern zudem noch mehr Informationen zu Themen des E-Marketings. Das Studieninstitut f\u00fcr Kommunikation pr\u00e4sentiert dazu seine Weiterbildungen. Michael Hosang, Gesch\u00e4ftsf\u00fchrer des Studieninstituts, erkl\u00e4rt: &#8222;Im Mittelstand zeigt sich ein gro\u00dfer Wissenshunger f\u00fcr Online-Marketing und folgerichtig auch f\u00fcr den Bereich Weiterbildung. Denn qualifiziertes Internet-Marketing erreicht der Unternehmer am besten durch ein gezieltes Invest in die eigenen Mitarbeiter.&#8220; Ziel des Studieninstituts ist es, Einsteigern ohne Vorkenntnisse wie auch Marketing-Fachkr\u00e4ften mit Vorkenntnissen Wissen im Bereich Online-Marketing zu vermitteln.<\/p> <p>Dazu geben die Fachberater des Studieninstituts eine kompakte \u00dcbersicht: F\u00fcr Einsteiger bietet sich der dreit\u00e4gige Grundlagen-Kurs Online-Marketing Basics an. F\u00fcr Mitarbeiter mit erstem Hintergrundwissen ist der berufsbegleitende Lehrgang zum Online-Marketing-Manager wie auch das FH-Studium zum Betriebswirt\/in Online-Marketing geeignet, um vorhandenes Know-how deutlich zu vertiefen. F\u00fcr Spezialisten bieten sich die Google Intensiv-Seminare Google AdWords und Google Analytics an.<\/p> <p>Weitere Informationen:<br \/> Basiskurs f\u00fcr Einsteiger &#8211; Online-Marketing Basics (komm) (http:\/\/www.studieninstitut.de\/online-marketing-basics)<br \/> Lehrgang f\u00fcr Fachkr\u00e4fte &#8211; Online-Marketing-Manager\/in (komm) (http:\/\/www.studieninstitut.de\/online-marketing)<br \/> Studium f\u00fcr Experten &#8211; Betriebswirt\/in (FH) f\u00fcr Online-Marketing (http:\/\/www.studieninstitut.de\/betriebswirt-online-marketing)<br \/> Spezialtrainings:<br \/> Google AdWords Professional: www.studieninstitut.de\/google-adwords-professional<br \/> Google Analytics Professional: www.studieninstitut.de\/google-analytics-professional<\/p> <p>Unternehmen k\u00f6nnen einzelne Aspekte der Weiterbildungen aus dem Bereich Online-Marketing als individuelle Trainings vor Ort durchf\u00fchren lassen. Weitere Informationen erhalten Sie gerne bei unserer Fachberatung, Fon 0211\/77 92 37-0,<br \/> beratung@studieninstitut.de.<\/p> <p>Informationen zum 3. e-Marketingday<br \/> Wann: 18. April 2013, 09:00 bis ca. 19:00 Uhr<br \/> Wo: Veranstaltungsort: Borussia-Park M\u00f6nchengladbach (f\u00fcr das Navigationssystem: Am Borussia Park),<br \/> Hennes-Weisweiler-Allee 1, 41179 M\u00f6nchengladbach<br \/> Veranstalter &amp; Organisation: Industrie- und Handelskammern im Rheinland<br \/> Informationen und Anmeldung: www.e-marketingday.de<\/p> <p>\u00dcber das Studieninstitut f\u00fcr Kommunikation:<br \/> Das Studieninstitut f\u00fcr Kommunikation ist Spezialist f\u00fcr praxisorientierte Weiterbildungen und Inhouse-Schulungen mit Fokus auf Event- und Messemanagement, Public Relations sowie Marketing und Kommunikation. Seit 1998 bietet das Studieninstitut neben wirtschaftsnahen Alternativen zu klassischer Ausbildung und Studium mit Basis- und Fortgeschrittenenkursen sowie IHK-Qualifizierungen ein breites Spektrum an Bildungsm\u00f6glichkeiten. Das starke Branchennetzwerk und das Portal Kjobs.de runden das Angebot ab. Experten aus Wirtschaft und Wissenschaft vermitteln direkt anwendbares Know-how. Langj\u00e4hrige Zusammenarbeit mit renommierten Agenturen und Unternehmen der Kommunikationsbranche garantieren praxisorientierte Wissensvermittlung f\u00fcr nachhaltige Erfolge der individuellen Karriereplanung. Seit 2006 engagiert sich das Studieninstitut als Initiator mit dem INA Nachwuchs Event Award f\u00fcr die Nachwuchsf\u00f6rderung. Seit 2012 wird zudem mit Partnern der Nachwuchs-Moderatoren-Wettbewerb ausgeschrieben. Zur Qualit\u00e4tssicherung werden die Weiterbildungskonzepte fortlaufend \u00fcberpr\u00fcft und den Marktbedingungen angepasst. Dar\u00fcber hinaus ist das Studieninstitut f\u00fcr Kommunikation seit 2011 nach DIN EN ISO 9001:2008 zertifiziert. Dies gew\u00e4hrleistet die systematische Erfassung der Kunden- und Branchenanforderungen. Ferner best\u00e4tigt die AZAV-Zertifizierung die Leistungsf\u00e4higkeit des Studieninstituts. Neben dem Hauptsitz in D\u00fcsseldorf hat das Studieninstitut Standorte in M\u00fcnchen, Hamburg und Berlin und bietet Spezialthemen bundesweit mit Kooperationspartnern an.<\/p> <p>Kontakt:<br \/> Studieninstitut f\u00fcr Kommunikation<br \/> Tanja Barleben<br \/> Reisholzer Werftstr. 35<br \/> 40589 D\u00fcsseldorf<br \/> 0211 779237-16<br \/> tbarleben@studieninstitut.de<br \/> http:\/\/www.studieninstitut.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>e-Marketingday Rheinland am 18. April 2013: Informationen rund um Online-Marketing f\u00fcr Unternehmen aus dem Mittelstand &#8211; Fach- und Anwenderforen sowie Begleitausstellung bieten Know-how und Austausch &#8211; Studieninstitut f\u00fcr Kommunikation informiert \u00fcber Weiterbildungen f\u00fcr Online-Marketing Bereits zum dritten Mal pr\u00e4sentieren die Industrie- und Handelskammern im Rheinland den e-Marketingday. Kleine und mittlere Unternehmen sind eingeladen, sich im<\/p>\n","protected":false},"author":3,"featured_media":197332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[1734],"class_list":["post-56310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-event-entertainment-lifestyle","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/56310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=56310"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/56310\/revisions"}],"predecessor-version":[{"id":274974,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/56310\/revisions\/274974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197332"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=56310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=56310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=56310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}