{"id":5637,"date":"2010-05-17T08:57:32","date_gmt":"2010-05-17T07:57:32","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=5637"},"modified":"2022-08-25T10:31:21","modified_gmt":"2022-08-25T09:31:21","slug":"fremdsprachen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/fremdsprachen-105637\/","title":{"rendered":"Franz\u00f6sisch und Italienisch online lernen: Fremdsprachen-Portal dalango mit neuen Sprachen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>dalango , das e-learning-Portal des Spotlight Verlags, baut aus: Die Webseite zum online Sprachen lernen zeigt erweitert das Angebot um Franz\u00f6sisch und Italienisch.<\/p> <p>dalango, das e-learning-Portal des Spotlight Verlags, pr\u00e4sentiert im frischen Design zwei weitere Fremdsprachen. Der User kann jetzt neben Englisch, Business Englisch und Spanisch auch Franz\u00f6sisch und Italienisch online lernen.<!--more--><\/p> <p>Das Konzept:<br \/> &#8211; Kurze Videos zeigen Alltagssituationen in der Fremdsprache, von der Begr\u00fc\u00dfung auf Franz\u00f6sisch, dem Restaurant-Besuch in Italien, der Hotel-Reservierung auf Spanisch, dem Meeting mit internationalen Gesch\u00e4ftspartnern bis hin zum Small Talk auf Englisch.<br \/> &#8211; Die Darsteller sind muttersprachliche Schauspieler: So vermittelt jedes Video authentischen Redefluss, mit Dialekten und unterschiedlichen Sprechgeschwindigkeiten. Durch Untertitel und das integrierte W\u00f6rterbuch des Online-Anbieters leo.org k\u00f6nnen unbekannte Vokabeln per Mausklick nachgeschlagen werden.<br \/> &#8211; Der User trainiert anschlie\u00dfend aktiv Wortschatz, Grammatik und H\u00f6rverst\u00e4ndnis in neun \u00dcbungen mit L\u00fcckentexten, Sch\u00fcttels\u00e4tzen und Multiple-Choice-Aufgaben. Die Ergebnisse werden auf dem pers\u00f6nlichen Lernblatt gespeichert.<br \/> &#8211; dalango funktioniert nach dem Flatrate-Prinzip: Registrierte Nutzer entscheiden selbstst\u00e4ndig, wann, wo und wie viel sie lernen m\u00f6chten. F\u00fcr jedes Sprach-Angebot gibt es ein kostenloses Video zum Ansehen und passende \u00dcbungen f\u00fcr den schnellen Selbsttest.<\/p> <p>Aktuell kann man mit \u00fcber 450 Videos und 4.000 \u00dcbungen Sprachen online lernen \u2013 und das Team produziert am laufenden Band weiter. Kommende Episoden f\u00fchren den Lerner zur Urlaubsvorbereitung auf die franz\u00f6sische Weinstra\u00dfe und an den Strand nach Italien.<\/p> <p>Info: http:\/\/www.dalango.de<\/p> <p>dalango ist ein Angebot des Spotlight Verlags. Das Tochterunternehmen der Verlagsgruppe Georg von Holtzbrinck publiziert sieben Sprachmagazine mit einer verbreiteten Gesamtauflage von 341.237 Exemplaren (IVW I\/2010) und setzt mit www.SprachenShop.de auf E-Commerce. Info: www.spotlight-verlag.de<\/p> <p>Fraunhoferstra\u00dfe 22<br \/> 82152 Planegg\/M\u00fcnchen<br \/> Deutschland<\/p>","protected":false},"excerpt":{"rendered":"<p>dalango , das e-learning-Portal des Spotlight Verlags, baut aus: Die Webseite zum online Sprachen lernen zeigt erweitert das Angebot um Franz\u00f6sisch und Italienisch. dalango, das e-learning-Portal des Spotlight Verlags, pr\u00e4sentiert im frischen Design zwei weitere Fremdsprachen. Der User kann jetzt neben Englisch, Business Englisch und Spanisch auch Franz\u00f6sisch und Italienisch online lernen.<\/p>\n","protected":false},"author":291,"featured_media":198872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeit-erziehung-bildung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=5637"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5637\/revisions"}],"predecessor-version":[{"id":274834,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5637\/revisions\/274834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198872"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=5637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=5637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=5637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}