{"id":5815,"date":"2010-05-21T11:37:57","date_gmt":"2010-05-21T10:37:57","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=5815"},"modified":"2013-05-03T13:59:01","modified_gmt":"2013-05-03T12:59:01","slug":"coaching-duesseldorf","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/coaching-duesseldorf-105815\/","title":{"rendered":"Coaching mit The Work in D\u00fcsseldorf"},"content":{"rendered":"<p>Stress und Burnout ad\u00e9 : Weniger \u00c4rger, Frust und Sorgen<br \/> Was ist der Anlass f\u00fcr ein Coaching mit The Work in D\u00fcsseldorf?<br \/> Viele Menschen haben die Freude am Privatleben oder am Beruf verloren. \u00dcberforderung, Hoffnungslosigkeit und Frustration treten in den allt\u00e4glichen Vordergrund. Zwei von drei Managern in Deutschland f\u00fchlen sich im Job &#8222;ausgebrannt&#8220;: Zu diesem Ergebnis kommt eine Untersuchung der Bertelsmann Stiftung in Unternehmen und Organisationen. In dieser Lebensphase ist echtes Gl\u00fcck nicht zu finden. Hier bedarf es einer gezielten Intervention mit einer erprobten Methode.<!--more--><br \/> Was ist The Work?<br \/> Die Coachingmethode The Work unterst\u00fctzt Menschen bereits seit mehr als 20 Jahren dabei, Stress ausl\u00f6sende Gedanken so zu bearbeiten (englisch \u201eto work\u201c), dass sie weniger oder keinen Stress mehr ausl\u00f6sen. Eine der zentralen Ideen besteht darin, dass Stress und Burnout nicht durch Lebensumst\u00e4nde, sondern durch die eigenen Gedanken \u00fcber diese entstehen. Laut einer Studie der US-amerikanischen Stanford-Universit\u00e4t geh\u00f6rt The Work zu den zurzeit wirkungsvollsten M\u00f6glichkeiten, um emotionale Zust\u00e4nde wie Zukunftsangst, Sorge, Wut oder Traurigkeit zu regulieren.<br \/> Was passiert in einem Coaching mit The Work in D\u00fcsseldorf?<br \/> Nach dem Kennenlernen und einer Erwartungskl\u00e4rung werden zuerst diejenigen individuellen Gedanken gesucht, welche Stress ausl\u00f6sen und so einen \u201eBurnout\u201c verursachen. Dies k\u00f6nnen bspw. sein: \u201eIch muss meine Ziele erreichen!\u201c (Schaffe es aber nicht.) oder \u201eIch darf nicht NEIN! sagen!\u201c (M\u00fcsste es aber tun.). Dann wird mit diesen Gedanken im Coaching so gearbeitet, dass neue Sichtweisen m\u00f6glich sind. Diese erlauben dann neue Lebensfreude. Weitere Informationen hierzu finden sich unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.christian-bremer.de\"  >www.christian-bremer.de<\/a>.<br \/> Wer ist Ihr Coach?<br \/> Christian Bremer, Coach for The Work, arbeitet seit 18 Jahren als Coach f\u00fcr Unternehmer, Freiberufler und F\u00fchrungskr\u00e4fte. Auch Privatpersonen geh\u00f6ren zu seinen Klienten. Au\u00dferdem arbeitet er bspw. f\u00fcr H&amp;M, Deutsche Bank und adidas Group \/ Reebok. Er wurde vom ersten Deutschen, der von der \u201eErfinderin\u201c von The Work, Byron Katie, zertifiziert wurde, direkt ausgebildet. So sind Qualit\u00e4t und Ergebnis garantiert.<br \/> Wo findet das Coaching statt, wie lange dauert es und was kostet es?<br \/> Das Coaching kann in unseren R\u00e4umen in D\u00fcsseldorf-Gerresheim oder in Ihren Konferenzr\u00e4umen stattfinden. Die Dauer h\u00e4ngt vom Anliegen ab. Meistens werden 5-8 Einheiten \u00e1 90 Minuten durchgef\u00fchrt, um eine echte Linderung zu erreichen. Der Invest h\u00e4ngt von dem Umfang und dem Ort des Coachings ab. Vor dem Coaching werden individuelle Angebote erstellt.<br \/> Weitere Informationen zu: Coaching mit The Work in D\u00fcsseldorf<br \/> BREMER Coaching und individuelles Training<br \/> Christian Bremer, Dipl.-P\u00e4d. und zertifizierter Coach for The Work<br \/> Stapelbachweg 16a, 40635 D\u00fcsseldorf<br \/> Telefon: 0211 \u2013 30 176 188<br \/> Email: info@christian-bremer.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Stress und Burnout ad\u00e9 : Weniger \u00c4rger, Frust und Sorgen Was ist der Anlass f\u00fcr ein Coaching mit The Work in D\u00fcsseldorf? Viele Menschen haben die Freude am Privatleben oder am Beruf verloren. \u00dcberforderung, Hoffnungslosigkeit und Frustration treten in den allt\u00e4glichen Vordergrund. Zwei von drei Managern in Deutschland f\u00fchlen sich im Job &#8222;ausgebrannt&#8220;: Zu diesem<\/p>\n","protected":false},"author":291,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-5815","post","type-post","status-publish","format-standard","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=5815"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5815\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=5815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=5815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=5815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}