{"id":5915,"date":"2010-05-27T12:09:25","date_gmt":"2010-05-27T11:09:25","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=5915"},"modified":"2013-07-29T14:20:11","modified_gmt":"2013-07-29T13:20:11","slug":"clanmo-lufthansa-app","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/clanmo-lufthansa-app-105915\/","title":{"rendered":"CLANMO und Lufthansa ver\u00f6ffentlichen App f\u00fcr drei neue Plattformen"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5918\" title=\"Lufthansa260510.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/edc9ac3e31b4eca6df76a0c7ec5b909c.jpg\" alt=\"\" width=\"133\" height=\"74\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/3405897bb0c3c96f0a198ecace839d9d.jpg\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>K\u00f6ln, 26.05.10<br \/> Seit dem Siegeszug des iPhones sind Apps gefragt wie nie. Nach dem gelungenen Update der Lufthansa iPhone App im Februar 2010, legte die Deutsche Lufthansa nun mit einem erweiterten App-Angebot nach. Ab sofort sind die f\u00fcr das iPhone entwickelten Services nun auch f\u00fcr Blackberry, Android und J2ME als App erh\u00e4ltlich. Wie bereits das mobile Lufthansa Serviceportal und die iPhone App, stammen auch die drei neuen Apps aus dem Hause der K\u00f6lner Agentur CLANMO.<!--more--><br \/> \u201eNach rund zwei Jahren Erfahrung mit dem mobilen Serviceportal  war uns klar, dass wir mit einer iPhone App nur einen Teil unserer Kunden erreichen\u201c, so Marcus Casey, Leiter E-Commerce und Mobile bei der Deutsche Lufthansa AG. \u201eDarum haben wir gr\u00fcndlich evaluiert, mit welchen Endger\u00e4ten am h\u00e4ufigsten auf das mobile Serviceportal zugegriffen wird. Auf Basis dieser Ergebnisse realisierte CLANMO zus\u00e4tzlich f\u00fcr Blackberry, Android und J2ME eine eigene Lufthansa-App, die seit April in den jeweiligen Stores verf\u00fcgbar ist.\u201c<br \/> Passend zum Interaktionskonzept der jeweiligen Plattform entwickelte CLANMO eine ma\u00dfgeschneiderte L\u00f6sung, bei der vor allem auf Flexibilit\u00e4t und Komfort bei der Reiseplanung im Vordergrund steht. Neben dem neusten Flugplan sowie aktuellen Ankunft- und Abflug-Informationen k\u00f6nnen Lufthansa-Kunden bei allen Apps vom schnellen Zugriff auf pers\u00f6nliche Reisedaten profitieren.<br \/> \u201eDie Deutsche Lufthansa ist ein echtes Vorbild f\u00fcr erfolgreiche Kundenbindung \u00fcber den mobilen Kanal. Per App werden speziell die Kundengruppen mit Premium-Services versorgt, die f\u00fcr das Unternehmen relevant sind. Mit dieser Flexibilit\u00e4t sichert sich die Deutsche Lufthansa eine wichtige Position f\u00fcr das kommende Wachstum im Bereich m-commerce\u201c, so Joachim Bader, Gesch\u00e4ftsf\u00fchrer CLANMO.<br \/> Die App steht ab sofort zum kostenlosen Download zur Verf\u00fcgung.<\/p> <p>Im iTunes Store f\u00fcr iPhone:<br \/> (http:\/\/itunes.apple.com\/de\/app\/lufthansa\/id299219152?mt=8)<br \/> F\u00fcr Blackberry Handy (zZ. nur in englisch verf\u00fcgbar):<br \/> (http:\/\/appworld.blackberry.com\/webstore\/content\/8276)<br \/> Im OVI Store f\u00fcr Nokia:<br \/> (http:\/\/store.ovi.com\/content\/31568?lang=de)<br \/> F\u00fcr Google Handys mit Android Betriebssystem (nicht im Browser aufrufbar):<br \/> (http:\/\/market.android.com\/search?q=pname:com.lufthansa.android.lufthansa)<br \/> Lufthansa Mobile Portal:<br \/> (http:\/\/mobile.lufthansa.com\/lp\/bkm\/)<\/p> <p>\u00dcber CLANMO:<br \/> Die CLANMO GmbH (http:\/\/www.clanmo.com) ist eine hochdekorierte Agentur f\u00fcr Mobile Interaction. Sie betreut Kunden sowohl strategisch als auch konzeptionell bei der mobilen Markenf\u00fchrung und der Entwicklung des mobilen Service-Portfolios. Schwerpunktbranchen sind Travel, Automotive, Fashion, Lifestyle und Tele-kommunikation. Die Arbeit von CLANMO zeichnet sich nachhaltig durch hohe Qualit\u00e4t und Innovationskraft aus. F\u00fcr Kunden wie zum Beispiel IKEA, Lufthansa und Konami erarbeitete CLANMO mehrfach Projekte, die sich zu Industry-Benchmarks entwickelten und mit zahlreichen Awards ausgezeichnet wurden. Unter anderem gewann CLANMO den Global Mobile Award 2010 f\u00fcr die IKEA PS Einrichtungskamera. Von den Standorten M\u00fcnchen und K\u00f6ln aus unterst\u00fctzt CLANMO Kunden mit einem Full-Serviceangebot aus strategischer Beratung, Kreation und hauseigener Mobile Technologie. Dabei liefert CLANMO das gesamte Mobile Portfolio aus einer Hand: Kampagnenkreation, Applikationsentwicklung, Mobile Internet und Mobile Mediaplanung. Kunden sind u.a. Lufthansa, Konami, Europcar, Vodafone, T-Mobile, Hugo Boss und Porsche.<br \/> Pressekontakt:<br \/> forvision<br \/> Anke Piontek<br \/> Beratung f\u00fcr Marketing, PR und TV<br \/> Spichernstra\u00dfe 32<br \/> 50672 K\u00f6ln<br \/> tel: 0221\/51 09 16 90<br \/> fax: 0221\/51 09 16 9-29<br \/> mail: piontek@forvision.de<br \/> http: www.forvision.de<\/p>","protected":false},"excerpt":{"rendered":"<p>K\u00f6ln, 26.05.10 Seit dem Siegeszug des iPhones sind Apps gefragt wie nie. Nach dem gelungenen Update der Lufthansa iPhone App im Februar 2010, legte die Deutsche Lufthansa nun mit einem erweiterten App-Angebot nach. Ab sofort sind die f\u00fcr das iPhone entwickelten Services nun auch f\u00fcr Blackberry, Android und J2ME als App erh\u00e4ltlich. Wie bereits das<\/p>\n","protected":false},"author":291,"featured_media":198863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-5915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handy-elektronik-telekommunikation"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=5915"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/5915\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198863"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=5915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=5915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=5915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}