{"id":60090,"date":"2013-04-10T11:50:25","date_gmt":"2013-04-10T10:50:25","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=60090"},"modified":"2013-04-10T11:50:25","modified_gmt":"2013-04-10T10:50:25","slug":"bundesregierung-verschaerft-die-bankenregulierung","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/bundesregierung-verschaerft-die-bankenregulierung-1060090\/","title":{"rendered":"Bundesregierung versch\u00e4rft die Bankenregulierung"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-60091\" title=\"\u00dcber Grenzen ins Unbekannte gehen \u2013 Neues entdecken, Ver\u00e4nderungen systematisch und effizient umsetzen \u2013 schnell Erfolge generieren\" alt=\"mutaree_logo_3\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/081d6747790740ac277323985fb56bd7.jpg\" width=\"168\" height=\"91\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/081d6747790740ac277323985fb56bd7.jpg\" \/>In dynamischen Zeiten mit Schlagzeilen \u00fcber Banken- und Finanzkrisen und neuen strategischen, systemischen oder regulatorischen Anforderungen ist ein funktionierendes Change Management f\u00fcr Banken unverzichtbar. Doch die Finanzbranche weist noch Optimierungsbedarf bei ihrem Ver\u00e4nderungsmanagement auf: Lediglich 38 Prozent der Banker bewerten ihre Erfolgsquote bei bisher durchgef\u00fchrten Ver\u00e4nderungsprozessen mit 75 bis 100 Prozent. Die H\u00e4lfte der Finanzinstitute sch\u00e4tzt ihre Erfolgsquote bei nur 50 Prozent ein; dies ergab die Studie der Mutaree GmbH zur Change-Fitness.<\/p> <p><!--more-->\u201eBanken k\u00f6nnen Herausforderungen wie das Trennbankengesetz nur meistern, wenn sie flexibel auf diese Situationen reagieren. Deshalb sollte die deutsche Finanzbranche ihre Change-Fitness noch weiter ausbauen, um f\u00fcr den zuk\u00fcnftigen Wandel ger\u00fcstet zu sein\u201c, sagt Claudia Schmidt, Gesch\u00e4ftsf\u00fchrerin der Mutaree GmbH.<\/p> <p>Bundesregierung versch\u00e4rft die Bankenregulierung<br \/> Die Gesch\u00e4fte der Banken- und Finanzkonzerne sollen strenger kontrolliert werden: Die Bundesregierung hat im Februar 2013 einen Gesetzesentwurf vorgelegt, der die Bankenaufsicht jetzt mit einem neuen Gesetz vorantreiben soll: Das Trennbankengesetz. Ganz konkret beinhalt dieses Paket die Abspaltung der Spekulationsgesch\u00e4fte der Banken von den Kundengeldern, Haftstrafen f\u00fcr Top-Manager bei Vernachl\u00e4ssigung ihrer Pflichten und die sogenannten Bankentestamente.<\/p> <p>Seit der Finanzkrise 2008 gab es eine Vielzahl an Vorschl\u00e4gen zur st\u00e4rkeren Kontrolle des Finanzsektors. Die Bundesregierung schreitet jetzt zur Tat: Sie hat am 6. Februar 2013 ein Gesetz zur Bankenregulierung beschlossen. Die Bundesregierung m\u00f6chte risikoreiche Bereiche vom Einlagengesch\u00e4ft abtrennen. Das bedeutet f\u00fcr gr\u00f6\u00dfere Finanzinstitute, dass sie sich auf eine Abspaltung des Investmentgesch\u00e4fts vom klassischen Bankgesch\u00e4ft einstellen m\u00fcssen. Nach den Empfehlungen des europ\u00e4ischen Liikanen-Expertenberichts soll das Kundengesch\u00e4ft demnach abgeschirmt werden, wenn Einlagenkreditinstitute oder Gruppen, denen Einlagenkreditinstitute angeh\u00f6ren, bestimmte Schwellenwerte \u00fcberschreiten. Sie m\u00fcssen das Eigengesch\u00e4ft dann in eine rechtlich und wirtschaftlich selbstst\u00e4ndige Gesellschaft ausgliedern.<\/p> <p>BaFin fordert Sanierungsplan von den Banken<br \/> Banken m\u00fcssen Notfallpl\u00e4ne ausarbeiten und ihre Ergebnisse der BaFin vorlegen: Aktuell sind 36 deutsche Institute als systemrelevant eingestuft. Die betroffenen Banken m\u00fcssen bis Ende 2013 ihren Notfallplan einreichen. Dabei handelt es sich um Pl\u00e4ne, in denen die Sanierung und schnelle Abwicklung der Institution geregelt ist. Dadurch sollen fr\u00fchzeitig Ma\u00dfnahmen ergriffen werden k\u00f6nnen. Die Bankenaufsicht kann au\u00dferdem verlangen, dass m\u00f6gliche Hindernisse bei der Abwicklung bereits vorher beseitigt werden.<\/p> <p>Banken erkennen Ver\u00e4nderungsbedarf<br \/> 67 Prozent der Banker erkennen zwar fr\u00fchzeitig die Notwendigkeit f\u00fcr eine Ver\u00e4nderung, jedoch folgen dem erkannten Ver\u00e4nderungsbedarf oft zu wenig und nicht die richtigen, bzw. strukturierten Adaptionsans\u00e4tze. 52 Prozent der Kreditinstitute verf\u00fcgen nicht \u00fcber ein ausgebildetes Change-Management-Team. Au\u00dferdem fehlt es den Mitarbeitern bei fast der H\u00e4lfte der Banken am n\u00f6tigen Know-how um ein umfangreiches Change-Projekt effektiv umzusetzen.<\/p> <p>\u201eDamit die Bankenbranche zuk\u00fcnftig bessere Ergebnisse vorweisen kann, sollte die Change-Qualifikation zum integralen Bestandteil der Unternehmensf\u00fchrung werden. Denn das Engagement und Umsetzungsgeschick der F\u00fchrungskr\u00e4fte und Mitarbeiter pr\u00e4gt das Ergebnis ma\u00dfgeblich\u201c, sagt Claudia Schmidt.<\/p> <p>\u00dcber die Mutaree GmbH:<br \/> Die <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.mutaree.com\/\" title=\"Erfolgreich Grenzen \u00fcberschreiten\" >Mutaree GmbH<\/a> ist der Experte f\u00fcr Ver\u00e4nderungsmanagement. Das Leistungsangebot umfasst die Planung und Steuerung von Ver\u00e4nderungsprozessen sowie die Umsetzungsbegleitung zur Erreichung der gesetzten Ver\u00e4nderungsziele. Dabei steht der Mensch immer im Mittelpunkt. Mutaree ber\u00e4t Kunden aus verschiedenen Branchen: Banken und Versicherungen, Chemie und Pharma, Energieversorgung, Gesundheitswesen, Telekommunikation, \u00d6ffentliche Verwaltung sowie Touristik. Die Mutaree GmbH ist Mitglied im Bundesverband Deutscher Unternehmensberater e.V. (BDU).<\/p> <p>Pressekontakt:<br \/> Stefan Roth<br \/> Unternehmenskommunikation<br \/> Telefon: +49 (40) 32 57 79-32<br \/> Telefax: +49 (40) 32 57 79-20<br \/> s.roth@mutaree.com<\/p>","protected":false},"excerpt":{"rendered":"<p>In dynamischen Zeiten mit Schlagzeilen \u00fcber Banken- und Finanzkrisen und neuen strategischen, systemischen oder regulatorischen Anforderungen ist ein funktionierendes Change Management f\u00fcr Banken unverzichtbar. Doch die Finanzbranche weist noch Optimierungsbedarf bei ihrem Ver\u00e4nderungsmanagement auf: Lediglich 38 Prozent der Banker bewerten ihre Erfolgsquote bei bisher durchgef\u00fchrten Ver\u00e4nderungsprozessen mit 75 bis 100 Prozent. Die H\u00e4lfte der Finanzinstitute<\/p>\n","protected":false},"author":3,"featured_media":60091,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-60090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banken-kredit-finanzberatung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=60090"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/60091"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=60090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=60090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=60090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}