{"id":604,"date":"2008-09-30T14:26:32","date_gmt":"2008-09-30T13:26:32","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/von-pons-gibts-jetzt-was-auf-die-ohren-10604\/"},"modified":"2022-05-24T11:51:07","modified_gmt":"2022-05-24T10:51:07","slug":"von-pons-gibts-jetzt-was-auf-die-ohren","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/von-pons-gibts-jetzt-was-auf-die-ohren-10604\/","title":{"rendered":"Von PONS gibt&#8217;s jetzt was auf die Ohren"},"content":{"rendered":"<p> <font size=\"-1\"><strong>Lekt\u00fcrehilfe als neue &#8222;H\u00f6rstoff&#8220;-Reihe f\u00fcr MP3-Player<\/strong><\/font><\/p> <table style=\"float: right; width: 168px\" border=\"0\" cellpadding=\"5\" cellspacing=\"0\"> <tr> <td align=\"center\" bgcolor=\"#ededed\"> <table border=\"0\" cellpadding=\"3\" cellspacing=\"0\" width=\"168\"> <tr> <td align=\"center\"><\/td> <\/tr> <tr> <td class=\"txtklein\" align=\"center\"><nobr><\/nobr><\/td> <\/tr> <tr> <td colspan=\"2\" class=\"txtklein\" align=\"center\"><!-- copyrighttext --><!-- end copyrighttext --><\/td> <\/tr> <\/table> <\/td> <\/tr> <\/table> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"> <span class=\"txt\"> <!--PTE:ORT-->Stuttgart (pts\/30.09.2008\/10:34) &#8211; Ob Leseratte oder B\u00fcchermuffel: Mit dieser CD f\u00fcr MP3-Player wird Abi-Wissen leichter zug\u00e4nglich. Shakespeare oder Auster, Schiller oder Kafka &#8211; in 8 Ausgaben der Reihe &#8222;H\u00f6rstoff&#8220; werden die Erl\u00e4uterungen zu deren Werken jetzt erstmalig f\u00fcrs Ohr pr\u00e4sentiert und die Besprechung der Lekt\u00fcre im Fach Deutsch und Englisch leichter verst\u00e4ndlich.<\/span><\/font><!--more--><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\"><span class=\"txt\"> Muttersprachler erz\u00e4hlen und erl\u00e4utern in abwechslungsreichen Dialogen, worum es im jeweiligen Werk geht, was man \u00fcber Autor und Epoche wissen muss und welche Charakterisierungen, Textanalysen oder Interpretationen es dazu geben kann.<\/span><\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Der Lausch-Angriff aufs Abitur-Wissen: passend zur Generation iPod<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Ob man die MP3-Datei abspielt, weil man mit dem Fahrrad unterwegs ist, es sich zu Hause auf dem Sofa gem\u00fctlich machen und einfach nur lauschen will oder im 64 Seiten starken Booklet mit seinen klaren Texten und \u00fcbersichtlichen Diagrammen nachlesen will: die neue &#8222;H\u00f6rstoff&#8220;-Reihe erlaubt vielf\u00e4ltigen Einsatz f\u00fcr Auge und Ohr. Neben einem umfassenden Teil mit Inhaltsangaben, Analysen und Interpretationen befinden sich im hinteren Teil des Booklets auch m\u00f6gliche Abiturfragen mit L\u00f6sungsans\u00e4tzen, so dass man sich f\u00fcr die gro\u00dfe Pr\u00fcfung richtig fit machen kann.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Ob Leseratte oder eher B\u00fcchermuffel: f\u00fcr beide hat PONS nun die L\u00f6sung parat: die neue Lekt\u00fcrenhilfe-Reihe &#8222;H\u00f6rstoff&#8220;. Auf dieser MP3-CD erf\u00e4hrt man alles Wichtige zum Lesestoff, der gerade in der Schule durchgenommen wird.<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Originalsprache f\u00fcr das richtige Ohrentraining<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Bei den 4 neuen englischen Lekt\u00fcrehilfen zu Romeo &amp; Juliet, Fahrenheit 451, Brave New World und Moon Palace kann man einem abwechslungsreichen Gespr\u00e4ch in Dialogform lauschen und h\u00f6rt so &#8211; direkt von Muttersprachlern &#8211; worum es im jeweiligen St\u00fcck oder Roman geht. So kommt man schnell ins Thema, trainiert das H\u00f6rverstehen in der Fremdsprache und kann sich gleichzeitig auf die Diskussion im Unterricht auf Englisch vorbereiten. Wer also auch m\u00fcndlich sicher im Umgang mit den Texten werden will, um dann locker mitreden zu k\u00f6nnen, hat durch die Audio-Lekt\u00fcrehilfe einen klaren Vorteil. Kurzum: nicht nur f\u00fcr &#8222;lesefaule&#8220; Sch\u00fcler die geeignete Hilfe. Deshalb: Ohren auf, wenn&#8217;s um Literatur geht!<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Produktdaten:<br \/> PONS H\u00f6rstoff Lekt\u00fcrehilfe f\u00fcr MP3-Player<br \/> Theodor Fontane, Effi Briest, ISBN: 978-3-12-561452-9<br \/> Franz Kafka, Der Proce\u00df, ISBN: 978-3-12-561451-2<br \/> Friedrich Schiller, Die R\u00e4uber, ISBN: 978-3-12-561450-5<br \/> J.W. von Goethe, Faust I, ISBN: 978-3-12-561453-6<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">William Shakespeaere, Romeo &amp; Juliet, ISBN: 978-3-12-561455-0<br \/> Ray Bradbury, Fahrenheit 451, ISBN: 978-3-12-561456-7<br \/> Aldous Huxley, Brave new World, ISBN: 978-3-12-561457-4<br \/> Paul Auster, Moon Palace, ISBN: 978-3-12-561529-8<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Preis: je 9,95 Euro<br \/> Booklet (64 Seiten), 14,3 x 14,3 cm mit eingeklebter MP3-CD<\/font><\/p> <p><font size=\"-1\" face=\"Verdana, Arial, Helvetica, sans-serif\">Erh\u00e4ltlich im Buchhandel und unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pons.de\/\"  target=\"_blank\" rel=\"noopener\">http:\/\/www.pons.de<\/a> (Ende)<br \/> <br clear=\"all\" \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pons.de\/\"  target=\"_new\" rel=\"noopener\"><\/a><br \/> Aussender: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pons.de\/\"  target=\"_new\" rel=\"noopener\">PONS GmbH<\/a><br \/> Ansprechpartner:                        Tamara Ziegler<br \/> email: <a href=\"mailto:t.ziegler%40pons.de\">t.ziegler@pons.de<\/a><br \/> Tel. +49 (0)711 6672 5538   <\/font><\/p>","protected":false},"excerpt":{"rendered":"<p>Lekt\u00fcrehilfe als neue &#8222;H\u00f6rstoff&#8220;-Reihe f\u00fcr MP3-Player Stuttgart (pts\/30.09.2008\/10:34) &#8211; Ob Leseratte oder B\u00fcchermuffel: Mit dieser CD f\u00fcr MP3-Player wird Abi-Wissen leichter zug\u00e4nglich. Shakespeare oder Auster, Schiller oder Kafka &#8211; in 8 Ausgaben der Reihe &#8222;H\u00f6rstoff&#8220; werden die Erl\u00e4uterungen zu deren Werken jetzt erstmalig f\u00fcrs Ohr pr\u00e4sentiert und die Besprechung der Lekt\u00fcre im Fach Deutsch und<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-604","post","type-post","status-publish","format-standard","hentry","category-arbeit-erziehung-bildung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=604"}],"version-history":[{"count":3,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/604\/revisions"}],"predecessor-version":[{"id":274586,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/604\/revisions\/274586"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}