{"id":60502,"date":"2013-04-12T15:22:13","date_gmt":"2013-04-12T14:22:13","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=60502"},"modified":"2014-07-29T06:25:01","modified_gmt":"2014-07-29T05:25:01","slug":"die-japanische-waseda-university-kauft-als-erste-universitaet-in-asien-die-springer-book-archives","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/die-japanische-waseda-university-kauft-als-erste-universitaet-in-asien-die-springer-book-archives-1060502\/","title":{"rendered":"Erste Universt\u00e4t in Asien mit umfassenden Bestand historischer Inhalte von Springer"},"content":{"rendered":"<p>Die japanische Waseda University kauft als erste Universit\u00e4t in Asien die Springer Book Archives<\/p> <p>Historisches Bucharchiv von Springer steht jetzt Studenten, Dozenten und Wissenschaftlern zur Verf\u00fcgung<\/p> <p>Wie Springer heute bekannt gab, hat die Universit\u00e4tsbibliothek der Waseda University in Tokio, Japan, die englischsprachigen Titel der Springer Book Archives (SBA) gekauft. Die Nutzer dieser Bibliothek haben dadurch ab sofort \u00fcber SpringerLink (link.springer.com) Online-Zugriff auf den Springer-Buchbestand, der bis in das Jahr 1842 zur\u00fcckgeht. Es ist nicht nur der erste SBA-Kauf einer japanischen Universit\u00e4t bzw. Forschungseinrichtung, sondern der erste in Asien \u00fcberhaupt.<\/p> <p><!--more-->Die Springer Book Archives sind wissenschaftliche Titel, die Springer seit seiner Verlagsgr\u00fcndung 1842 verlegt hat und die nun zum ersten Mal digitalisiert wurden. Die englischen Buchtitel belaufen sich derzeit auf \u00fcber 43.000 eBooks; bis zum Abschluss des Projekts Ende 2013 sollen es 50.000 Titel sein. \u201eZusammen mit den deutschsprachigen B\u00fcchern, die ebenfalls Teil der SBA-Titel sind, werden insgesamt 100.000 bedeutende wissenschaftliche Werke verf\u00fcgbar sein. So wird Wissenschaftsliteratur bewahrt und die Vergangenheit, Gegenwart und Zukunft der Forschung miteinander verbunden\u201c, sagt Olga Chiarcos, Herstellungsleiterin Deutschland und Managerin des SBA-Projekts.<\/p> <p>Auf diese einzigartige Sammlung historischer Wissensinhalte kann ohne DRM (Digital Rights Management) und als Volltext zugegriffen werden. Die eBooks bieten vielf\u00e4ltige Leseoptionen: Sie k\u00f6nnen auf den unterschiedlichsten elektronischen Ger\u00e4ten genutzt und sogar als gedruckte POD- Titel bestellt werden. Bei den meisten Titeln wird die POD-Option angeboten und somit bringt Springer B\u00fccher, die seit Jahrzehnten vergriffen waren, zur\u00fcck ins Buchregal.<\/p> <p>\u201eWir freuen uns, dass wir den Studenten, Wissenschaftlern und Dozenten unserer Universit\u00e4t und Bibliothek neben den Springer-Publikationen, die wir ohnehin in unserem Bestand haben, nun auch noch die SBA-Titel anbieten k\u00f6nnen\u201c, sagt Makoto Nakamoto, Verwaltungsdirektor der Waseda University Library. \u201eAu\u00dferdem sind wir stolz darauf, die erste Universit\u00e4t in Asien zu sein, die einen so umfassenden Bestand historischer Inhalte zur Verf\u00fcgung stellt. Wir denken, dass es in der Region eine hohe Nachfrage nach diesen n\u00fctzlichen Quellen geben wird.\u201c<\/p> <p>Als Springer 2006 seine ersten eBook-Collections (inkl. B\u00fccher mit dem Copyrightjahr 2005) auf den Markt brachte, hatte die Waseda University Library alle angebotenen Fachbereichs-Collections erworben. Mit dem Kauf der Springer Book Archives werden in der Waseda Universit\u00e4tsbibliothek nun s\u00e4mtliche englischsprachigen Springer-B\u00fccher verf\u00fcgbar sein, angefangen bei rar gewordenen B\u00fcchern, die zuletzt als vergriffen galten, bis hin zu den Neupublikationen.<\/p> <p>Die Waseda University Library blickt auf eine \u00fcber 130-j\u00e4hrige Geschichte zur\u00fcck. Gegr\u00fcndet wurde die Universit\u00e4t 1882, damals unter dem Namen Tokyo Senmon Gakko. Auf dem Campus der Universit\u00e4t gibt es mehr als 20 Bibliotheken und Bibliotheksr\u00e4ume sowie die Zentralbibliothek, die mehr als 5.500.000 Publikationen besitzt. Als eine der gr\u00f6\u00dften Universit\u00e4tsbibliotheken Japans empf\u00e4ngt die Waseda University Library jedes Jahr circa zwei Millionen Besucher, die insgesamt etwa 900.000 B\u00fccher ausleihen. Die Bibliothek baut ihre Online-Best\u00e4nde wie elektronische Zeitschriften, eBooks und Online-Datenbanken stetig aus. Zurzeit stellt sie ihren Nutzern \u00fcber 30.000 eJournals und \u00fcber 500.000 eBooks zur Verf\u00fcgung. Die Bibliothek besitzt zudem zahlreiche kostbare B\u00fccher, die als Nationalsch\u00e4tze und wichtige Kulturbest\u00e4nde gelten. Informationen und Farbmaterial zu diesen B\u00fcchern sind auf der Webseite \u201eKotenseki Sogo Database (Japanese &amp; Chinese Classics Online)\u201c frei zug\u00e4nglich. Als Pr\u00e4senz- und Online-Bibliothek bietet die Waseda University Library eine einmalige und unverzichtbare Bibliotheksinfrastruktur f\u00fcr Wissenschaftler und Studenten.<\/p> <p>Springer Science+Business Media (www.springer.com) ist ein international f\u00fchrender Verlag f\u00fcr hochwertige Inhalte in innovativen Informationsprodukten und Dienstleistungen im Bereich Science, Technology, Medicine. Hauptzielgruppe sind Forscher in Hochschulen und wissenschaftlichen Instituten ebenso wie in Forschungsabteilungen von Unternehmen. Die Verlagsgruppe ist au\u00dferdem ein renommierter Anbieter von Fachpublikationen in Europa, insbesondere im deutschsprachigen Raum und den Niederlanden. Diese werden von \u00c4rzten sowie Fachleuten aus dem Gesundheitswesen und der Verkehrserziehung genutzt. Springer brachte 2012 etwa 2.200 englischsprachige Zeitschriften und mehr als 7.500 neue B\u00fccher heraus. Ebenso erscheint im Verlag die weltweit gr\u00f6\u00dfte eBook-Collection im Bereich Science, Technology, Medicine und das umfangreichste Portfolio an Open Access-Zeitschriften. Springer Science+Business Media S.A. erzielte 2012 einen Jahresumsatz von ca. 981 Millionen Euro. Die Gruppe hat weltweit mehr als 7.000 Mitarbeiter.<\/p> <p>Kontakt: Renate Bayaz| <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.springer.com\/?SGWID=1-102-0-0-0\" title=\"Der Wissenschaftsverlag\" >Springer<\/a> | Tel.: +49-6221-487-8531| E-Mail: renate.bayaz@springer.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Die japanische Waseda University kauft als erste Universit\u00e4t in Asien die Springer Book Archives Historisches Bucharchiv von Springer steht jetzt Studenten, Dozenten und Wissenschaftlern zur Verf\u00fcgung Wie Springer heute bekannt gab, hat die Universit\u00e4tsbibliothek der Waseda University in Tokio, Japan, die englischsprachigen Titel der Springer Book Archives (SBA) gekauft. Die Nutzer dieser Bibliothek haben dadurch<\/p>\n","protected":false},"author":3,"featured_media":60503,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[361],"tags":[],"class_list":["post-60502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-verlagsnachrichten"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=60502"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60502\/revisions"}],"predecessor-version":[{"id":168537,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60502\/revisions\/168537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/60503"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=60502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=60502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=60502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}