{"id":60837,"date":"2013-04-12T13:53:35","date_gmt":"2013-04-12T12:53:35","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=60837"},"modified":"2014-09-13T07:15:18","modified_gmt":"2014-09-13T06:15:18","slug":"das-glueck-der-fortunarier","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/das-glueck-der-fortunarier-1060837\/","title":{"rendered":"Das Gl\u00fcck der Fortunarier"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"margin: 0px 10px 10px 0px;\" title=\"Einmal Fortunarien bitte von Barbara Lexa\" alt=\"Bild\" src=\"http:\/\/pm.connektar.de\/kultur-kunst\/fortunarien-ein-glueckliches-land-mit-vorbildcharakter-9131\/anhang\/blx-087-neu.jpg?b=200&amp;h=200\" width=\"121\" height=\"141\" \/>Die Neuerscheinung ,,Einmal Fortunarien bitte!&#8220; besticht durch eine F\u00fclle von umsetzbaren Anregungen f\u00fcr ein gl\u00fccklicheres Leben.<\/p> <p>W\u00e4hrend sich die negativen Berichte und Hiobsbotschaften in den Medien in den letzten Jahren t\u00e4glich h\u00e4ufen, steigt gleichzeitig bei vielen Menschen der Wunsch nach mehr Gl\u00fcck und Harmonie im Leben. Eine m\u00e4rchenhafte Anleitung hierzu ist nun das neu erschienene Buch von Barbara Lexa: &#8222;Einmal Fortunarien bitte!&#8220;.<br \/> Die zeitlose Erz\u00e4hlung in &#8222;Spielfilml\u00e4nge&#8220; nimmt die Leser mit auf eine Reise in das unbekannte Land Fortunarien, dessen Bewohner die Grundlagen ihres gl\u00fccklichen Landes gerne weitergeben.<\/p> <p><!--more-->So erf\u00e4hrt der Leser nicht nur, wie die Fortunarier bis ins hohe Alter gesund bleiben und welche Nahrungsmittel sie bevorzugen. Auch die Themen Finanzen, Schulsystem und Politik kommen anschaulich zur Sprache. Das B\u00fcchlein unfasst 60 Seiten und zeigt auf interessante Weise auf, wie man die fortunarischen Gedanken erfolgreich in das eigene Leben \u00fcbertragen kann. Gesundheit statt krank durch Medikamente, Essen ohne schlechtes Gewissen &#8211; und das alles ohne Geld? Einmal Fortunarien &#8211; die Fahrkarte in eine gl\u00fccklichere Zukunft. Das Buch kostet 6,50 EUR und kann direkt unter www.balexa.de bezogen werden.<\/p> <p>Die Autorin und Musikerin Barbara Lexa bekam f\u00fcr ihre Lieder schon mehrfach Kleinkunstpreise. Sie befasst sich schon seit ihrer Jugend mit spirituellen Themen, die sie unter anderem auch in ihrem Dialekt-Buch &#8222;M\u00e4rchen auf Boarisch 2&#8220; einflie\u00dfen lie\u00df. 2009 gr\u00fcndete sie den Barbara Lexa Verlag, um die eigenen B\u00fccher und CDs selbst zu vertreiben.<img decoding=\"async\" alt=\"\" src=\"http:\/\/connekt.connektar.de\/s\/?23ab-ba-f9008\" \/><\/p> <p>\u00dcber:<\/p> <p>Barbara Lexa Verlag<br \/> Frau Barbara Lexa<br \/> Enzianstr. 7<br \/> 82515 Wolfratshausen<br \/> Deutschland<\/p> <p>fon ..: 08171\/20395<br \/> web ..: http:\/\/www.balexa.de<br \/> email : post@barbara-lexa.de<\/p> <p><span style=\"font-style: italic;\">Ob M\u00e4rchen und Bibel auf Boarisch oder m\u00e4rchenhafte Tontr\u00e4ger &#8211; im BaLeXa Verlag erhalten Sie hochwertige Bavarica und spirituelle Belletristik aus Wolfratshausen.<\/span><\/p> <p>Pressekontakt:<\/p> <p>Barbara Lexa Verlag<br \/> Frau Barbara Lexa<br \/> Enzianstr. 7<br \/> 82515 Wolfratshausen<\/p> <p>fon ..: 49817120395<br \/> web ..: http:\/\/www.balexa.de<br \/> email : post@barbara-lexa.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Neuerscheinung ,,Einmal Fortunarien bitte!&#8220; besticht durch eine F\u00fclle von umsetzbaren Anregungen f\u00fcr ein gl\u00fccklicheres Leben.<\/p>\n","protected":false},"author":371,"featured_media":197278,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1711],"tags":[3040,2628,3041,2625,3038,3039],"class_list":["post-60837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-burnout-therapie-psychologie","tag-friedensbotschaft","tag-lebensglueck","tag-lebenssinn","tag-lebensweisheiten","tag-seelenfrieden","tag-zeitenwandel"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/371"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=60837"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60837\/revisions"}],"predecessor-version":[{"id":172539,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/60837\/revisions\/172539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/197278"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=60837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=60837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=60837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}