{"id":609,"date":"2008-10-07T07:21:22","date_gmt":"2008-10-07T06:21:22","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/bildung-arbeitsmarkt-und-betriebsubergaben-sind-zentrale-thema-in-den-nachsten-jahren-10609\/"},"modified":"2010-11-19T20:39:14","modified_gmt":"2010-11-19T19:39:14","slug":"bildung-arbeitsmarkt-und-betriebsubergaben-sind-zentrale-thema-in-den-nachsten-jahren","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/bildung-arbeitsmarkt-und-betriebsubergaben-sind-zentrale-thema-in-den-nachsten-jahren-10609\/","title":{"rendered":"Bildung, Arbeitsmarkt und Betriebs\u00fcbergaben sind zentrale Thema in den n\u00e4chsten Jahren!"},"content":{"rendered":"<p>Noch nie wurde \u00fcber Bildung, Arbeitsmarkt und Generationswechsel in Betrieben so viel diskutiert. Fachkr\u00e4ftemangel in Handwerk und der Industrie, Probleme bei Betriebs\u00fcbergaben aus der Gr\u00fcnderzeit &#8211; Generationswechsel &#8211; oder die Frage nach der richtige Fort- und Weiterbildung. <!--more--><\/p> <p>Die Firma www.meisterscout.de widmet sich seit August 2008 voll und ganz diesen Aufgaben.<\/p> <p>Aus- und Weiterbildungen, Meister- und Gesellenjobs sowie Betriebs\u00fcbergaben an Unternehmer und Existenzgr\u00fcndern im Handwerk und der Industrie findet man jetzt hier:<\/p> <p>www.azubib\u00f6rse24.de<\/p> <p>www.gesellenjobs.de<\/p> <p>www.meisterschulen.de<\/p> <p>www.meisterjobs24.de<\/p> <p>www.betriebs\u00fcbernahmen24.de<\/p> <p>www.meisterschulen.de ist das marktf\u00fchrende Portal zum Suchen und Finden von Meisterschulen \/ Meisterkursen und jeglicher Art von Fort- und Weiterbildungsma\u00dfnahmen in Industrie und Handwerk. Laut Zentralverband des Deutschen Handwerks (ZDH), den Handwerkskammern und Meisterschulen.de finden mehr als 80 Prozent aller Meistersch\u00fcler ihre Meisterkurse \u00fcber das Internet.<\/p> <p>Damit ist die Plattform der neu gegr\u00fcndeten Meisterscout GbR der absolute Marktf\u00fchrer in diesem Bereich. Nach Abschluss der Schule machen sich \u00fcber 60 Prozent der Meister innerhalb der ersten drei Monate selbstst\u00e4ndig. Daraus entstand die Plattform:<\/p> <p>www.betriebs\u00fcbernahmen24.de . Seit Ende Mai 2008 k\u00f6nnen Existenzgr\u00fcnder, Unternehmer und Jungmeister hier Betriebe kaufen, verkaufen, pachten, mieten oder Franchisesysteme finden. Seit dem Start nutzten diese Plattform bereits \u00fcber 25.000 Besucher. Mehr als 300 Betriebsangebote und Gesuche befinden sich aktuell in dieser Datenbank &#8211; im September konnten wir die Besucherzahl auf \u00fcber 10.000 steigern. Dies bedeutet, dass wir seit unserem ersten vollen Startmonat im Juni (2500 Besucher) die Nutzerzahlen vervierfachen konnten.<\/p> <p>www.meisterjobs24.de l\u00f6st nach der erfolgreichen Aus-\/ Fort- und Weiterbildungen die Frage nach dem geeigneten Arbeitgeber. Umgekehrt suchen Arbeitgeber aus Handwerk und Industrie h\u00e4nderingend nach qualifizierten Mitarbeitern. Auf www.meisterjobs24.de finden Meister Stellenangebote zu ihren Berufen oder k\u00f6nnen aktiv einen neuen Job suchen. Der Arbeitgeber kann ab 25,&#8211; \u20ac im Monat sein Stellenangebot einstellen und selbst verwalten, Arbeitsuchende ab 9,90 im Monat. Seit dem Start dieser B\u00f6rse Ende Juli besuchten bereits \u00fcber 15.000 Interessenten diesen Marktplatz und aktuell sind \u00fcber 100 Meisterjobs gelistet.<\/p> <p>Seit Anfang August 2008 sind nun auch die B\u00f6rsen www.azubib\u00f6rse24.de und www.gesellenjobs.de online.<\/p> <p>\u201eDie Idee einen Azubi zum Gesellenjob dann zur Meisterschule und am Ende zum Meisterjob oder zum eigenen Unternehmen zu begleiten, stand immer im Mittelpunkt&#8220; so Kai Einfeldt, Gesellschafter Meisterscout &#8211; Nach dem Firmenmotto: \u201eKeep it fast and simple&#8220;<\/p> <p>Unsere B\u00f6rsen sind miteinander verkn\u00fcpft, so dass beispielsweise bei einer Jobsuche nach Augenoptikermeister auch auf unsere Betriebsb\u00f6rse verwiesen wird wenn dort Betriebsangebote f\u00fcr Augenoptiker vorhanden sind und umgekehrt. Der Nutzer wird mit nur einem Klick (neues Fenster wird ge\u00f6ffnet) direkt in den Bereich Augenoptikerbetrieb zum kaufen verlinkt. Ebenso von der Betriebsb\u00f6rse in die Jobb\u00f6rse.<\/p> <p>\u201eWir sind die Ersten, die mit \u00fcber 80 Prozent der k\u00fcnftigen Jungmeister Kontakt haben. Mit den neuen Portalen unterst\u00fctzen wir die k\u00fcnftigen Unternehmer und Entscheider mit unseren einfachen Funktionen und unserer Angebotsf\u00fclle auf ihrem weiteren beruflichen Weg. Wir machen Stellen- und Betriebsanzeigen f\u00fcr den Mittelstand einfach und bezahlbar&#8220;, so Thomas Ewald, Mitgr\u00fcnder von Meisterscout.<\/p> <p>Azubis, Sch\u00fcler und Meistersch\u00fcler erhalten Stellengesuche in unseren B\u00f6rsen f\u00fcr einen gewissen Zeitraum kostenfrei. Die Laufzeiten sind jeweils an das Ausbildungsende oder an max. 3 Monate gebunden. Unsere Preispolitik ist sehr moderat aber auch strategisch wichtig.<\/p> <p>Portale, die kein Geld f\u00fcr Anzeigen und Stellenangebote verlangen, haben in k\u00fcrzester Zeit veraltete Daten und dies m\u00f6chten wir unbedingt vermeiden.<br \/> Thomas Ewald, Kai Einfeldt<\/p> <p>Gesellschafter \/ Gr\u00fcnder<\/p> <p>Meisterscout<\/p> <p>M\u00f6wenweg 1<\/p> <p>82279 Eching am Ammersee<\/p> <p>Tel.: 08143\/99739-12<\/p> <p>Fax: 08143\/99739-20<\/p>","protected":false},"excerpt":{"rendered":"<p>Noch nie wurde \u00fcber Bildung, Arbeitsmarkt und Generationswechsel in Betrieben so viel diskutiert. Fachkr\u00e4ftemangel in Handwerk und der Industrie, Probleme bei Betriebs\u00fcbergaben aus der Gr\u00fcnderzeit &#8211; Generationswechsel &#8211; oder die Frage nach der richtige Fort- und Weiterbildung.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-609","post","type-post","status-publish","format-standard","hentry","category-arbeit-erziehung-bildung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=609"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/609\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}