{"id":6095,"date":"2010-06-02T14:50:56","date_gmt":"2010-06-02T13:50:56","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=6095"},"modified":"2026-01-30T11:49:50","modified_gmt":"2026-01-30T10:49:50","slug":"assistenzaerzte-eine-gefahr","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/assistenzaerzte-eine-gefahr-106095\/","title":{"rendered":"Frisch gebackene Assistenz\u00e4rzte: eine Gefahr f\u00fcr Leib und Leben?"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>T\u00f6dliche Medikationsirrt\u00fcmer durch unerfahrenes Klinikpersonal<\/p> <p>New York \/ Heidelberg, XX. Mai 2010<\/p> <p>Sind frisch ausgebildete Assistenz\u00e4rzte eine Gefahr f\u00fcr die Patienten? Dr. David Phillips und Gwendolyn Barker von der University of California, San Diego, in den Vereinigten Staaten haben im Rahmen einer Studie festgestellt, dass die Zahl t\u00f6dlicher Medikationsirrt\u00fcmer an Lehrkrankenh\u00e4usern im Juli einen H\u00f6chststand erreicht. Dies ist genau der Zeitpunkt, wenn neue Assistenz\u00e4rzte ihre Arbeit aufnehmen und verst\u00e4rkt f\u00fcr die Versorgung der Patienten verantwortlich sind. Diese Ergebnisse\u00b9 erschienen soeben in der Onlineausgabe der Springer-Zeitschrift Journal of General Internal Medicine\u00b2.<!--more-->Phillips und Barker untersuchten in ihrer Studie den Zusammenhang zwischen mangelnder Erfahrung und medizinischen Irrt\u00fcmern. Dabei haben sie sich vor allem auf die Anzahl von Medikationsirrt\u00fcmern (wie versehentliche \u00dcberdosierung eines Medikaments, versehentliche Einnahme und Fehler bei der Medikamentengabe sowie medikament\u00f6se Komplikationen bei medizinischen und chirurgischen Eingriffen) konzentriert, die speziell im Juli stark variiert, wenn Tausende von Assistenz\u00e4rzten ihre Arbeit aufnehmen.<\/p> <p>Es wurden 244.388 amerikanische Totenscheine aus den Jahren 1979 bis 2006 untersucht, auf denen t\u00f6dliche Medikationsirrt\u00fcmer als Haupttodesursache angegeben worden waren. Verglichen wurde die tats\u00e4chliche Zahl der Todesf\u00e4lle im Juli mit der in einem bestimmten Monat eines bestimmten Jahres erwarteten Zahl. Au\u00dferdem wurde \u00fcberpr\u00fcft, ob es im Juli Unterschiede gab zwischen Todesf\u00e4llen innerhalb und au\u00dferhalb von Krankenh\u00e4usern wie auch zwischen Landkreisen (Counties) mit und ohne Lehrkrankenh\u00e4user.<\/p> <p>Die Autoren stellten fest, dass t\u00f6dliche Medikationsirrt\u00fcmer an Krankenh\u00e4usern in der Tat im Juli einen H\u00f6chststand erreichten, allerdings nur in Counties mit Lehrkrankenh\u00e4usern. Dort lag die Anzahl 10 Prozent \u00fcber dem erwarteten Niveau. Bei anderen Todesursachen und Todesf\u00e4llen au\u00dferhalb von Krankenh\u00e4usern lie\u00df sich ein derartiger Zusammenhang nicht erkennen.<\/p> <p>Die Autoren schlussfolgerten: \u201eUnsere Erkenntnisse machen deutlich, welche Konsequenzen zu ziehen sind: 1) \u00dcberpr\u00fcfung wie viel Verantwortung an neue Assistenz\u00e4rzte \u00fcbertragen werden kann; 2) st\u00e4rkere Supervision; 3) in der Ausbildung mehr Gewicht auf Sicherheit in der Verabreichung von Medikamenten legen. Diese Ma\u00dfnahmen k\u00f6nnten sowohl t\u00f6dliche als auch nicht t\u00f6dliche Medikationsirrt\u00fcmer reduzieren und damit auch die erheblichen Kosten, die mit solchen Irrt\u00fcmern verkn\u00fcpft sind.\u201c<\/p> <p>Quelle<br \/> 1.\tPhillips DP &amp; Barker GEC (2010). A July spike in fatal medication errors: a possible effect of new medical residents. Journal of General Internal Medicine; DOI 10.1007\/s11606-010-1356-3<br \/> 2. \tThe Journal of Internal Medicine is the official journal of the Society of General Internal Medicine.<\/p> <p>Der vollst\u00e4ndige Artikel steht Journalisten als PDF-Dokument zur Verf\u00fcgung.<\/p> <p>Kontakt: Renate Bayaz, Springer, Tel. +49 6221 487-8414, renate.bayaz@springer.com<\/p> <p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.springer.com\/about+springer\/media\/springer+select?SGWID=1-11001-6-952522-0\"  >http:\/\/www.springer.com\/about+springer\/media\/springer+select?SGWID=1-11001-6-952522-0<\/a><\/p> <p>Springer-Verlag GmbH, Heidelberg, Zweigniederlassung  der Springer-Verlag GmbH, BerlinTiergartenstrasse  17D-69121 Heidelberg<\/p>","protected":false},"excerpt":{"rendered":"<p>T\u00f6dliche Medikationsirrt\u00fcmer durch unerfahrenes Klinikpersonal New York \/ Heidelberg, XX. Mai 2010 Sind frisch ausgebildete Assistenz\u00e4rzte eine Gefahr f\u00fcr die Patienten? Dr. David Phillips und Gwendolyn Barker von der University of California, San Diego, in den Vereinigten Staaten haben im Rahmen einer Studie festgestellt, dass die Zahl t\u00f6dlicher Medikationsirrt\u00fcmer an Lehrkrankenh\u00e4usern im Juli einen H\u00f6chststand<\/p>\n","protected":false},"author":291,"featured_media":198853,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8808],"tags":[],"class_list":["post-6095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenschaft"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/6095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=6095"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/6095\/revisions"}],"predecessor-version":[{"id":278301,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/6095\/revisions\/278301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198853"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=6095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=6095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=6095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}