{"id":62956,"date":"2013-04-24T11:36:22","date_gmt":"2013-04-24T10:36:22","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=62956"},"modified":"2020-07-09T11:45:34","modified_gmt":"2020-07-09T10:45:34","slug":"gehoer-schluessel-zu-kommunikation-und-genuss","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/gehoer-schluessel-zu-kommunikation-und-genuss-1062956\/","title":{"rendered":"Geh\u00f6r &#8211; Schl\u00fcssel zu Kommunikation und Genuss"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-62957\" title=\"M\u00f6gliche Symptome bei H\u00f6rproblemen\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/53cb0e59c47ab6bdfe50b74e20105bd5.jpg\" width=\"199\" height=\"146\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/53cb0e59c47ab6bdfe50b74e20105bd5.jpg\" \/>Die Welt ist lauter geworden. Mehr Mobilit\u00e4t und mehr Verkehr erzeugen L\u00e4rm. Auch die \u00dcbertragungstechniken f\u00fcr Musik wurden verfeinert und intensiviert. Die Ger\u00e4uschbelastungen im Stra\u00dfenverkehr, im Arbeitsleben und in der Freizeit bedeuten gro\u00dfe Gefahren f\u00fcr Geh\u00f6r, Gesundheit und Wohlbefinden. Die F\u00f6rdergemeinschaft Gutes H\u00f6ren setzt auf Information und Pr\u00e4vention mit deutschlandweit rund 1.500 H\u00f6rakustik-Fachbetrieben.<\/p> <p>Die L\u00e4rmbelastung ist ma\u00dfgeblich daf\u00fcr verantwortlich, dass H\u00f6rprobleme weltweit zunehmend verbreitet sind. Allein in Deutschland gibt es nach Sch\u00e4tzungen rund 15 Millionen Betroffene. <!--more-->Ursache von H\u00f6rverlust sind meist Sch\u00e4digungen der feinen Haarzellen im Innenohr. Das Risiko ist um so gr\u00f6\u00dfer, je st\u00e4rker die Belastung ausf\u00e4llt und je l\u00e4nger sie andauert. Und einmal zerst\u00f6rte Haarzellen sind unwiederbringlich verloren. Weder regenerieren sie sich, noch wachsen sie nach.<\/p> <p>Die Themen:<\/p> <p>1. L\u00e4rmquellen erkennen, Belastung reduzieren, H\u00f6rtest machen<br \/> Die F\u00f6rdergemeinschaft Gutes H\u00f6ren setzt auf Information und Pr\u00e4vention mit deutschlandweit rund 1.500 H\u00f6rakustik-Fachbetrieben.<br \/> 2. Das L\u00e4rmometer &#8211; wie laut, wie sch\u00e4dlich?<br \/> Infografik zur Belastung des Geh\u00f6rs durch Ger\u00e4usche und L\u00e4rm<br \/> 3. In Deutschland unterwegs: die gro\u00dfe FGH H\u00f6rtour 2013<br \/> Die H\u00f6rbotschafter der F\u00f6rdergemeinschaft Gutes H\u00f6ren starten im Mai mit drei H\u00f6rmobilen zur deutschlandweiten Vorsorgeaktion f\u00fcr mehr H\u00f6rgesundheit.<br \/> 4. Die Sprache im Fokus &#8211; wie wir h\u00f6ren<br \/> Hintergrundinfos: Das menschliche Geh\u00f6r hat sich auf das Sprachverstehen spezialisiert.<br \/> 5. H\u00e4ufig untersch\u00e4tzt: der Umgebungsl\u00e4rm an Bu?roarbeitspl\u00e4tzen<br \/> Auch \u201eleiser\u201c L\u00e4rm kann Geh\u00f6r und Gesundheit sch\u00e4digen.<br \/> 6. Finden Sie Ihren pers\u00f6nlichen H\u00f6rexperten vor Ort<br \/> Die Partnerakustiker der F\u00f6rdergemeinschaft Gutes H\u00f6ren bieten bundesweit faire und umfassende Beratung in h\u00f6chster Qualit\u00e4t bei allen Fragen rund um gutes H\u00f6ren.<\/p> <p>1. L\u00e4rmquellen erkennen, Belastung reduzieren, H\u00f6rtest machen<\/p> <p>Ohne regelm\u00e4\u00dfige H\u00f6rtests kann dies f\u00fcr lange Zeit unentdeckt bleiben, denn H\u00f6rverlust stellt sich meist schleichend ein. Die Betroffenen gew\u00f6hnen sich unmerklich an das immer schlechtere H\u00f6ren. Viele unternehmen erst etwas, wenn sie aufgrund ihrer H\u00f6rprobleme unter signifikanten Verst\u00e4ndigungsschwierigkeiten und Missverst\u00e4ndnissen leiden. Doch dann ist bereits wertvolle Zeit verstrichen. Das gute H\u00f6ren wurde regelrecht verlernt, da sich die neuronalen Vernetzungen im Gehirn nach und nach zur\u00fcckgebildet haben. Rechtzeitige Vorsorge im Sinne von L\u00e4rmpr\u00e4vention und H\u00f6rgesundheit ist daher unumg\u00e4nglich.<\/p> <p>Vor diesem Hintergrund setzen die F\u00f6rdergemeinschaft Gutes H\u00f6ren und ihre Partnerakustiker verst\u00e4rkt auf systematische H\u00f6rpr\u00e4vention. Dazu z\u00e4hlen die gezielte Aufkl\u00e4rung \u00fcber die Wichtigkeit des H\u00f6rens und die Gefahren des H\u00f6rverlusts sowie die Durchf\u00fchrung von regelm\u00e4\u00dfigen H\u00f6rtests ab ca. 40 Jahren, die ein wesentlicher kostenloser Beitrag zur gesundheitlichen Vorsorge sind.<br \/> Die H\u00f6rakustiker der F\u00f6rdergemeinschaft Gutes H\u00f6ren stehen f\u00fcr eine gro\u00dfe Auswahl von H\u00f6rl\u00f6sungen, faire und umfassende Beratung und h\u00f6chste Qualit\u00e4t. Sie sind am gemeinsamen FGH Zeichen, dem Ohr-Symbol mit dem Punkt zu erkennen. Einen FGH Partner in der N\u00e4he findet man im Internet unter www.fgh-info.de oder unter der kostenlosen Hotline 0800-360 9 360.<\/p> <p>2. Das L\u00e4rmometer &#8211; wie laut, wie sch\u00e4dlich?<\/p> <p>Das Geh\u00f6r ist st\u00e4ndig Gefahren durch Ger\u00e4usche und L\u00e4rm ausgesetzt. Vielfach werden H\u00f6rsch\u00e4den nicht sofort erkannt. Deshalb setzt die F\u00f6rdergemeinschaft Gutes H\u00f6ren auf systematische H\u00f6rpr\u00e4vention. Dazu z\u00e4hlen gezielte Aufkl\u00e4rungsarbeit und kostenlose H\u00f6rtests. Einen FGH Partner in der N\u00e4he findet man im Internet unter www.fgh-info.de<\/p> <p>3. In Deutschland unterwegs: die gro\u00dfe FGH H\u00f6rtour 2013<\/p> <p>Das kommt an: Informationen und H\u00f6rchecks auf der Stra\u00dfe und im Vorbeigehen &#8211; die H\u00f6rmobile der F\u00f6rdergemeinschaft Gutes H\u00f6ren starten offiziell am 14. Mai 2013, dem Tag des H\u00f6rens, zur gro\u00dfen Tour durch ganz Deutschland. Bis September werden sie dann bei den FGH Partnern vor Ort Station machen.<\/p> <p>Immer mehr Menschen interessieren sich f\u00fcr ihre H\u00f6rgesundheit und nehmen die attraktiven Angebote der F\u00f6rdergemeinschaft Gutes H\u00f6ren und ihrer Partnerakustiker wahr. Die H\u00f6rtour des letzten Jahres hat dabei eindrucksvoll gezeigt: H\u00f6rminderungen sind weiter verbreitet als vielfach angenommen.<\/p> <p>Bei 14% der Jugendlichen unter 20 Jahren wurden bereits leichte bis mittlere H\u00f6rminderungen festgestellt. Von den Erwachsenen von 21 bis 40 Jahren h\u00f6ren 28% nicht mehr einwandfrei. Die Tendenz ist mit zunehmendem Lebensalter weiter steigend: In der Altersgruppe der 41 &#8211; 60j\u00e4hrigen nimmt der Anteil der H\u00f6rminderungen signifikant auf 59% zu. Mit \u00fcber 60 Jahren sind 83% von Einschr\u00e4nkungen des Geh\u00f6rs betroffen.<\/p> <p>4. Die Sprache im Fokus &#8211; wie wir h\u00f6ren<\/p> <p>Das Geh\u00f6r ist der Schl\u00fcssel zu Kommunikation und zu H\u00f6rgenuss. Die F\u00e4higkeit zu kommunizieren, zu sprechen und zuzuh\u00f6ren, pr\u00e4gen das Zusammenleben der Menschen im Gro\u00dfen wie im Kleinen. Die st\u00e4ndige Gegenwart von Musik in der heutigen Welt ist ein eindeutiger Beweis f\u00fcr die Lust am H\u00f6ren &#8211; gleichzeitig liegen darin allerdings auch erhebliche Gefahren fu?r das Geh\u00f6r.<\/p> <p>Fu?r das menschliche Ohr muss der Schall eine bestimmte Intensit\u00e4t erreichen, um u?berhaupt geh\u00f6rt zu werden. Diesen Punkt nennt man H\u00f6rschwelle. Sie wird bestimmt von der Tonh\u00f6he (Frequenz, gemessen in Hertz) und der Lautst\u00e4rke bzw. dem Schalldruck (Dezibel). Ein gesundes Ohr nimmt Frequenzen zwischen 20 und 20.000 Hertz wahr.<\/p> <p>Entsprechend dem Tonh\u00f6henumfang der menschlichen Sprache ist es zwischen 500 und 5.000 Hertz am empfindlichsten. Bei 2000 Hertz liegt die H\u00f6rschwelle um 0 Dezibel, bei 3000-4000 Hertz sogar bei -5 Dezibel. Au\u00dferhalb des Sprachbereichs sind gr\u00f6\u00dfere Lautst\u00e4rken fu?r die Wahrnehmung n\u00f6tig. Die Schmerzgrenze liegt bei 120 Dezibel. Schallschutz ist nach der L\u00e4rm- und Vibrations- Arbeitsschutz-Verordnung, kurz \u201eL\u00e4rmVibrationsArbSchV\u201c, bereits bei 80 Dezibel vorgeschrieben.<\/p> <p>5. H\u00e4ufig untersch\u00e4tzt: der Umgebungsl\u00e4rm an Bu?roarbeitspl\u00e4tzen<\/p> <p>Heute werden L\u00e4rm- und Schallschutz durch die L\u00e4rm- und Vibrations-Arbeitsschutz-Verordnung, kurz \u201eL\u00e4rmVibrationsArbSchV\u201c geregelt. L\u00e4rm-entwicklungen von \u00fcber 80 Dezibel, so der gesetzliche Grenzwert, entstehen vielfach im Baugewerbe oder an industriellen Arbeitspl\u00e4tzen, wo der Schallschutz zur Pr\u00e4vention gesetzlich geregelt ist. Denn an vorderster Stelle der statistisch erfassten Berufskrankheiten steht immer noch die berufsbedingte Schwerh\u00f6rigkeit.<\/p> <p>Nicht zu untersch\u00e4tzen sind dagegen auch die unauff\u00e4lligen Dauerbelastungen. Hier ist der L\u00e4rmpegel im B\u00fcro zu nennen, der unter bestimmten Bedingungen sogar an den gesetzlichen Grenzwert heranreichen kann. W\u00e4hrend PCs, Drucker, Faxger\u00e4te oder Kopierer der neueren Generationen immer leiser werden, entstehen vor allem in gr\u00f6\u00dferen B\u00fcroeinheiten durch Stimmengewirr, Telefonklingeln und umherlaufende Kollegen nervt\u00f6tende Ger\u00e4uschkulissen, die auf die Dauer zu Stress f\u00fchren und das Geh\u00f6r sch\u00e4digen k\u00f6nnen.<\/p> <p>Die H\u00f6rexperten der F\u00f6rdergemeinschaft Gutes H\u00f6ren verweisen darauf, dass Verst\u00e4ndigungsschwierigkeiten bei der B\u00fcroarbeit erste Anzeichen f\u00fcr H\u00f6rminderungen sein k\u00f6nnen. Das Problem ist vielen Menschen bekannt: Bei hohem Ger\u00e4uschpegel oder bei gleichzeitigen Gespr\u00e4chen mehrerer Personen wird es immer schwieriger, den Gespr\u00e4chspartner zu verstehen. Auch h\u00e4ufigeres \u00dcberh\u00f6ren des Telefons oder Schwierigkeiten, gr\u00f6\u00dferen Besprechungen zu folgen, sollten ein Anlass f\u00fcr die \u00dcberpr\u00fcfung des Geh\u00f6rs sein.<\/p> <p>Da sich H\u00f6rminderungen in den meisten F\u00e4llen schleichend einstellen, sind sie vielen Betroffenen zun\u00e4chst gar nicht bewusst. Der H\u00f6rcheck schafft dann nicht nur Klarheit, sondern ist auch Ausgangspunkt f\u00fcr Abhilfe. Gerade bei leichten bis mittleren H\u00f6rminderungen leisten moderne H\u00f6rsysteme Hervorragendes und gleichen die Defizite nahezu vollst\u00e4ndig aus. Zus\u00e4tzliche Vorteile f\u00fcr Berufst\u00e4tige: Stressfaktoren und Fehlerquellen durch falsches Verstehen spielen keine Rolle mehr. Und die Konzentration liegt wieder ganz auf dem ungetr\u00fcbten Arbeitsalltag und dem beruflichen Fortkommen.<\/p> <p>6. Finden Sie Ihren pers\u00f6nlichen H\u00f6rexperten vor Ort<\/p> <p>Die F\u00f6rdergemeinschaft Gutes H\u00f6ren (FGH) betreibt bundesweit Aufkl\u00e4rungsarbeit \u00fcber gutes H\u00f6ren und organisiert in Kooperation mit ihren Partnerakustikern zahlreiche Informations- und H\u00f6rtest-Aktionen \u00fcberall in Deutschland. Die FGH versteht sich als Ratgeber f\u00fcr Menschen mit H\u00f6rminderungen und deren Angeh\u00f6rige sowie f\u00fcr alle Menschen, die an gutem H\u00f6ren interessiert sind.<\/p> <p>Partner in der F\u00f6rdergemeinschaft Gutes H\u00f6ren sind deutschlandweit rund 1.500 Meisterbetriebe f\u00fcr H\u00f6rakustik. Sie bieten umfassende Beratungs- und Serviceleistungen rund um das Thema H\u00f6ren an &#8211; vom kostenlosen H\u00f6rtest \u00fcber die Auswahl und Anpassung individuell geeigneter H\u00f6rtechnologie bis hin zu H\u00f6rpr\u00e4vention, H\u00f6rtraining und Nachsorge. H\u00f6rexperten in der N\u00e4he sind zu finden unter www.fgh-info.de oder unter der kostenlosen Rufnummer 0800 360 9 360 (montags &#8211; freitags von 9 &#8211; 18h).<\/p> <p>Am 14. Mai 2013 starten die H\u00f6rmobile der F\u00f6rdergemeinschaft Gutes H\u00f6ren wieder zur deutschlandweiten H\u00f6rtour, um in Fu\u00dfg\u00e4ngerzonen und auf belebten Pl\u00e4tzen wertvolle Informationen rund um das H\u00f6ren und kostenlose H\u00f6rtests anzubieten. Bereits vor dem offiziellen Start gibt es H\u00f6rmobiltermine. Weitere Informationen und Termine>><\/p> <p>Verwendung und Nachdruck der Texte honorarfrei mit Quellennachweis: &#8222;FGH&#8220;<\/p> <p>&nbsp;<\/p> <p>Firmenkontakt<br \/> F\u00f6rdergemeinschaft Gutes H\u00f6ren<br \/> Karsten Mohr<br \/> K\u00f6nigstra\u00dfe 52<\/p> <p>30175 Hannover<br \/> &#8211;<\/p> <p>E-Mail: presse@fgh-info.de<br \/> Homepage: http:\/\/www.fgh-info.de<br \/> Telefon: 0511 76333666<\/p> <p>Pressekontakt<br \/> F\u00f6rdergemeinschaft Gutes H\u00f6ren<br \/> Karsten Mohr<br \/> K\u00f6nigstra\u00dfe 52<\/p> <p>30175 Hannover<br \/> &#8211;<\/p> <p>E-Mail: presse@fgh-info.de<br \/> Homepage: http:\/\/<br \/> Telefon: 0511 76333666<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Welt ist lauter geworden. Mehr Mobilit\u00e4t und mehr Verkehr erzeugen L\u00e4rm. Auch die \u00dcbertragungstechniken f\u00fcr Musik wurden verfeinert und intensiviert. Die Ger\u00e4uschbelastungen im Stra\u00dfenverkehr, im Arbeitsleben und in der Freizeit bedeuten gro\u00dfe Gefahren f\u00fcr Geh\u00f6r, Gesundheit und Wohlbefinden. Die F\u00f6rdergemeinschaft Gutes H\u00f6ren setzt auf Information und Pr\u00e4vention mit deutschlandweit rund 1.500 H\u00f6rakustik-Fachbetrieben. Die L\u00e4rmbelastung<\/p>\n","protected":false},"author":3,"featured_media":62957,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-62956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medizin-gesundheit-pflege-soziales"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/62956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=62956"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/62956\/revisions"}],"predecessor-version":[{"id":271736,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/62956\/revisions\/271736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/62957"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=62956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=62956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=62956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}