{"id":63344,"date":"2013-04-26T11:52:01","date_gmt":"2013-04-26T10:52:01","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=63344"},"modified":"2013-04-26T11:52:02","modified_gmt":"2013-04-26T10:52:02","slug":"schadprogramm-im-gewand-einer-bank-sicherheits-app","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/schadprogramm-im-gewand-einer-bank-sicherheits-app-1063344\/","title":{"rendered":"Schadprogramm im Gewand einer Bank-Sicherheits-App"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-63345\" title=\"G Data entdeckt angebliches Sicherheitszertifikat f\u00fcr Android-Mobilger\u00e4te\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/c610ae4e05b2a5079ac0492cd6d8c93a.png\" width=\"161\" height=\"198\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/45d978cb5b8d5cc6c57c8b0f3e1f6915.png\" \/>Cyber-Bankr\u00e4uber haben es aktuell auf Android-Mobilger\u00e4te abgesehen, um mTAN- und PIN-Nummern f\u00fcr Online-Bankkonten zu stehlen. Hierzu versuchen die Kriminellen mit Hilfe einer angeblichen Postbank-Mail die Nutzer zur Installation einer \u201eSSL Zertifikat App\u201c zu bewegen. W\u00e4hlen die Anwender den in der E-Mail enthaltenen Link \u00fcber ihr Smartphone oder Tablet an, gelangen sie auf eine Internetseite, auf der die vermeintliche SSL-Zertifikats-App und eine Installationsanleitung bereit stehen. <!--more-->Die sch\u00e4dliche Anwendung, die angeblich f\u00fcr mehr Sicherheit beim mobilen Online-Banking sorgen soll, sp\u00e4ht nach der Installation die mTAN- und PIN-Nummern aus und versendet sie an die T\u00e4ter. Kriminelle sind so in der Lage, Online-Bankgesch\u00e4fte zu manipulieren und bei \u00dcberweisungen Geldbetr\u00e4ge auf andere Konten umzuleiten. Kunden, die Ihr Android-Ger\u00e4t mit G Data MobileSecurity 2 absichern, sind vor dem Sch\u00e4dling gesch\u00fctzt.<\/p> <p>Beim Zwei-Wege-Authentifizierungsverfahren kommen u.a. auch Smartphones und Tablet-PCs zum Einsatz. Hierbei wird die Transaktionsnummer (TAN) von der Bank per SMS zum Smartphone oder Tablet gesendet. F\u00fcr die Bankr\u00e4uber 3.0. sind diese Ger\u00e4te daher ein lohnende Angriffsziele, da viele Anwender auf eine Sicherheitsl\u00f6sung f\u00fcr ihr Mobilger\u00e4t verzichten.<\/p> <p>Im aktuellen Fall geben die T\u00e4ter sich als Kundenbetreuer der Postbank aus und versenden millionenfach gef\u00e4lschte Service E-Mails mit der Aufforderung zur Installation der vermeintlichen \u201eSSL Zertifikat App\u201c. Statt einer Banking-Sicherheits-App, wird ein Schadprogramm installiert, das alle empfangenen mTANs umgehend an die Kriminellen weiterleitet.<\/p> <p>Der im E-Mail-Text enthaltene Link leitet bei einem Mobileger\u00e4t auf eine pr\u00e4parierte Webseite mit einem Postbank-Banner weiter, auf der die angebliche Sicherheits-App und eine Installationsanleitung hinterlegt sind. Wird die Webseite \u00fcber einen PC aufgerufen, erscheint nur ein Hinweis, dass die Installation des Zertifikats erfolgreich war.<\/p> <p>Nach der Installation der App verlangt die Anwendung vom Nutzer die Eingabe der Kontonummer und PIN-Nummern. Dar\u00fcber hinaus fordert das Programm eine Reihe von Berechtigungen ein, die u.a. den Zugriff auf empfangene SMS-Nachrichten erlaubt. Die T\u00e4ter sind so in der Lage, Daten zu stehlen, die f\u00fcr Online-Bankgesch\u00e4fte ben\u00f6tigt werden. Die Cyber-Bankr\u00e4uber sind so in der Lage \u00dcberweisungsvorg\u00e4nge zu manipulieren.<\/p> <p>&nbsp;<\/p> <p>Die G Data Software AG, mit Unternehmenssitz in Bochum, ist ein innovatives und schnell expandierendes Softwarehaus mit Schwerpunkt auf IT-Sicherheitsl\u00f6sungen. Als Spezialist f\u00fcr Internetsicherheit und Pionier im Be-reich Virenschutz entwickelte das 1985 in Bochum gegr\u00fcndete Unternehmen bereits vor mehr als 20 Jahren das erste Antiviren-Programm. G Data ist damit eines der \u00e4ltesten Security-Software-Unternehmen der Welt.<\/p> <p>Das Produktportfolio umfasst<\/p> <p>Sicherheitsl\u00f6sungen f\u00fcr Endkunden, den Mittelstand und f\u00fcr Gro\u00dfunter-nehmen. G Data Security-L\u00f6sungen sind weltweit in mehr als 90 L\u00e4ndern erh\u00e4ltlich.<\/p> <p>Weitere Informationen zum Unternehmen und zu G Data Security-L\u00f6sungen finden Sie unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.gdata.de\" title=\"Security-Technologien\" >www.gdata.de<\/a>.<\/p> <p>&nbsp;<\/p> <p>Firmenkontakt<br \/> G Data Software AG<br \/> Kathrin Beckert<br \/> K\u00f6nigsallee b 178<\/p> <p>44799 Bochum<br \/> &#8211;<\/p> <p>E-Mail: Kathrin.Beckert@gdata.de<br \/> Homepage: http:\/\/www.gdata.de<br \/> Telefon: +49 (0) 234 \/ 9762-376<\/p> <p>Pressekontakt<br \/> G Data Software AG<br \/> Kathrin Beckert<br \/> K\u00f6nigsallee b 178<\/p> <p>44799 Bochum<br \/> &#8211;<\/p> <p>E-Mail: Kathrin.Beckert@gdata.de<br \/> Homepage: http:\/\/<br \/> Telefon: +49 (0) 234 \/ 9762-376<\/p>","protected":false},"excerpt":{"rendered":"<p>Cyber-Bankr\u00e4uber haben es aktuell auf Android-Mobilger\u00e4te abgesehen, um mTAN- und PIN-Nummern f\u00fcr Online-Bankkonten zu stehlen. Hierzu versuchen die Kriminellen mit Hilfe einer angeblichen Postbank-Mail die Nutzer zur Installation einer \u201eSSL Zertifikat App\u201c zu bewegen. W\u00e4hlen die Anwender den in der E-Mail enthaltenen Link \u00fcber ihr Smartphone oder Tablet an, gelangen sie auf eine Internetseite, auf<\/p>\n","protected":false},"author":3,"featured_media":63345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-63344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banken-kredit-finanzberatung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/63344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=63344"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/63344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/63345"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=63344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=63344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=63344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}