{"id":64825,"date":"2013-04-30T15:41:07","date_gmt":"2013-04-30T15:41:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=64825"},"modified":"2015-04-24T11:03:19","modified_gmt":"2015-04-24T10:03:19","slug":"das-selbstbild-des-zweiflers-ins-objektiv-gesehen-richtige-licht-ruecken","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/das-selbstbild-des-zweiflers-ins-objektiv-gesehen-richtige-licht-ruecken-1064825\/","title":{"rendered":"Das Selbstbild des Zweiflers ins objektiv gesehen richtige Licht r\u00fccken"},"content":{"rendered":"<p>Selbstzweifel &#8211; die Boykotteure des Gl\u00fccks der Deutschen<\/p> <p>Geht nicht, schaff ich nicht, klappt eh nicht. Ich bin nicht attraktiv genug, nicht wirklich liebenswert. Ausserdem bin ich nicht intelligent genug, nicht begabt genug und Durchhalteverm\u00f6gen ja da sieht es auch nicht wirklich gut aus bei mir. Ich bin kein Erfolgstyp und das Schickals meint es auch nicht gut mit mir. Die innere Stimme ist ein Miesepeter, Bedenkentr\u00e4ger, Besserwisser und ewiger Kritiker.<br \/> <!--more-->Bei einigen regt sie sich nur ab und zu, andere jedoch begleitete der Einfluss der inneren Stimme mit diktatorischer Hartn\u00e4ckigkeit, scheinbar ohne Pause zu machen. Oft nimmt sie uns sogar jeglichen Mut. Denn der innere N\u00f6rgler ist undifferenziert, entmutigend und vor allem m\u00e4kelig &#8211; aber bedauerlicherweise ist er auch ein Teil von uns.<\/p> <p>Allerdings macht es das sowohl im Privatleben wie auch im Job h\u00e4ufig das Leben unn\u00f6tig schwer. Doch mit ein bisschen Anstrengung l\u00e4sst sich ganz gut damit leben.<\/p> <p>Doch muss das wirklich sein? Muss man wirklich stets an uns selbst zweifeln?<\/p> <p>Die Folge dieser Selbstzweifel ist doch, dass man stets verunsichert sind, sich wenig oder im Schlimmsten Fall nichts zutraut, das Vertrauen in sich selbst verliert, irgendwann Angst hat vor ungewohnten oder gar neuen Situationen, sch\u00fcchtern ist und uns in Gegenwart anderer unsicher und gehemmt f\u00fchlt, Angst vor Ablehnung hat und m\u00f6glicherweise private berufliche Herausforderungen nicht mehr annimmt &#8211; aus Angst, sich zu blamieren und aus Angst vor Misserfolg.<\/p> <p>Auch Komplimente kann man nur schwer annehmen da man \u00fcberzeugt ist, dass auch andere an den eigenen F\u00e4higkeiten zweifeln.<\/p> <p>Sicher hilft es in solchen Phasen des Zweifelns an sich und seinen F\u00e4higkeiten nichts, sich einzureden, was andere k\u00f6nnen kann ich auch oder sich gewisse mantras gebetsm\u00fchlenartig vorzusagen. Wenn man nicht von innen heraus \u00fcberzeugt ist, ein wertvoller Mensch zu sein hilft es nichts, sich das dann nur einzureden.<\/p> <p>Aber was kann man wirklich tun? &#8211; Wer kann da schon helfen?<\/p> <p>Solange es sich nicht um eine psychische Erkrankung handelt ist gerade bei Selbstzweifeln psychologische Beratung (http:\/\/www.verband-psychologischer-berater.de) pr\u00e4destiniert das Selbstbild des Zweiflers ins objektiv gesehen richtige Licht zu r\u00fccken.<\/p> <p>Psychologische Beratung ist keine Heilbehandlung- und soll es auch nicht sein !<\/p> <p>Bei der psychologischen Beratung geht es vielmehr darum, Menschen zu unterst\u00fctzen und zu beraten. Es werden im Rahmen von Beratungsgespr\u00e4chen L\u00f6sungen zur Erreichung von positiven Ver\u00e4nderungen erarbeitet. Das \u00fcbergeordnete Ziel einer psychologischen Beratung ist, ganz allgemein gesagt, die Verbesserung der Lebensqualit\u00e4t.<\/p> <p>Diese professionellen psychologischen Berater versuchen, durch gezielte Gespr\u00e4che, st\u00fctzende und aktivierende Methoden und Techniken, individuelle Potentiale zu wecken und deren Wachstum zu f\u00f6rdern. Aufbauend auf einer von Empathie und Objektivit\u00e4t gepr\u00e4gten zwischenmenschlichen, pers\u00f6nlichen Beziehung verfolgen psychologische Berater in ihrer Arbeit f\u00fcr und mit Ihren Klienten Ziele wie Einsicht in die belastende Situation finden, Neuorientierung im Leben finden, Handlungsf\u00e4higkeit wieder gewinnen, Ressourcen entdecken und n\u00fctzen, St\u00f6rungen bew\u00e4ltigen, Selbstverantwortung und Beziehungsf\u00e4higkeit f\u00f6rdern.<\/p> <p>Im Rahmen dieser Beratungsgespr\u00e4che erarbeiten die Klienten zusammen mit Ihrem Berater (http:\/\/psychologische-beratung-finden.de\/) Strategien den inneren N\u00f6rgler zu bezwingen, und das loszulassen, was Sie klein macht, negative Gedankenmuster zu erkennen und umzustrukturieren bzw negative Glaubenss\u00e4tze umzukehren.<\/p> <p>Sie erarbeiten Wege, sich anzunehmen, wie sie sind und lernen ihre Talente und F\u00e4higkeiten zu entfalten. Da Selbstwertgef\u00fchl auch viel mit tun hat erarbeiten sie gemeinsam mit Ihrem psychologischen Berater Wege zu mehr Achtsamkeit, damit man sich f\u00fchlen kann und letztendlich besser f\u00fchlt.<\/p> <p>Und wenn auch Sie im Rahmen der Kampagne &#8222;Deutschland wird emotional stark!&#8220; (http:\/\/www.deutschland-wird-emotional-stark.de) eine kostenlose psychologische Beratungsstunde zum Thema &#8222;Selbstzweifel &#8211; die Saboteure des Gl\u00fccks der Deutschen&#8220; bei den psychologischen Beratern in Anspruch nehmen m\u00f6chten &#8211; wenden Sie sich bitte an den Verband psychologischer Berater unter 089-510 864 30!<\/p> <p>Sandra Neumayr, Vizepr\u00e4sidentin des Verbandes psy. Berater, Leitende Dozentin der Akademie psychologischer Berater in M\u00fcnchen, psychologische Leitung Results Institut (http:\/\/www.results-muenchen.de)<\/p> <p>Verband psychologischer Berater<br \/> Der Verband ist die erste unabh\u00e4ngige Adresse und Ansprechpartner nur f\u00fcr psychologische Berater!<br \/> Mit Engagement, Fachkompetenz und starken Partnern vertreten wir die beruflichen Interessen unserer Mitglieder in der Gesellschaft, um die hohe Verantwortung dieser Arbeit zu w\u00fcrdigen und den Ratsuchenden Schutz und Orientierungshilfe am &#8222;Psychologischen Markt&#8220; zu geben.<\/p> <p>Wir sind Ansprechpartner und Informant f\u00fcr Medien und \u00d6ffentlichkeit in allen Fragen zum T\u00e4tigkeitsbereich der psychologischen Beratung und engagieren uns f\u00fcr Wertsch\u00e4tzung und Anerkennung dieses Berufsbildes.<\/p> <p>Kontakt:<br \/> Verband psychologischer Berater<br \/> Manja Bochmann<br \/> Am Schnepfenweg 40<br \/> 80995 M\u00fcnchen<br \/> 08951086430<br \/> kontakt@vfpb.de<br \/> http:\/\/verband-psychologischer-berater.de\/<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Selbstzweifel &#8211; die Boykotteure des Gl\u00fccks der Deutschen Geht nicht, schaff ich nicht, klappt eh nicht. Ich bin nicht attraktiv genug, nicht wirklich liebenswert. Ausserdem bin ich nicht intelligent genug, nicht begabt genug und Durchhalteverm\u00f6gen ja da sieht es auch nicht wirklich gut aus bei mir. Ich bin kein Erfolgstyp und das Schickals meint es<\/p>\n","protected":false},"author":3,"featured_media":64826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1711],"tags":[1734],"class_list":["post-64825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-burnout-therapie-psychologie","tag-default"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/64825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=64825"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/64825\/revisions"}],"predecessor-version":[{"id":181840,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/64825\/revisions\/181840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/64826"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=64825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=64825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=64825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}