{"id":657,"date":"2008-10-24T11:59:32","date_gmt":"2008-10-24T10:59:32","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/merian-zeigt-zukunftsmusik-an-der-elbe-10657\/"},"modified":"2010-11-19T20:39:15","modified_gmt":"2010-11-19T19:39:15","slug":"merian-zeigt-zukunftsmusik-an-der-elbe","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/merian-zeigt-zukunftsmusik-an-der-elbe-10657\/","title":{"rendered":"MERIAN zeigt Zukunftsmusik an der Elbe"},"content":{"rendered":"<p>Neues MERIAN Hamburg erscheint am 23. Oktober 2008Hamburg (red) &#8211; Wer in Hamburg lebt, der muss nicht wegfahren, denn die ganze Welt ist ja schon da. Dies ist die zentrale Botschaft der neuen Hamburg-Ausgabe von MERIAN.<\/p> <p>Zu seinem 60-j\u00e4hrigen Bestehen erscheint eine mit 212 Seiten besonders umfangreiche Ausgabe des Reise- und Kulturmagazins. Gefeiert wird darin die \u201eWeltstadt am Wasser&#8220;:\u201eHamburgs Sch\u00f6nheit&#8220;, schreibt der bekennende Hamburger Niklas Maak, der aus beruflichen Gr\u00fcnden woanders leben muss, \u201eliegt nicht in den strahlend wei\u00dfen Villen von Harvestehude, im glitzernden Licht der Alster &#8211; Hamburgs Sch\u00f6nheit liegt in der N\u00e4he der absoluten Gegens\u00e4tze.&#8220; <!--more--><\/p> <p>Das MERIAN-Hamburg zeigt viel Neues: Die Hafencity ist nicht nur Europas gr\u00f6\u00dftes Stadterweiterungsprojekt, sondern auch ein Paradequartier der Gegenwartsarchitektur. Alle Projekte und Highlights des neuen Viertel werden in MERIAN  auf 22  Seiten gezeigt und beschrieben. Autor Gerhard Waldherr hat die ersten Bewohner der Hafencity besucht, und Joachim Mischke, Autor des Buchs \u201eHamburg Musik!&#8220;, befasst sich mit \u201eZukunftsmusik&#8220; und erz\u00e4hlt die Geschichte der Elbphilharmonie als \u201eM\u00e4rchen von der Sch\u00f6nen und der Baustelle&#8220;. \u201eDie Elbphilharmonie&#8220;, so Chefredakteur Hallaschka \u00fcber dieses St\u00fcck, \u201ewird ein weltweit g\u00fcltiges Wahrzeichen f\u00fcr Hamburg sein, so wie es das Opernhaus f\u00fcr Sydney ist.&#8220;<\/p> <p>\u201eWieder einmal habe ich bei der Arbeit an diesem Jubil\u00e4umsheft die Sch\u00f6nheit der Stadt entdecken d\u00fcrfen&#8220;, schreibt Hallaschka weiter. \u201eUnd damit meine ich nicht nur Hafencity und den Elbrand, sondern vor allem die Klassiker. Wo in Deutschland gibt es noch einmal so etwas wie das Blankeneser Treppenviertel, St. Pauli und die vielen Stadtviertel mit ganz eigenem Charakter?&#8220;<\/p> <p>Das Schanzenviertel, Winterhude, Ottensen und Eppendorf sind vier ganz besonders charakterstarke Stadtteile.  Vier Starautoren teilen in MERIAN ihr Insiderwissen \u00fcber ihr Quartier mit den Lesern: Willi Winkler schreibt \u00fcber den neuen Reichtum und die alte Anarchie im Schanzenviertel, und Petra Oelker schw\u00e4rmt von Winterhude, dem alte Arbeiterquartier in Alsterlage. Die preisgekr\u00f6nte Comic-Zeichnerin Isabel Kreitz hat die Wandlung Ottensens vom Schmuddelviertel zum Szenebezirk gezeichnet, und Evelyn Holst widmet sich dem Besserverdienerviertel Eppendorf und seinen \u201eLatte-Macchiato-Muttis&#8220;.<\/p> <p>Dazu kommen ein bis ins Detail recherchierter Serviceteil mit touristischen Tipps, ein herausnehmbarer Stadtplan, Infografiken und als Highlight eine von der MERIAN-Kartografie erarbeitete ausklappbare Karte, die Touristen wie Kenner der Hansestadt zielsicher durch die Stadt f\u00fchrt.<\/p> <p>Das neue MERIAN-Heft Hamburg erscheint in einer Auflage von 135.000 Exemplaren. Es ist<br \/> ab 23. Oktober 2008 f\u00fcr 7,95 \u20ac bundesweit und im deutschsprachigen Ausland im Buch- und Zeitschriftenhandel erh\u00e4ltlich.<br \/> ACHTUNG Redaktionen: Kostenfreie Fotos k\u00f6nnen unter redaktion@merian.de angefordert werden. Unter dieser Adresse erhalten Redaktionen auch Exemplare f\u00fcr Gewinnspiele und Rezensionen. Auf Anfrage gibt MERIAN einzelne Texte zum Nachdruck frei.<\/p> <p>Am Sonnabend, 25. Oktober 2008, 15 Uhr, ist Andreas Hallaschka, Chefredakteur MERIAN,<br \/> zu Gast in der Thalia Buchhandlung Hamburg, Europa Passage und stellt die MERIAN-Ausgabe Hamburg vor.<\/p> <p>Die n\u00e4chsten Ausgaben von MERIAN: \u201eUnsere Erde&#8220; (EVT: 04.12.08), \u201eArgentinien&#8220;<br \/> (EVT 18.12.08; AS: 27.10.08) und \u201eLinz&#8220; (EVT: 29.01.09; AS: 01.12.08).<br \/> Hamburg, 22. Oktober 2008<br \/> ________________________________________________________________________________<br \/> Pressekontakt: Mona Burmester, Presse und \u00d6ffentlichkeitsarbeit JAHRESZEITEN VERLAG, Tel. 040\/2717-2493, Fax 040\/2717-2063, E-Mail: presse@jalag.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Neues MERIAN Hamburg erscheint am 23. Oktober 2008Hamburg (red) &#8211; Wer in Hamburg lebt, der muss nicht wegfahren, denn die ganze Welt ist ja schon da. Dies ist die zentrale Botschaft der neuen Hamburg-Ausgabe von MERIAN. Zu seinem 60-j\u00e4hrigen Bestehen erscheint eine mit 212 Seiten besonders umfangreiche Ausgabe des Reise- und Kulturmagazins. Gefeiert wird darin<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-657","post","type-post","status-publish","format-standard","hentry","category-sport-und-freizeit"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=657"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/657\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}