{"id":659,"date":"2008-10-26T08:48:32","date_gmt":"2008-10-26T07:48:32","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/databasepro-kostenlos-kennenlernen-10659\/"},"modified":"2017-07-07T15:58:05","modified_gmt":"2017-07-07T14:58:05","slug":"databasepro-kostenlos-kennenlernen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/databasepro-kostenlos-kennenlernen-10659\/","title":{"rendered":"databasepro kostenlos kennenlernen"},"content":{"rendered":"<p style=\"margin-top: 25px\">News f\u00fcr Datenbankprofis &#8211; Neue Mediengesellschaft Ulm startet Fachzeitschrift f\u00fcr Datenmanagement<span class=\"fett\"> (pressebox) M\u00fcnchen, 24.10.2008<\/span> &#8211; Die erste Ausgabe der databasepro, der neuen Fachzeitschrift f\u00fcr Datenmanagement, Architekturen und Business-L\u00f6sungen, erscheint am 4. November.<br \/> Das j\u00fcngste Printobjekt der Neuen Mediengesellschaft Ulm mbH bietet zweimonatlich ein breites Themenspektrum rund um aktuelle Servertechnologien und richtet sich an Entwickler, Administratoren und Softwarearchitekten.<!--more--><br \/> Inhaltlich wird die databasepro weit \u00fcber die klassischen Entwickler- und Administrationsthemen hinausgehen. Die Redaktion um Chefredakteur Erik Franz verschreibt sich nicht einer bestimmten Plattform, sondern wird neben den Marktf\u00fchrern wie Oracle, IBM &amp; Co. auch MySQL und anderen Open-Source-Themen regelm\u00e4\u00dfig Raum geben.<\/p> <p>Schwerpunkte der Startausgabe 06\/08 sind der neue Microsoft SQL Server 2008 sowie umfangreiche Artikel zu Datensicherungskonzepten und Cloud Computing.<br \/> Methoden und Tools rund um Business Intelligence sind ebenfalls Bestandteil des redaktionellen Konzepts, das neben Anwender- und Praxisberichten ausf\u00fchrliche Produkttests, Case Studies, Tipps &amp; Tricks, Branchenschwerpunkte und Markt\u00fcbersichten bietet.<\/p> <p>Zusammen mit der Heft-DVD und dem online-Portal bildet die databasepro f\u00fcr den Leser eine umfassende Informationsplattform.<\/p> <p>Die databasepro erscheint sechs Mal im Jahr und ist im Zeitschriftenhandel und im Abonnement erh\u00e4ltlich. Ein kostenloses Probeabo gibt\u2019s unter www.databasepro.de\\probelesen.<\/p> <p>Ansprechpartner:<br \/> ELEMENT C<br \/> Christoph Hausel<br \/> Tel: 089 &#8211; 720 137 20<br \/> Email: <a href=\"mailto:c.hausel@elementc.de\">c.hausel@elementc.de<\/a><br \/> www.elementc.de<\/p> <p><span class=\"fett\">\u00dcber Neue Medien Ulm Holding GmbH:<\/span>                       Die Neue Mediengesellschaft Ulm mbH, 1983 gegr\u00fcndet, ist ein international agierendes Medienunternehmen. Das Kerngesch\u00e4ft der Neue Mediengesellschaft sind Zeitschriften aus den Bereichen Computer, Internet und Telekommunikation sowie Kundenzeitschriften.<\/p>","protected":false},"excerpt":{"rendered":"<p>News f\u00fcr Datenbankprofis &#8211; Neue Mediengesellschaft Ulm startet Fachzeitschrift f\u00fcr Datenmanagement (pressebox) M\u00fcnchen, 24.10.2008 &#8211; Die erste Ausgabe der databasepro, der neuen Fachzeitschrift f\u00fcr Datenmanagement, Architekturen und Business-L\u00f6sungen, erscheint am 4. November. Das j\u00fcngste Printobjekt der Neuen Mediengesellschaft Ulm mbH bietet zweimonatlich ein breites Themenspektrum rund um aktuelle Servertechnologien und richtet sich an Entwickler, Administratoren<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-659","post","type-post","status-publish","format-standard","hentry","category-computer-und-videospiele"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=659"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/659\/revisions"}],"predecessor-version":[{"id":269048,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/659\/revisions\/269048"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}