{"id":67718,"date":"2013-05-17T11:27:16","date_gmt":"2013-05-17T10:27:16","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=67718"},"modified":"2013-05-17T11:27:16","modified_gmt":"2013-05-17T10:27:16","slug":"unbestimmte-rechtsbegriffe-im-internetrecht","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/unbestimmte-rechtsbegriffe-im-internetrecht-1067718\/","title":{"rendered":"Unbestimmte Rechtsbegriffe im Internetrecht"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-67719\" title=\"Marcus Redig Rechtsanwalt\" alt=\"Marcus Redig Rechtsanwalt\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/05ad831af34d0245cc90ec314d745926.jpg\" width=\"108\" height=\"162\" imagescaler=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/imagescaler\/9791918cae02254a814b4b262602a94f.jpg\" \/>Wir leben in einer medialen Welt, in der die Vernetzung immer weiter voran schreitet und das Internet nicht mehr wegzudenken ist. Nicht nur junge Menschen bewegen sich mittlerweile im &#8222;World Wide Web&#8220; wie selbstverst\u00e4ndlich.<\/p> <p>Allerdings k\u00f6nnen hierbei aber auch Probleme auftreten, die im Gesch\u00e4ft um die Ecke nicht passieren. Insbesondere bei Gesch\u00e4ften \u00fcber die Plattform Ebay, wissen die Verbraucher oft nicht, welche Rechte sie eigentlich haben. Die Mehrzahl der Ebay-Verk\u00e4ufer bezeichnen sich offiziell als Privat-Verk\u00e4ufer und wollen regelm\u00e4\u00dfig die Gew\u00e4hrleistung ausschlie\u00dfen. Allerdings ist nicht selten dieser Gew\u00e4hrleistungsausschluss unwirksam.<\/p> <p><!--more-->Die Kanzlei Redig &amp; Redig mit Sitz in M\u00f6rlenbach und Mannheim bietet einerseits den Ebay-Verk\u00e4ufern Hilfestellung, wie diese als tats\u00e4chliche Privatperson die Gew\u00e4hrleistung richtig ausschlie\u00dfen k\u00f6nnen; andererseits kann die Kanzlei Redig &amp; Redig bei der rechtlichen Gestaltung eines Online- oder Ebay-Shops behilflich sein, angefangen von einer ordnungsgem\u00e4\u00df formulierten Widerrufsbelehrung, bis hin zu individuell angepassten allgemeinen Gesch\u00e4ftsbedingungen..<\/p> <p>Abmahung Fileshareing (Illegaler Musik-, Bilder- oder Filmdownload)<\/p> <p>Bei den Themen rund um das sogenannte Filesharing besitzt die Kanzlei Redig &amp; Redig eine gro\u00dfe Erfahrung in urheberrechtlichen Angelegenheiten, wenn es also um den illegalen Musik-, Bilder oder Filmdownload geht. Hierbei ist eine anwaltliche Vertretung absolut ratsam, da der &#8222;Ertappte&#8220; es dann mit der Musik- bzw. Filmindustrie und ggfs. der Staatsanwaltschaft zu tun hat.<\/p> <p>Bereits im Sommer 2008 wurde das &#8222;Gesetz zur Verbesserung der Durchsetzung von Rechten des geistigen Eigentums&#8220; verabschiedet. Diese Gesetzesnovelle enth\u00e4lt in dem neuen \u00a7 97a UrhG eine Regelung, nach der bei &#8222;einfach gelagerten F\u00e4llen&#8220; mit nur &#8222;unerheblicher Rechtsverletzung&#8220; die H\u00f6he der Abmahngeb\u00fchr 100,- EUR nicht \u00fcbersteigen darf.<\/p> <p>Allerdings enth\u00e4lt diese Regelung einige unbestimmte Rechtsbegriffe, deren Inhalt durch die Rechtsprechung in Zukunft noch genauer zu bestimmen ist. Das Risiko besteht f\u00fcr die Nutzer von Tauschb\u00f6rsen im Internet darin, dass die zu entscheidenden Gerichte die Messlatte f\u00fcr eine erhebliche Rechtsverletzung niedrig h\u00e4ngen und schon wenige bzw. einzelne Musiktitel oder Filme ausreichen, um von einer erheblichen Rechtsverletzung auszugehen. Dann w\u00fcrden bereits kleinste Vergehen nicht mehr unter das Privileg der neuen Regelung fallen.<\/p> <p>Wer also eine Abmahnung wegen einer Urheberrechtsverletzung bekommt, sollte unbedingt einen Rechtsanwalt aufsuchen. Nicht zuletzt im Hinblick auf die Neuregelungen des Urheberrechtsgesetzes ist ein gro\u00dfer Verhandlungsspielraum vorhanden. Und ein unerfahrene (Rechts-) Laie hat es regelm\u00e4\u00dfig mit den Gro\u00dfkonzernen wie Sony BMG zu tun und kann ohne anwaltliche Hilfe dabei schnell ungewollt eine Menge Lehrgeld bezahlen.<\/p> <p>Weitere Informationen zu den Themen <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/kanzlei-redig.de\/\" title=\"Rechtsanw\u00e4lte und Notar\" >Internetrecht Mannheim<\/a> oder auch Verkehrsrecht Mannheim und Erbrecht Mannheim erh\u00e4lt man auf der Internetseite kanzlei-redig.de.- Rechtsanwalt Mannheim.<\/p> <p>Firmenkontakt<br \/> Kanzlei Redig &amp; Redig<br \/> Marcus Redig<br \/> L\u00e4rchenweg 3<\/p> <p>69509 M\u00f6rlenbach<br \/> Deutschland<\/p> <p>E-Mail: moerlenbach@kanzlei-redig.de<br \/> Homepage: http:\/\/www.kanzlei-redig.de<br \/> Telefon: 06209 \/ 7158-0<\/p> <p>Pressekontakt<br \/> Kanzlei Redig &amp; Redig<br \/> Marcus Redig<br \/> L\u00e4rchenweg 3<\/p> <p>69509 M\u00f6rlenbach<br \/> Deutschland<\/p> <p>E-Mail: redig@deine-seo.de<br \/> Homepage: http:\/\/www.kanzlei-redig.de<br \/> Telefon: 06209 \/ 7158-0<\/p>","protected":false},"excerpt":{"rendered":"<p>Wir leben in einer medialen Welt, in der die Vernetzung immer weiter voran schreitet und das Internet nicht mehr wegzudenken ist. Nicht nur junge Menschen bewegen sich mittlerweile im &#8222;World Wide Web&#8220; wie selbstverst\u00e4ndlich. Allerdings k\u00f6nnen hierbei aber auch Probleme auftreten, die im Gesch\u00e4ft um die Ecke nicht passieren. Insbesondere bei Gesch\u00e4ften \u00fcber die Plattform<\/p>\n","protected":false},"author":3,"featured_media":67719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-67718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recht-wirtschaft-steuerberatung"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/67718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=67718"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/67718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/67719"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=67718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=67718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=67718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}